{"id":8475,"date":"2022-09-27T18:39:15","date_gmt":"2022-09-27T23:39:15","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=8475"},"modified":"2022-09-27T18:39:15","modified_gmt":"2022-09-27T23:39:15","slug":"tuxpan-conmemora-el-201-aniversario-de-la-consumacion-de-la-independencia","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2022\/09\/27\/tuxpan-conmemora-el-201-aniversario-de-la-consumacion-de-la-independencia\/","title":{"rendered":"Tuxpan conmemora el 201 Aniversario de la Consumaci\u00f3n de la Independencia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\"><em><strong>TUXPAN, VERACRUZ.<\/strong> <\/em><strong>Autoridades municipales<\/strong> encabezaron esta ma\u00f1ana el acto c\u00edvico con el que se <strong>conmemor\u00f3 el 201 Aniversario de la Consumaci\u00f3n de la Independencia de M\u00e9xico.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">En el evento, el director de Servicios Municipales, Miguel Mart\u00edn L\u00f3pez acudi\u00f3 en representaci\u00f3n del alcalde Jos\u00e9 Manuel Pozos Castro. Tambi\u00e9n se tuvo la presencia de las regidoras Mar\u00eda del Pilar Mart\u00ednez Matesanz y Maryanela Monroy Flores; Fabian Arg\u00fcelles, en representaci\u00f3n del regidor Luis Demetrio L\u00f3pez Mar\u00edn; el director de la Comisi\u00f3n Municipal del Deporte, Manuel Cortina Mart\u00ednez.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>En ese mismo acto se llev\u00f3 a cabo la ceremonia de abanderamiento de los atletas integrantes de la delegaci\u00f3n que representar\u00e1 a Tuxpan en los Juegos Paraestatales Veracruz 2022, pr\u00f3ximos a realizarse en Boca del R\u00edo; y la respectiva acreditaci\u00f3n de cada uno de ellos como seleccionados municipales. <\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10672 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-CONSUMACION-INDEPENDENCIA-1-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Luego del izamiento de la bandera, se enton\u00f3 el Himno Nacional y se realiz\u00f3 la presentaci\u00f3n de la escolta de adultos con discapacidad de paratletismo. <\/strong><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10674 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-CONSUMACION-INDEPENDENCIA-3-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>La joven Jade Anah\u00ed Campos Trejo, nadadora con discapacidad f\u00edsica, expuso una rese\u00f1a hist\u00f3rica referente al 201 aniversario de la Consumaci\u00f3n de la Independencia, ocurrida el 27 de septiembre de 1821; y el joven atleta Diego Ben\u00edtez Gonz\u00e1lez declam\u00f3 el juramento deportivo. <\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10673 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-CONSUMACION-INDEPENDENCIA-2-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">El director de Comude municipal destac\u00f3 que esta delegaci\u00f3n representar\u00e1 con gallard\u00eda y honor a nuestro municipio en este importante evento: \u201cVayan a Boca del R\u00edo y traigan consigo por lo que tanto han trabajado y luchado, peleen por esa medalla, muchachos\u201d<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Por su parte, Miguel Mart\u00edn L\u00f3pez se\u00f1al\u00f3 que en este d\u00eda se conmemora a hombres y mujeres que entregaron su vida para lograr una naci\u00f3n independiente y justa. <\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10675 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/09\/P-CONSUMACION-INDEPENDENCIA-4-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Cruz David Mart\u00ednez Herrera agradeci\u00f3 al Gobierno Municipal por el respaldo brindado a la preparaci\u00f3n de las personas con discapacidad que practican alg\u00fan deporte, y por el apoyo que se otorg\u00f3 para que puedan presentarse en estos juegos paraestatales; as\u00ed como al Club Caimanes al que pertenecen.\u00a0<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Tambi\u00e9n se cont\u00f3 con la presencia del Mayor de Zapadores de la 19\u00aa Zona Militar, Baltazar Cuencas S\u00e1nchez; el Capit\u00e1n de Corbeta Arturo David Lendeche Cancino, representante de la Fuerza Naval del Golfo; Anam\u00edn Gonz\u00e1lez M\u00e1rquez, en representaci\u00f3n de la Delegaci\u00f3n Regional de la SEV en Tuxpan; y directores y coordinadores de las diversas \u00e1reas del Ayuntamiento.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; TUXPAN, VERACRUZ. Autoridades municipales encabezaron esta ma\u00f1ana el acto c\u00edvico con el que se conmemor\u00f3 el 201 Aniversario de<\/p>\n","protected":false},"author":4,"featured_media":8480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[237,1443,701,1442,72,73],"class_list":["post-8475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-boca-del-rio","tag-consumacion-indenpendencia","tag-jose-manuel-pozos","tag-paratletismo","tag-tuxpan","tag-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2022\/09\/P-CONSUMACION-INDEPENDENCIA-5.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-21 22:52:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/8475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=8475"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/8475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/8480"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=8475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=8475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=8475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}