{"id":78915,"date":"2026-05-25T00:17:21","date_gmt":"2026-05-25T06:17:21","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=78915"},"modified":"2026-05-24T20:08:15","modified_gmt":"2026-05-25T02:08:15","slug":"colectivos-protestan-contra-informe-de-noboa-y-denuncian-crisis-social-en-ecuador","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/05\/25\/colectivos-protestan-contra-informe-de-noboa-y-denuncian-crisis-social-en-ecuador\/","title":{"rendered":"Colectivos protestan contra informe de Noboa y denuncian crisis social en Ecuador"},"content":{"rendered":"<p class=\"nota-justify\">Integrantes de organizaciones sociales y colectivos ciudadanos rechazaron este domingo el informe presentado por el presidente de Ecuador, Daniel Noboa, ante la Asamblea Nacional, y denunciaron el deterioro de las condiciones de vida, el aumento de la violencia y la crisis del sistema de salud p\u00fablica en el pa\u00eds sudamericano.<\/p>\n<p class=\"nota-justify\">Mientras el mandatario rend\u00eda cuentas por el primer a\u00f1o de su segundo periodo presidencial, manifestantes realizaron un plant\u00f3n en las inmediaciones de la Universidad Central del Ecuador, en Quito, donde lanzaron consignas contra el gobierno, entre ellas \u201cFuera, Noboa, fuera\u201d.<\/p>\n<p class=\"nota-justify\">Rosa Pacheco, integrante del Comit\u00e9 2 de Octubre, asegur\u00f3 en declaraciones a Prensa Latina que la poblaci\u00f3n \u201cest\u00e1 cansada de tanta violencia, de tanta inseguridad, del desempleo y de la falta de medicinas en los hospitales\u201d.<\/p>\n<p class=\"nota-justify\">\u201cDaniel Noboa es un mit\u00f3mano\u201d, afirm\u00f3 la activista al cuestionar las cifras y resultados expuestos por el mandatario durante su intervenci\u00f3n en el Parlamento.<\/p>\n<p class=\"nota-justify\">Pacheco sostuvo que la situaci\u00f3n del pa\u00eds \u201cse refleja en las calles\u201d y denunci\u00f3 el incremento del desempleo, as\u00ed como la crisis que atraviesa el sistema sanitario p\u00fablico. \u201cVemos morir amigos, familiares y ciudadanos en las puertas de los hospitales\u201d, se\u00f1al\u00f3. Tambi\u00e9n denunci\u00f3 la situaci\u00f3n de pacientes renales afectados, seg\u00fan dijo, por la falta de inversi\u00f3n estatal en salud.<\/p>\n<p class=\"nota-justify\">Durante su mensaje ante la Asamblea, Noboa defendi\u00f3 la gesti\u00f3n econ\u00f3mica y de seguridad de su administraci\u00f3n y asegur\u00f3 que su gobierno \u201crecuper\u00f3 la confianza del mundo en Ecuador\u201d, adem\u00e1s de reducir el riesgo pa\u00eds y reactivar la actividad econ\u00f3mica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes de organizaciones sociales y colectivos ciudadanos rechazaron este domingo el informe presentado por el presidente de Ecuador, Daniel Noboa,<\/p>\n","protected":false},"author":4,"featured_media":78916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-78915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/CLRO.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:16:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=78915"}],"version-history":[{"count":1,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78915\/revisions"}],"predecessor-version":[{"id":78917,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78915\/revisions\/78917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/78916"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=78915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=78915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=78915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}