{"id":78345,"date":"2026-05-13T00:06:29","date_gmt":"2026-05-13T06:06:29","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=78345"},"modified":"2026-05-12T20:45:16","modified_gmt":"2026-05-13T02:45:16","slug":"pan-y-morena-chocan-en-san-lazaro-por-juicios-politicos-contra-rocha-moya-y-maru-campos","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/05\/13\/pan-y-morena-chocan-en-san-lazaro-por-juicios-politicos-contra-rocha-moya-y-maru-campos\/","title":{"rendered":"PAN y Morena chocan en San L\u00e1zaro por juicios pol\u00edticos contra Rocha Moya y Maru Campos"},"content":{"rendered":"<p class=\"nota-justify\">La estrategia de que Morena exija realizarle juicio pol\u00edtico a la gobernadora de Chihuahua, Maru Campos, en respuesta a la demanda del PAN de hacer lo mismo con el gobernador sinaloense Rub\u00e9n Rocha Moya, \u201cno sirve y no vale la pena\u201d, consider\u00f3 el grupo parlamentario guinda en la C\u00e1mara de Diputados.<\/p>\n<p class=\"nota-justify\">Sin embargo, dicha bancada indic\u00f3 que respaldar\u00e1 la decisi\u00f3n de la dirigencia nacional morenista sobre ese tema, al tiempo que indic\u00f3 que le pedir\u00e1 a la Subcomisi\u00f3n de Examen Previo que le \u201cd\u00e9 celeridad\u201d a las 57 solicitudes de juicio pol\u00edtico que ya existen en este momento.<\/p>\n<p class=\"nota-justify\">Por su parte, la presidenta de la Mesa Directiva de la C\u00e1mara, la panista Kenia L\u00f3pez Rabad\u00e1n, defendi\u00f3 la actuaci\u00f3n de Campos Galv\u00e1n, y consider\u00f3 que los juicios pol\u00edticos deben usarse contra funcionarios acusados de delitos graves, como Rocha Moya.<\/p>\n<p class=\"nota-justify\">El coordinador de la bancada de Morena en San L\u00e1zaro, Ricardo Monreal \u00c1vila, dijo respetar la decisi\u00f3n de ambos partidos de presentar solicitudes de juicio pol\u00edtico, aunque consider\u00f3 que \u201cdeber\u00edamos ser m\u00e1s prudentes, m\u00e1s recatados\u201d, pues \u201cno conviene convertirse ni en ministerios p\u00fablicos ni en jueces. No es nuestra funci\u00f3n, no es nuestra responsabilidad\u201d.<\/p>\n<p class=\"nota-justify\">Luego de recordar que ya hay 57 peticiones en ese sentido en la Subcomisi\u00f3n de Examen Previo de la C\u00e1mara de Diputados, por la supuesta comisi\u00f3n de diversos il\u00edcitos, el legislador recalc\u00f3 en conferencia de prensa que \u201ceste peloteo de \u2018t\u00fa presentas una, yo presento otra\u2019, no sirve, no vale la pena. Por eso yo insisto en que tengamos calma\u201d, sobre todo de cara a las elecciones del pr\u00f3ximo a\u00f1o.<\/p>\n<p class=\"nota-justify\">En dichos comicios, indic\u00f3, \u201ctenemos que generar condiciones de entendimiento pol\u00edtico, racional, pac\u00edfico, y no esta estridencia de golpeteo y de odio que se desarrolla a trav\u00e9s de los medios, las redes y las conferencias de prensa\u201d.<\/p>\n<p class=\"nota-justify\">Ante la insistencia de las preguntas en ese sentido, Monreal estim\u00f3 que la presentaci\u00f3n de una demanda de juicio pol\u00edtico contra la gobernadora de Chihuahua, por parte de Morena, en respuesta a la del\u00a0<i>blanquiazul<\/i>\u00a0contra Rocha Moya, \u201cera de esperarse, porque si no hay prudencia de ninguna de las partes, pues va a ser una lucha\u201d.<\/p>\n<p class=\"nota-justify\">El ex gobernador de Zacatecas enfatiz\u00f3: \u201cno me gusta ese golpe tras golpe, porque finalmente lo \u00fanico que genera es sensibilidad, no altura de miras, no permitir que las instancias desarrollen su investigaci\u00f3n, sino se somete a lo pol\u00edtico-partidista acciones que debieran ser de una autoridad ministerial o de una autoridad jurisdiccional\u201d.<\/p>\n<p class=\"nota-justify\">Esa din\u00e1mica de intercambio de peticiones de juicio pol\u00edtico, alert\u00f3, \u201cpuede rebasarse y a M\u00e9xico no le conviene ese tipo de expresiones que pueden incluso llegar a la violencia en lugares y regiones\u201d, por lo que consider\u00f3 que \u201ctodos nos tenemos que someter a un principio clave: prudencia, sensatez y no estridencia ni provocaci\u00f3n\u201d.<\/p>\n<p class=\"nota-justify\">Pese a ello, Monreal puntualiz\u00f3 que respaldar\u00e1 la decisi\u00f3n final de la dirigencia morenista con respecto a este tema, porque los legisladores guindas \u201cno somos un grupo de sueltos ni asumimos cada uno una posici\u00f3n personal en la lucha pol\u00edtica\u201d.<\/p>\n<p class=\"nota-justify\">En ese sentido, aunque dijo ignorar los detalles de la movilizaci\u00f3n que se realizar\u00eda en Chihuahua para demandar juicio pol\u00edtico contra la gobernadora panista, subray\u00f3 que \u201csi me invitaran, salvo que tuviese trabajo, acudir\u00eda en raz\u00f3n del llamado del partido. Porque la \u00fanica manera de sacar adelante al pa\u00eds es con la unidad, la cohesi\u00f3n del movimiento, no con actitudes separatistas, individualistas o contradictorias con las decisiones que toma la direcci\u00f3n nacional\u201d.<\/p>\n<p class=\"nota-justify\">Monreal llam\u00f3 a que se le d\u00e9 el \u201ccurso normal\u201d a todas las demandas de juicio pol\u00edtico que lleguen a San L\u00e1zaro, conforme a la ley y sin \u201cprioridad ni privilegio\u201d para ninguna de ellas, y adelant\u00f3 que le pedir\u00e1 a su correligionario Hugo Eric Flores, presidente de la Subcomisi\u00f3n de Examen Previo, que le \u201cd\u00e9 celeridad\u201d el an\u00e1lisis de las 57 solicitudes que ya hay.<\/p>\n<p class=\"nota-justify\">\u201cLa idea es trabajar estos d\u00edas. Aunque tenemos receso en el Pleno, no hay receso en las comisiones y en las subcomisiones. Entonces, (Flores) puede trabajar en raz\u00f3n de los elementos jur\u00eddicos que \u00e9l tenga o que le hayan hecho llegar algunas procuradur\u00edas o la Fiscal\u00eda General de la Rep\u00fablica o las fiscal\u00edas de los estados\u201d, puntualiz\u00f3.<\/p>\n<p class=\"nota-justify\">El coordinador morenista recalc\u00f3: \u201chay que ponerle a todos fr\u00edo, calma; hay que actuar con sensatez en todos los movimientos y en todas las acciones que se tengan. No creo que lleguemos a un extremo en donde todos lamentemos de ingobernabilidad y confrontaci\u00f3n. No, yo creo que va a haber madurez pol\u00edtica para resolver los problemas por la v\u00eda del di\u00e1logo y por la v\u00eda de las instituciones, atendamos todos los problemas y nos alejemos de la confrontaci\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estrategia de que Morena exija realizarle juicio pol\u00edtico a la gobernadora de Chihuahua, Maru Campos, en respuesta a la<\/p>\n","protected":false},"author":4,"featured_media":78346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-78345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/LAVADERO.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:24:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=78345"}],"version-history":[{"count":1,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78345\/revisions"}],"predecessor-version":[{"id":78347,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78345\/revisions\/78347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/78346"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=78345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=78345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=78345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}