{"id":78253,"date":"2026-05-11T00:02:49","date_gmt":"2026-05-11T06:02:49","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=78253"},"modified":"2026-05-11T00:02:49","modified_gmt":"2026-05-11T06:02:49","slug":"la-espanola-isabel-diaz-ayuso-salio-chispada-de-mexico-como-tapon-de-sidra","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/05\/11\/la-espanola-isabel-diaz-ayuso-salio-chispada-de-mexico-como-tapon-de-sidra\/","title":{"rendered":"La espa\u00f1ola Isabel D\u00edaz Ayuso sali\u00f3 chispada de M\u00e9xico como tap\u00f3n de sidra"},"content":{"rendered":"<p><strong>-Los maestros NO pedimos reducci\u00f3n del ciclo escolar, pero somos disciplinados.<\/strong><\/p>\n<p>La derecha mexicana o panistas\u00a0 invit\u00f3 a Isabel D\u00edaz Ayuso, a visitar M\u00e9xico. La presidenta de la comunidad madrile\u00f1a ten\u00eda contemplado recorrer varios Estados del Pa\u00eds, pero tras una serie de protestas en su contra, intempestivamente tuvo que suspender su periplo y regresar a su natal Espa\u00f1a.<\/p>\n<p>La se\u00f1ora Ayuso se fue con los \u00e1nimos bastante disminuidos, ya que en todos sus eventos se registraron hechos de repudio y rechazo, a su presencia en M\u00e9xico. La idea de los dirigentes del PAN, no era otra cosa m\u00e1s que, ver si levantan en su afiliaci\u00f3n o ver si convencen a los ciudadanos rumbo a las elecciones del 2027.<\/p>\n<p>El fracaso de esta estrategia, la de ir por espa\u00f1oles, argentinos y estadounidenses, para orquestar una campa\u00f1a negra &#8211; digital en contra de la SOBERAN\u00cdA NACIONAL y del gobierno mexicano encabezada por la presidenta Claudia Sheinbaum Pardo, tuvo su primer rev\u00e9s.<\/p>\n<p>Es que no hay nada que en estos tiempos que la cibern\u00e9tica cubre todo\u00a0 permanezca oculto o en el anonimato; todo se sabe. Se supo por ejemplo que, detr\u00e1s de la guerra sucia y campa\u00f1a negra en las redes sociales en contra del gobierno mexicano, est\u00e1 Donald Trump y los republicanos y; para materializar \u00e9sta operaci\u00f3n que busca desestabilizar a los gobiernos progresistas de Latinoam\u00e9rica, en donde Estados Unidos est\u00e1 utilizando al ex presidente de Honduras, Orlando Hern\u00e1ndez, condenado por narcotr\u00e1fico, pero indultado por el presidente gringo, para dirigir \u00e9sta estrategia, tambi\u00e9n participa Javier Milei de Argentina, principal financiador de todo este entramado y por si fuera poco tambi\u00e9n est\u00e1 Benjam\u00edn Netanyahu, presidente de Israel.<\/p>\n<p>Claro, los dirigentes del PAN, Jorge Romero, Lilly T\u00e9llez, Marco Cort\u00e9s, Ricardo Anaya y del PRI, Alejandro Moreno C\u00e1rdenas, creyeron que con las acusaciones por parte de las autoridades anglosajona en contra del gobernador Rocha Moya de Sinaloa, por su probable relaci\u00f3n con el narcotr\u00e1fico, era el mejor momento de traer a los representantes de derecha a M\u00e9xico, y mira lo que son las cosas, la se\u00f1ora D\u00edaz Ayuso sufri\u00f3 un brutal rechazo y fuerte cuestionamientos por parte de toda una sociedad mexicana\u00a0 despierta y avispada. A la derecha mexicana y; en especial a la senadora del PAN, Lilly T\u00e9llez y; otros,\u00a0 vende patria, el pueblo no los baja de traidores.<\/p>\n<p>La guerra sucia y; campa\u00f1a negra de la derecha y republicanos, hasta hoy no les ha arrojado el saldo a favor que esperaban. En un programa de televisi\u00f3n (tercer grado) y en pleno debate, la polit\u00f3loga mexicana Viridiana R\u00edos, refut\u00f3 a Leo Zukerman sobre la necesidad de separar en dos a MORENA, y que, en efecto, por un lado el grupo de funcionarios p\u00fablicos que se est\u00e1n corrompiendo y que est\u00e1n siendo relacionados con actos de corrupci\u00f3n, el gobierno mexicano los debe de investigar y condenar, pero con pruebas y aqu\u00ed en M\u00e9xico y por otro lado est\u00e1n los m\u00e1s 35 millones de votos cosechados en el 2024, los 13 millones de afiliados, 40 millones que est\u00e1n dispuestos en estos momentos votar por MORENA en el 2027, m\u00e1s el 70 por ciento de respaldo a\u00a0 la presidenta Claudia Sheinbaum, finalmente son a ellos a los que se debe MORENA.<\/p>\n<p>Sin embargo, es tiempo de ser en\u00e9rgicos en los posicionamientos ante cualquier intenci\u00f3n injerencista y; en eso, la mandataria mexicana ha estado a la altura de las circunstancias. Por cierto, la Ejecutiva Federal convoc\u00f3 a todos los legisladores de la Cuarta Transformaci\u00f3n, incluyendo a sus aliados del PT y Verde, los inst\u00f3 a cerrar filas, ir a sus bases a informar de la embestida extranjera y de la actitud entreguista de los conservadores mexicanos (PAN y PRI).<\/p>\n<p>Por cierto, en Veracruz, dentro del morenismo existe un vac\u00edo de liderazgos, no hay en estos momentos alguien capaz de convocar a todos los actores a la unidad. Hay un d\u00e9ficit de legisladores con capacidad de comunicar, de incidir e influir en la militancia guinda.<\/p>\n<p>La gobernadora est\u00e1 sola en ese sentido, claro, el papel de las legisladoras del sur, es de lo m\u00e1s rescatable. Estamos a un par de meses para que inicie formalmente el proceso electoral rumbo al 2027 y si no se toman decisiones contundentes\u00a0 para reorganizar la estructura morenista, el\u00a0 triunfo en m\u00e1s de un distrito est\u00e1 en riesgo.<\/p>\n<p>LOS MAESTROS N0 PEDIMOS REDUCCI\u00d3N DEL CICLO ESCOLAR, PERO SOMOS DISCIPLINADOS.<\/p>\n<p>Trece supervisores escolares, m\u00e1s de doscientas directores de igual n\u00famero escuelas primarias federales ubicadas en municipios del sur de Veracruz desde Soconusco- Minatitl\u00e1n e Hidalgotitl\u00e1n, NO pidieron reducci\u00f3n del ciclo escolar\u00a0 2025-2026, sin embargo, son disciplinados, lo que diga la autoridad educativa.<\/p>\n<p>Ese ha sido el mensaje abierto y conciso del jefe\u00a0 del Sector\u00a0 Educativo N\u00fam. 19 de la zona Cosoleacaque, profesor Juan Rodr\u00edguez Arroyo, con quien se platic\u00f3\u00a0 en su propia oficina ubicada en la colonia 7 de mayo municipio de\u00a0 Cosoleacaque.<\/p>\n<p>Esta decisi\u00f3n nos tom\u00f3 un poco desprevenidos en virtud de que ten\u00edamos\u00a0 algunas actividades programadas hasta el mes de junio, ya que seg\u00fan el calendario escolar vigente el cierre de este\u00a0 periodo\u00a0 2025-2026, terminaba en la segunda quincena de julio, expres\u00f3 el jefe del sector, y\u00a0 abundo el mentor, vamos a tener que recalendarizar esas actividades y suspender algunas no\u00a0 nos queda de otra quien manda,\u00a0 manda.<\/p>\n<p>Aunque tambi\u00e9n pensamos y\u00a0 analizamos en virtud de que se viene el mundial de f\u00fatbol, los riesgos de seguridad que pudiera ocurrir entre la ciudadan\u00eda, los maestros y\u00a0 ni\u00f1os por eso respetamos y admiramos a nuestra presidenta de la Rep\u00fablica Claudia Shinbaum y estamos seguros de que no desautorizar\u00e1 a un secretario de educaci\u00f3n, concluye diciendo el profesor Rodr\u00edguez Arroyo.<\/p>\n<p>LA IGLESIA CAT\u00d3LICA Y GOBIERNO MUNICIPAL SE UNEN PARA CELEBRAR A \u201cSAN ISIDRO LABRADOR\u201d<\/p>\n<p>Por primera vez en la historia del municipio de Zaragoza, entidad que se localiza al sur de Veracruz de origen n\u00e1huatl la iglesia Cat\u00f3lica y el gobierno municipal su han unido para celebrar juntos la fiesta del patrono del pueblo\u00a0 \u201cSan Isidro Labrador\u201d en el municipio de Zaragoza, el cual tiene lugar el 15 de mayo;\u00a0 ya que este evento\u00a0 encierra una mezcla de fervor religioso, cultura n\u00e1huatl y tradici\u00f3n agr\u00edcola, en donde a\u00fan existe el trueque entre vecinos, el Tapalewi ayuda mutua.<\/p>\n<p>As\u00ed lo ha manifestado presb\u00edtero\u00a0 Fernando Cerero, encargado de la parroquia \u201cSan Isidro Labrador\u201d; en un evento que tuvo lugar en el auditorio de la misma iglesia ubicado en el atrio parroquial, en donde tambi\u00e9n estuvo el presidente municipal\u00a0 Miguel \u00c1ngel Grajales Mateo y ediles de su comuna.<\/p>\n<p>Las festividades incluyen; elecci\u00f3n y coronaci\u00f3n de la reina o\u00a0 la joven que gane el certamen, misas en diferentes horarios, feria, m\u00fasica de banda, danzas tradicionales, y eventos destacados como la cabalgata, cerdo encebado, palo encebado y el tianguis agroecol\u00f3gico que promueve el trueque como lo hac\u00edan los ancestros de este municipio.<\/p>\n<p>El mun\u00edcipe Grajales Mateo en la reuni\u00f3n anuncio, habr\u00e1 una gran vigilancia por elementos de la Guardia Nacional para garantiza la seguridad de los vecinos y visitantes, y explic\u00f3, cada a\u00f1o, el municipio de Zaragoza, se llena de color y fervor para celebrar la Feria en honor a San Isidro Labrador, una festividad que no solo rinde homenaje al santo patrono de los agricultores, sino que tambi\u00e9n se erige como un basti\u00f3n de la cultura y las tradiciones n\u00e1huatl que perduran en la regi\u00f3n, por eso en esta ocasi\u00f3n la festividad ser\u00e1 en grande.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-78177 size-full\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/FIRMA-EDITORIAL-PD-2.jpg\" alt=\"\" width=\"1024\" height=\"125\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/FIRMA-EDITORIAL-PD-2.jpg 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/FIRMA-EDITORIAL-PD-2-300x37.jpg 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/FIRMA-EDITORIAL-PD-2-768x94.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Los maestros NO pedimos reducci\u00f3n del ciclo escolar, pero somos disciplinados. La derecha mexicana o panistas\u00a0 invit\u00f3 a Isabel D\u00edaz Ayuso, a visitar M\u00e9xico. La presidenta de la comunidad madrile\u00f1a ten\u00eda contemplado recorrer varios Estados del Pa\u00eds, pero tras una serie de protestas en su contra, intempestivamente tuvo que suspender su periplo y regresar a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-78253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:56:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/02\/LEAD-POLITICO-ROJO.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=78253"}],"version-history":[{"count":1,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78253\/revisions"}],"predecessor-version":[{"id":78254,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/78253\/revisions\/78254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/73432"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=78253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=78253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=78253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}