{"id":77935,"date":"2026-05-06T00:03:32","date_gmt":"2026-05-06T06:03:32","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=77935"},"modified":"2026-05-05T20:19:04","modified_gmt":"2026-05-06T02:19:04","slug":"orden-transparencia-y-civilidad-pide-congreso-a-ayuntamientos","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/05\/06\/orden-transparencia-y-civilidad-pide-congreso-a-ayuntamientos\/","title":{"rendered":"Orden, transparencia y civilidad pide Congreso a ayuntamientos"},"content":{"rendered":"<p>El objetivo del Congreso del Estado al acercar a las autoridades las herramientas necesarias para el buen funcionamiento de la administraci\u00f3n p\u00fablica municipal es que prevalezcan la transparencia y la rendici\u00f3n de cuentas en beneficio de la poblaci\u00f3n, afirm\u00f3 el presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (Jucopo) de la LXVII Legislatura, diputado Esteban Bautista Hern\u00e1ndez, en el inicio de las jornadas Veracruz y la fiscalizaci\u00f3n: capacitaci\u00f3n para la gesti\u00f3n responsable 2026.<\/p>\n<p>A este encuentro, coordinado por la Secretar\u00eda de Fiscalizaci\u00f3n de esta Soberan\u00eda, en colaboraci\u00f3n con la Contralor\u00eda General del Estado (CGE) y el Tribunal de Justicia Administrativa del Estado de Veracruz (Trijaev), acudieron el presidente de la Comisi\u00f3n Permanente de Vigilancia, diputado Miguel Guillermo Pintos Guill\u00e9n; la representante del Distrito XXIV de Santiago Tuxtla, diputada Janix Liliana Castro Mu\u00f1oz; el presidente municipal de Santiago Tuxtla, No\u00e9 Dom\u00ednguez Cadena, y la presidenta del Trijaev, magistrada Leticia Aguilar Jim\u00e9nez, as\u00ed como autoridades de 36 municipios.<\/p>\n<p>Como parte de su mensaje, el legislador Esteban Bautista exhort\u00f3 a las y los mun\u00edcipes a conducirse con rectitud y apego a derecho, a enfocar los recursos donde se necesite y el pueblo lo solicite. Les dijo que \u201custedes con los contralores ir\u00e1n integrando los expedientes de cada obra y ante cualquier duda ah\u00ed estamos en el Congreso para ayudarles\u201d.<\/p>\n<p>Precis\u00f3 que el Poder Legislativo tiene como prop\u00f3sito coadyuvar con los ayuntamientos para el fortalecimiento de la transparencia, en concordancia con lo implementado por la gobernadora de Veracruz, Roc\u00edo Nahle Garc\u00eda, y les invit\u00f3 a que \u201ccomo iniciaron su administraci\u00f3n, as\u00ed avancen hasta culminar\u201d.<\/p>\n<p>Tras compartir su experiencia al frente de la administraci\u00f3n municipal de Tatahuicapan de Ju\u00e1rez, el diputado Bautista Hern\u00e1ndez destac\u00f3 la unidad como herramienta fundamental para lograr el progreso social. \u201cCuando inicia el gobierno municipal, inicia la responsabilidad de trabajar para todas y con todos. Hay que gobernar de la mano con el pueblo para generar resultados y comentarios positivos\u201d, coment\u00f3.<\/p>\n<p>Posteriormente, el diputado Miguel Guillermo Pintos Guill\u00e9n prioriz\u00f3 el cumplimiento de las responsabilidades administrativas de los ayuntamientos y recalc\u00f3 que las capacitaciones impulsadas por el Congreso del Estado tienen como finalidad ayudar a las y los servidores p\u00fablicos a realizar su labor de manera eficiente, privilegiando la transparencia y colocando a la sociedad en el centro de inter\u00e9s de la toma de decisiones.<\/p>\n<p>A su vez, la representante del Distrito XXIV de Santiago Tuxtla en el Congreso local, diputada Janix Liliana Castro Mu\u00f1oz, consider\u00f3 que una administraci\u00f3n que conoce sus obligaciones, que domina los procesos de comprobaci\u00f3n, que entiende la normatividad y aplica buenas pr\u00e1cticas genera confianza, que es \u201cel capital pol\u00edtico m\u00e1s valioso que puede tener un gobierno municipal\u201d.<\/p>\n<p>Agreg\u00f3 que en Veracruz avanzar hacia gobiernos locales m\u00e1s fuertes implica apostar por la profesionalizaci\u00f3n, reconocer que la transparencia no se improvisa, que la rendici\u00f3n de cuentas no se simula y que la buena administraci\u00f3n se construye con disciplina, conocimiento y compromiso.<\/p>\n<p>Despu\u00e9s de los mensajes de las autoridades y con la presencia de las diputadas Erika del Carmen Rosario Morales e Ingrid Jeny Calder\u00f3n Dom\u00ednguez y del diputado Urbano Bautista Mart\u00ednez, inici\u00f3 la capacitaci\u00f3n con la charla Control Interno Municipal, a cargo del titular de la Secretar\u00eda de Fiscalizaci\u00f3n, Aurelio Rivera Galindo. Acto seguido, la magistrada Leticia Aguilar Jim\u00e9nez habl\u00f3 sobre Responsabilidad del servidor p\u00fablico y sanciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo del Congreso del Estado al acercar a las autoridades las herramientas necesarias para el buen funcionamiento de la administraci\u00f3n p\u00fablica municipal es que prevalezcan la transparencia y la rendici\u00f3n de cuentas en beneficio de la poblaci\u00f3n, afirm\u00f3 el presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (Jucopo) de la LXVII Legislatura, diputado Esteban Bautista [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":77936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-77935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:03:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-05-at-19.54.41-4.jpeg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/77935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=77935"}],"version-history":[{"count":1,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/77935\/revisions"}],"predecessor-version":[{"id":77937,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/77935\/revisions\/77937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/77936"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=77935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=77935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=77935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}