{"id":76974,"date":"2026-04-15T00:16:59","date_gmt":"2026-04-15T06:16:59","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76974"},"modified":"2026-04-15T00:16:59","modified_gmt":"2026-04-15T06:16:59","slug":"comando-central-de-estados-unidos-presume-paralizar-comercio-irani-buques-cruzan-ormuz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/15\/comando-central-de-estados-unidos-presume-paralizar-comercio-irani-buques-cruzan-ormuz\/","title":{"rendered":"Comando Central de Estados Unidos presume paralizar comercio iran\u00ed; buques cruzan Ormuz"},"content":{"rendered":"<p class=\"nota-justify\">El comandante del Comando Central de las Fuerzas Armadas de Estados Unidos (Centcom), almirante Brad Cooper, afirm\u00f3 esta noche que \u00abse ha implementado por completo el bloqueo de los puertos iran\u00edes\u00bb y asegur\u00f3 que las fuerzas estadunidenses mantienen la superioridad mar\u00edtima en Medio Oriente.<\/p>\n<p class=\"nota-justify\">\u201cSe estima que 90 por ciento de la econom\u00eda de Ir\u00e1n se basa en el comercio mar\u00edtimo internacional\u201d, declar\u00f3 en X. \u201cEn menos de 36 horas desde que se implement\u00f3 el bloqueo, las fuerzas estadunidenses han paralizado por completo el comercio econ\u00f3mico que entra y sale de Ir\u00e1n por v\u00eda mar\u00edtima\u201d.<\/p>\n<p class=\"nota-justify\">Horas antes, The Wall Street Journal report\u00f3 que al menos tres buques que zarparon de puertos iran\u00edes cruzaron el estrecho de Ormuz en las \u00faltimas 24 horas a pesar del \u201cbloqueo militar estadunidense\u201d. Los buques iran\u00edes forman parte de una veintena de barcos mercantes y al menos ocho petroleros-entre ellos, el Rich Starry, un nav\u00edo chino sancionado por Washington- que cruzaron la estrat\u00e9gica v\u00eda mar\u00edtima por la cual transita 20 por ciento del petr\u00f3leo que se consume a nivel mundial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El comandante del Comando Central de las Fuerzas Armadas de Estados Unidos (Centcom), almirante Brad Cooper, afirm\u00f3 esta noche que<\/p>\n","protected":false},"author":4,"featured_media":76975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-76974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/mj.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:27:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76974"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76975"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}