{"id":76953,"date":"2026-04-15T00:09:47","date_gmt":"2026-04-15T06:09:47","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76953"},"modified":"2026-04-15T00:09:47","modified_gmt":"2026-04-15T06:09:47","slug":"profeco-inicia-colocacion-de-mantas-en-gasolinerias-con-precios-altos","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/15\/profeco-inicia-colocacion-de-mantas-en-gasolinerias-con-precios-altos\/","title":{"rendered":"Profeco inicia colocaci\u00f3n de mantas en gasoliner\u00edas con precios altos"},"content":{"rendered":"<p class=\"nota-justify\">El titular de la Procuradur\u00eda Federal del Consumidor (Profeco), C\u00e9sar Iv\u00e1n Escalante Ruiz, inici\u00f3 la colocaci\u00f3n de mantas en gasoliner\u00edas que tienen precios altos, como un d\u00eda antes lo adelant\u00f3 la presidenta Claudia Sheinbaum, como una de las acciones de su gobierno, para evitar los precios a sobre costo de los combustibles.<\/p>\n<p class=\"nota-justify\">En esta ocasi\u00f3n, la colocaci\u00f3n de una de esas mantas fue en una estaci\u00f3n de servicio en la localidad de Amecameca, en el Estado de M\u00e9xico, en la cual se lee: \u201cNo cargues aqu\u00ed. Se vuelan la barda con los precios\u201d.<\/p>\n<p class=\"nota-justify\">En la manta con fondo blanco y letras de color guinda, caracter\u00edstico de Morena, y color negro, tambi\u00e9n resalta una letra \u201cX\u201d color rojo carm\u00edn y la manta se coloc\u00f3 en la misma estructura donde se encuentra el tablero de los precios que est\u00e1n a la vista de los consumidores.<\/p>\n<p class=\"nota-justify\">La manta agrega las r\u00fabricas de la Secretar\u00edas de Econom\u00eda y de la Profeco.<\/p>\n<p class=\"nota-justify\">El funcionario subi\u00f3 el video de la colocaci\u00f3n en su cuenta de X y se\u00f1al\u00f3 que esa gasoliner\u00eda de la firma espa\u00f1ola Repsol est\u00e1 vendiendo el litro de di\u00e9sel en 31.49 pesos, cuando el acuerdo entre el gobierno federal y los gasolineros es acercarse en la mayor medida de lo posible a 28 pesos por litro.<\/p>\n<p class=\"nota-justify\">\u201cEl Estado mexicano est\u00e1 haciendo un esfuerzo inmenso por estabilizar el precio de los combustibles, en este caso del di\u00e9sel. La Secretar\u00eda de Hacienda (est\u00e1) haciendo su parte, la Secretar\u00eda de Energ\u00eda, Pemex, nosotros, como para que empresarios vendan en 31.49 pesos el litro de di\u00e9sel\u201d, reproch\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Procuradur\u00eda Federal del Consumidor (Profeco), C\u00e9sar Iv\u00e1n Escalante Ruiz, inici\u00f3 la colocaci\u00f3n de mantas en gasoliner\u00edas<\/p>\n","protected":false},"author":4,"featured_media":76954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-76953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/jasel.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 05:35:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76953"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76954"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}