{"id":76917,"date":"2026-04-14T00:17:58","date_gmt":"2026-04-14T06:17:58","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76917"},"modified":"2026-04-13T18:23:40","modified_gmt":"2026-04-14T00:23:40","slug":"chevron-firma-con-pdvsa-para-aumentar-produccion-de-petroleo-en-venezuela","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/14\/chevron-firma-con-pdvsa-para-aumentar-produccion-de-petroleo-en-venezuela\/","title":{"rendered":"Chevron firma con Pdvsa para aumentar producci\u00f3n de petr\u00f3leo en Venezuela"},"content":{"rendered":"<p class=\"nota-justify\">La estatal de hidrocarburos Petr\u00f3leos de Venezuela (Pdvsa) y la petrolera estadunidense Chevron firmaron un acuerdo de intercambio de activos entre una licencia de explotaci\u00f3n mar\u00edtima de gas por otra de explotaci\u00f3n de petr\u00f3leo pesado en la Faja del Orinoco.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">El acto se llev\u00f3 a cabo en el Palacio de Miraflores en presencia de la presidenta encargada Delcy Rodr\u00edguez y el subsecretario de hidrocarburos y energ\u00eda geot\u00e9rmica de Estados Unidos, Kyle Haustveit. Rodr\u00edguez agradeci\u00f3 a Chevron por ser ejemplo de una empresa \u201ccomprometida con Venezuela que, en los peores momentos, en las peores dificultades, no se fueron y hoy dan muestras claras de seguir avanzando\u201d.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">En concreto, Chevron devuelve una licencia de explotaci\u00f3n de gas en el campo Loran, un yacimiento mar\u00edtimo compartido con Trinidad y Tobago. En su lugar, adquiere una licencia de explotaci\u00f3n de petr\u00f3leo pesado en el campo Ayacucho 8 de la Faja del Orinoco. Con esto expande su participaci\u00f3n en la empresa mixta Petropiar, cuyos campos son contiguos. As\u00ed mismo, Chevron subir\u00e1 su participaci\u00f3n a 49% en la empresa conjunta PetroIndependencia.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">El presidente de Chevron Venezuela, Javier La Rosa, dijo que, con esto, sumando las tres empresas mixtas que manejan con Venezuela, consolidan la mayor producci\u00f3n de petr\u00f3leo del pa\u00eds.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">Dijo, adem\u00e1s, que el intercambio de activos ejecutado constituye \u201cel primer paso en esta nueva etapa\u201d y que el segundo paso \u201cvendr\u00e1 con la implementaci\u00f3n de la nueva Ley de Hidrocarburos\u201d, la cual, asegur\u00f3, acelerar\u00e1 la producci\u00f3n de petr\u00f3leo en Venezuela.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">El campo Loran fue explorado por Chevron hace algunos a\u00f1os y se confirm\u00f3 que conten\u00eda m\u00e1s de 7 billones de pies c\u00fabicos de reservas de gas; sin embargo, no se lleg\u00f3 a desarrollar. Se trata de la porci\u00f3n venezolana de un yacimiento compartido con Trinidad y Tobago llamado Loran-Manatee.<\/p>\n<p class=\"nota-justify\" lang=\"es-ES\">Seg\u00fan Reuters, se espera que el campo Loran sea adjudicado a Shell, cuya participaci\u00f3n en Venezuela durante los \u00faltimos a\u00f1os ha estado concentrada en gas y ya administra la porci\u00f3n trinitense de este yacimiento transfronterizo. Tambi\u00e9n se espera para los pr\u00f3ximos d\u00edas la visita de una delegaci\u00f3n de Trinidad y Tobago a Caracas para retomar relaciones y avanzar en los negocios conjuntos de gas, lo cual marcar\u00e1 un hito luego de a\u00f1os de tensiones entre el gobierno de Nicol\u00e1s Maduro y el de la primera ministra Kamla Persad-Bissessar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estatal de hidrocarburos Petr\u00f3leos de Venezuela (Pdvsa) y la petrolera estadunidense Chevron firmaron un acuerdo de intercambio de activos<\/p>\n","protected":false},"author":4,"featured_media":76918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-76917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/PEDE.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 01:33:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76917"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76918"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}