{"id":76816,"date":"2026-04-13T00:12:30","date_gmt":"2026-04-13T06:12:30","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76816"},"modified":"2026-04-12T23:12:11","modified_gmt":"2026-04-13T05:12:11","slug":"asi-esta-pegando-el-cierre-del-estrecho-de-ormuz-a-los-precios-del-tianguis","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/13\/asi-esta-pegando-el-cierre-del-estrecho-de-ormuz-a-los-precios-del-tianguis\/","title":{"rendered":"As\u00ed est\u00e1 pegando el cierre del estrecho de Ormuz a los precios del tianguis"},"content":{"rendered":"<p>Los productores del campo lo tienen claro: el encarecimiento de productos b\u00e1sicos como jitomate, chiles, lim\u00f3n o cebolla es resultado del alza de precios de los combustibles y la log\u00edstica, as\u00ed como de los fertilizantes \u2013tambi\u00e9n derivados del petr\u00f3leo\u2013, afirm\u00f3 la Uni\u00f3n Nacional de Trabajadores Agr\u00edcolas (UNTA).<\/p>\n<p>La l\u00f3gica es simple: si producir cuesta m\u00e1s y mover la mercanc\u00eda tambi\u00e9n, el precio final sube. El alza de los combustibles encarece el traslado de los alimentos, y el aumento de los fertilizantes eleva el costo de cultivar, lo que termina por reflejarse en el bolsillo de los consumidores.<\/p>\n<p>Esto ha pasado factura a los bolsillos y monederos de todos aquellos que al menos una vez a la semana hacen las compras en el mercado: de enero a la fecha, adquirir los productos m\u00e1s b\u00e1sicos ha aumentado a casi tres cuartas partes de un salario m\u00ednimo vigente, de acuerdo con el Laboratorio de An\u00e1lisis en Comercio, Econom\u00eda y Negocios (Lacen) de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM).<\/p>\n<p>En la calle y en casa se repite la misma frase: \u201cTodo est\u00e1 bien caro\u201d. En una verduler\u00eda de la Ciudad de M\u00e9xico, Ana pregunta a Carlos: \u201c\u00bfCu\u00e1nto es y por qu\u00e9 tan caro?\u201d El due\u00f1o del negocio de frutas, verduras y licuados hace la cuenta entre risas y agrega antes de que la marchanta suelte el billete de 200 pesos: \u201cS\u00ed, se\u00f1ora, pero el problema es que yo no gano m\u00e1s\u201d.<\/p>\n<p><strong>Los agroqu\u00edmicos se han encarecido entre 15% y 40%<\/strong><\/p>\n<p>Esta semana se dio a conocer que el alza de precios de frutas y verduras durante marzo provoc\u00f3 que la inflaci\u00f3n general en M\u00e9xico llegara a 4.59 por ciento, su nivel m\u00e1s alto desde octubre de 2024, de acuerdo con datos del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi).<\/p>\n<p>El impacto tambi\u00e9n se ve en la canasta b\u00e1sica a la que da seguimiento la Procuradur\u00eda Federal del Consumidor (Profeco), compuesta por 24 productos de consumo semanal para una familia de cuatro personas.<\/p>\n<p>En diciembre, el aumento anual en estos insumos (como cebolla, chile, jitomate, lim\u00f3n, papa, zanahoria y carnes de res y pollo) fue de 1.8 por ciento y para marzo de 6.4 por ciento, es decir, m\u00e1s del triple.<\/p>\n<p>De acuerdo con un an\u00e1lisis de BanCoppel, entre los productos con mayores alzas en marzo destacan el jitomate, con un incremento anual de 126.3 por ciento; chiles frescos, 34.1; lim\u00f3n, 32.7, y papa, 29 por ciento.<\/p>\n<p>En entrevista, Alvaro L\u00f3pez R\u00edos, l\u00edder de la UNTA, explic\u00f3 que las presiones inflacionarias a la producci\u00f3n agr\u00edcola, particularmente la de alimentos b\u00e1sicos, afectan desde las tierras de cultivo hasta la log\u00edstica. El primer gran golpe viene de los energ\u00e9ticos.<\/p>\n<p>\u201cLa producci\u00f3n del campo se ve impactada por dos factores. Las gasolinas y el di\u00e9sel subieron\u201d, lo que repercute en toda la cadena de trabajo en las parcelas, pues \u201cel di\u00e9sel es fundamental para la maquinaria agr\u00edcola\u201d.<\/p>\n<p>El aumento de costos no se detiene en los tractores. La movilidad de los agricultores tambi\u00e9n encarece el producto antes de llegar a los grandes mercados o al tianguis. \u201cSe usan camionetas para ir por insumos a la ciudad, lo que influye en el aumento de estos productos\u201d, agreg\u00f3 el dirigente.<\/p>\n<p>El segundo factor que ha disparado los costos son los agroqu\u00edmicos, cuyo suministro tambi\u00e9n han sufrido los estragos del panorama internacional. \u201cDesde el 2 de marzo, cuando empez\u00f3 el conflicto en Medio Oriente, los fertilizantes tambi\u00e9n se han ido para arriba entre 15 y 40 por ciento\u201d, explic\u00f3.<\/p>\n<p>La combinaci\u00f3n de ambos elementos, afirma el l\u00edder de la UNTA, hace matem\u00e1ticamente imposible que el precio final se mantenga estable, pues \u201cfertilizantes y combustibles al alza sin duda generan una escalada de aumentos\u201d.<\/p>\n<p>Al final de la cadena, el golpe es inevitable. La l\u00f3gica comercial y de supervivencia del sector impide que productores y vendedores absorban este choque inflacionario. \u201cNi modo que los comerciantes absorban ellos el incremento de los precios de estos dos insumos b\u00e1sicos para las actividades del campo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los productores del campo lo tienen claro: el encarecimiento de productos b\u00e1sicos como jitomate, chiles, lim\u00f3n o cebolla es resultado<\/p>\n","protected":false},"author":4,"featured_media":76817,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-76816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/asi-esta-pegando-el-cierre-del-estrecho-de-ormuz-a-los-precios-del-tianguis_38e628f5-02fd-4683-98c6-c59d76b6563a_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:54:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76816"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76817"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}