{"id":76804,"date":"2026-04-13T00:08:34","date_gmt":"2026-04-13T06:08:34","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76804"},"modified":"2026-04-12T23:06:15","modified_gmt":"2026-04-13T05:06:15","slug":"se-mantendra-el-apoyo-al-campo-sheinbaum","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/13\/se-mantendra-el-apoyo-al-campo-sheinbaum\/","title":{"rendered":"Se mantendr\u00e1 el apoyo al campo: Sheinbaum"},"content":{"rendered":"<p class=\"nota-justify\">En el 107 aniversario luctuoso de Emiliano Zapata, la presidenta Claudia Sheinbuam Pardo expres\u00f3 que su gobierno seguir\u00e1 apoyando al campo, al reconocer que hay un \u201cmomento dif\u00edcil porque el ma\u00edz est\u00e1 a muy bajo precio\u201d.<\/p>\n<p class=\"nota-justify\">Tenemos, dijo, varios programas, \u201cno solamente los Fertilizantes Gratuitos, Producci\u00f3n para el Bienestar, Sembrando Vida, sino ahora El Ma\u00edz es la Ra\u00edz para dotar de apoyo t\u00e9cnico y tambi\u00e9n maquinaria para los productores\u201d.<\/p>\n<p class=\"nota-justify\">Anunci\u00f3 que se pondr\u00e1 de acuerdo con la gobernadora Margarita Gonz\u00e1lez para construir algunas presas y recuperar los cultivos \u201cy el riego agr\u00edcola en esta zona tan importante de Morelos\u201d.<\/p>\n<p class=\"nota-justify\">En la ex hacienda de Chinameca, donde el\u00a0<i>Caudillo del Sur\u00a0<\/i>fue asesinado, la mandataria resalt\u00f3 que en la Cuarta Transformaci\u00f3n \u201cno se nos olvida por qu\u00e9 llegamos aqu\u00ed; a nosotros no nos puso en el poder ning\u00fan potentado como era antes; nos puso el pueblo de M\u00e9xico\u201d.<\/p>\n<p class=\"nota-justify\">Resalt\u00f3 que la caracter\u00edstica de estos gobiernos es que \u201cluchamos por soberan\u00eda, independencia, libertad, justicia social y democracia.<\/p>\n<p class=\"nota-justify\">\u201cY tan Zapata es nuestra visi\u00f3n, que en el gobierno del presidente (Andr\u00e9s Manuel) L\u00f3pez Obrador y en el nuestro hemos entregado m\u00e1s de 60 mil hect\u00e1reas de tierras comunales a los propietarios originarios\u201d y lo vamos a seguir haciendo, as\u00ed como apoyando al campo.<\/p>\n<p class=\"nota-justify\">Sheinbaum encabez\u00f3 ayer la entrega de carpetas b\u00e1sicas a cuatro ejidos y el reconocimiento a presidentas de comisariados ejidales y comunales en el estado por su labor y liderazgo. En la ceremonia, ley\u00f3 un texto que escribi\u00f3 sobre Emiliano Zapata, cuyo legado, afirm\u00f3, \u201csigue vivo\u201d.<\/p>\n<p class=\"nota-justify\">Agreg\u00f3 que la mejor forma de honrar a Zapata es no olvidar el origen de su lucha, combatir los privilegios, \u201cerradicar lo que a\u00fan persiste del viejo r\u00e9gimen de corrupci\u00f3n y seguir construyendo un pa\u00eds m\u00e1s justo, m\u00e1s igualitario y m\u00e1s digno para todas y todos\u201d.<\/p>\n<p class=\"nota-justify\">Honrarlo tambi\u00e9n significa, dijo, impulsar cambios que fortalezcan la vida democr\u00e1tica y pongan fin a los privilegios como las aprobadas reformas \u201cque conocemos como el\u00a0<i>plan B<\/i>\u201d.<\/p>\n<p class=\"nota-justify\">Previamente, inaugur\u00f3, acompa\u00f1ada de nietos y bisnietos del\u00a0<i>Caudillo del Sur<\/i>, el Museo Mujeres Zapatistas en ciudad Ayala, en la casa donde Zapata y Josefa Espejo contrajeron matrimonio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el 107 aniversario luctuoso de Emiliano Zapata, la presidenta Claudia Sheinbuam Pardo expres\u00f3 que su gobierno seguir\u00e1 apoyando al<\/p>\n","protected":false},"author":4,"featured_media":76805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-76804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/se-mantendra-el-apoyo-al-campo-sheinbaum_b7e7e654-1e30-4bed-9343-cb649b41165b_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:18:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76804"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76805"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}