{"id":76726,"date":"2026-04-11T00:02:29","date_gmt":"2026-04-11T06:02:29","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76726"},"modified":"2026-04-10T19:42:56","modified_gmt":"2026-04-11T01:42:56","slug":"impugnacion-del-pt-en-tamiahua-sin-sustento","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/11\/impugnacion-del-pt-en-tamiahua-sin-sustento\/","title":{"rendered":"Impugnaci\u00f3n del PT en Tamiahua, \u201csin sustento\u201d"},"content":{"rendered":"<p>El representante de Movimiento Regeneraci\u00f3n Nacional (Morena) ante los \u00f3rganos electorales, Gabriel Z\u00fa\u00f1iga Ovando, calific\u00f3 como vaga, imprecisa y sin argumentaci\u00f3n jur\u00eddica, la impugnaci\u00f3n presentada por el Partido del Trabajo (PT) tras los resultados electorales de la elecci\u00f3n extraordinaria de Tamiahua. Pues afirm\u00f3 que solamente con \u201cdichos\u201d busca revertir el triunfo de la candidata de la coalici\u00f3n de Morena-PVEM, Pilar Guzm\u00e1n Medell\u00edn, sin embargo, consider\u00f3 que no proceder\u00e1.<\/p>\n<p>\u201cEs una es una demanda que, sin duda alguna, carece de todo sustento jur\u00eddico, es una demanda que no tendr\u00eda la fuerza jur\u00eddica suficiente para derrotar la elecci\u00f3n de Tamiahua; la verdad es que es vaga, imprecisa, sin argumentaci\u00f3n jur\u00eddica, porque solamente son dichos\u201d.<\/p>\n<p>Record\u00f3 que todas y cada una de las casillas que se instalaron el d\u00eda de la jornada electoral fueron abiertas y se contabilizaron, es decir, los errores o inconsistencias que pudiesen haberse dado en las casillas, habr\u00edan sido detectados.<\/p>\n<p>Acus\u00f3 que si alguien incurri\u00f3 en alguna irregularidad fue el PT, por haber hecho un uso indebido del padr\u00f3n electoral, al presentar una copia como prueba de los supuestos delitos electorales, ya que su reproducci\u00f3n constituye un il\u00edcito.<\/p>\n<p>Ante esta situaci\u00f3n, adelant\u00f3 que solicitar\u00e1 la intervenci\u00f3n de la Fiscal\u00eda Especializada en Delitos Electorales, la Fiscal\u00eda General del Estado (FGE) de Veracruz y el Instituto Nacional Electoral (INE), con el fin de que se investiguen posibles sanciones al respecto.<\/p>\n<p>\u201cCon la copia simple del padr\u00f3n electoral, ellos incurren en un delito, porque el padr\u00f3n electoral, por contener datos sensibles, no es susceptible de fotocopiar o de reproducirse\u201d.<\/p>\n<p>Y en cuanto a los se\u00f1alamientos sobre la presunta inelegibilidad de la candidata ganadora, confirm\u00f3 que Pilar Guzm\u00e1n Medell\u00edn cumple con todos los requisitos legales, al contar con acta de nacimiento y certificaci\u00f3n de residencia en el municipio de m\u00e1s de cuatro a\u00f1os.<\/p>\n<p>\u201cNo alcanzan a derrotar la victoria que tuvo Morena y el Partido Verde Ecologista de M\u00e9xico (PVEM), por lo tanto, Morena defender\u00e1 el triunfo de la ciudadana Pilar\u201d.<\/p>\n<p>Finalmente, aclar\u00f3 que la presencia de la diputada Citlalli Medell\u00edn Careaga en dos casillas durante la jornada electoral fue en calidad de ciudadana, pues ejerci\u00f3 su derecho al voto; record\u00f3 que la legisladora cuenta con licencia a su cargo, por lo que tiene sus derechos a salvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El representante de Movimiento Regeneraci\u00f3n Nacional (Morena) ante los \u00f3rganos electorales, Gabriel Z\u00fa\u00f1iga Ovando, calific\u00f3 como vaga, imprecisa y sin<\/p>\n","protected":false},"author":4,"featured_media":76727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-76726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/SDERT.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:23:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76726"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76727"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}