{"id":76723,"date":"2026-04-11T00:01:43","date_gmt":"2026-04-11T06:01:43","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76723"},"modified":"2026-04-10T19:41:10","modified_gmt":"2026-04-11T01:41:10","slug":"este-mes-inicia-rescate-integral-del-centro-historico-de-veracruz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/11\/este-mes-inicia-rescate-integral-del-centro-historico-de-veracruz\/","title":{"rendered":"Este mes inicia rescate integral del Centro Hist\u00f3rico de Veracruz"},"content":{"rendered":"<p>Durante este mes iniciar\u00e1 la rehabilitaci\u00f3n integral del Centro Hist\u00f3rico del puerto de Veracruz, anunci\u00f3 la gobernadora Roc\u00edo Nahle Garc\u00eda, como resultado del trabajo coordinado con el Ayuntamiento que encabeza Rosa Mar\u00eda Hern\u00e1ndez Espejo y el Instituto Nacional de Antropolog\u00eda e Historia, bajo la direcci\u00f3n en la entidad de Fernando Molina Herbert.<\/p>\n<p>Precis\u00f3 que el proyecto ejecutivo ya est\u00e1 concluido y que, tras la firma del convenio, las obras contemplan inversi\u00f3n para la conservaci\u00f3n del patrimonio cultural, as\u00ed como la rehabilitaci\u00f3n de edificios y monumentos hist\u00f3ricos, para dignificar los espacios p\u00fablicos y fortalecer la identidad del puerto.<\/p>\n<p>Por su parte, la presidenta municipal, Rosa Mar\u00eda Hern\u00e1ndez Espejo, destac\u00f3 el respaldo del Gobierno del Estado para atender m\u00e1s de 30 a\u00f1os de rezago hist\u00f3rico en la zona y avanzar en la recuperaci\u00f3n de espacios que por d\u00e9cadas permanecieron en abandono.<\/p>\n<p>Como parte del proyecto, se contempla tambi\u00e9n una intervenci\u00f3n urbana que incluye la definici\u00f3n de una paleta de colores y lineamientos est\u00e9ticos, en apego a criterios del INAH y tomando como referencia experiencias exitosas de rescate patrimonial en otras ciudades del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante este mes iniciar\u00e1 la rehabilitaci\u00f3n integral del Centro Hist\u00f3rico del puerto de Veracruz, anunci\u00f3 la gobernadora Roc\u00edo Nahle Garc\u00eda,<\/p>\n","protected":false},"author":4,"featured_media":76724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-76723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/VI.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:23:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76723"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76724"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}