{"id":76700,"date":"2026-04-10T00:14:05","date_gmt":"2026-04-10T06:14:05","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76700"},"modified":"2026-04-09T19:40:53","modified_gmt":"2026-04-10T01:40:53","slug":"congreso-de-tamaulipas-aprueba-minuta-de-plan-b","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/10\/congreso-de-tamaulipas-aprueba-minuta-de-plan-b\/","title":{"rendered":"Congreso de Tamaulipas aprueba minuta de &#8216;plan B&#8217;"},"content":{"rendered":"<p class=\"nota-justify\">El Congreso tamaulipeco aprob\u00f3 la minuta enviada por la C\u00e1mara de Diputados del Congreso de la Uni\u00f3n, el llamado &#8216;plan B&#8217;, mediante la cual se reforman los art\u00edculos 115 y 116, as\u00ed como la adici\u00f3n de un p\u00e1rrafo al art\u00edculo 134 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos.<\/p>\n<p class=\"nota-justify\">La reforma contempla ajustes en la integraci\u00f3n y funcionamiento de los ayuntamientos, en los presupuestos de los congresos locales, as\u00ed como el establecimiento de l\u00edmites a las remuneraciones de funcionarios electorales, en apego a los principios de austeridad, paridad de g\u00e9nero e igualdad sustantiva.<\/p>\n<p class=\"nota-justify\">Entre los principales cambios, se establece que los ayuntamientos tendr\u00e1n un l\u00edmite de hasta 15 regidur\u00edas, las cuales deber\u00e1n ser electas bajo los principios de paridad de g\u00e9nero vertical y horizontal, as\u00ed como con perspectiva de g\u00e9nero e igualdad sustantiva.<\/p>\n<p class=\"nota-justify\">Asimismo, se fija que el presupuesto de las legislaturas locales no podr\u00e1 exceder el 0.70 por ciento del presupuesto de egresos de la entidad federativa correspondiente, fortaleciendo la disciplina y racionalidad en el ejercicio del gasto p\u00fablico.<\/p>\n<p class=\"nota-justify\">En su intervenci\u00f3n, la diputada Lucero Deosdady Mart\u00ednez L\u00f3pez afirm\u00f3 que esta reforma no debilita a las instituciones, las moderniza y las pone al servicio del pueblo, bajo principios de austeridad y justicia social.<\/p>\n<p class=\"nota-justify\">\u201cEsta reforma no es un ataque a la justicia electoral, sino su fortalecimiento democr\u00e1tico; coloca a las instituciones al servicio del pueblo, no de intereses particulares\u201d, expres\u00f3.<\/p>\n<p class=\"nota-justify\">\u201cEstamos legislando para que cada peso del pueblo se traduzca en bienestar, no en lujos para unos cuantos\u201d, a\u00f1adi\u00f3. Tambi\u00e9n la minuta destaca que se establecen l\u00edmites a las percepciones de altos mandos en \u00f3rganos electorales, por lo que las remuneraciones de consejeros y magistrados no podr\u00e1n superar las de la titular del Poder Ejecutivo Federal, conforme a lo establecido en la Constituci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso tamaulipeco aprob\u00f3 la minuta enviada por la C\u00e1mara de Diputados del Congreso de la Uni\u00f3n, el llamado &#8216;plan<\/p>\n","protected":false},"author":4,"featured_media":76701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-76700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/tamaulipas-aprueba-reforma-constitucional-sobre-ayuntamientos-y-austeridad_a0983e03-56c3-45fe-a5d2-5d7ef5814816_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:35:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76700"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76701"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}