{"id":76679,"date":"2026-04-10T00:08:40","date_gmt":"2026-04-10T06:08:40","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76679"},"modified":"2026-04-09T19:26:27","modified_gmt":"2026-04-10T01:26:27","slug":"ante-mayor-importacion-de-gas-sheinbaum-reitera-analizar-fracking-con-enfoque-sostenible","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/10\/ante-mayor-importacion-de-gas-sheinbaum-reitera-analizar-fracking-con-enfoque-sostenible\/","title":{"rendered":"Ante mayor importaci\u00f3n de gas, Sheinbaum reitera analizar &#8216;fracking&#8217; con enfoque sostenible"},"content":{"rendered":"<p class=\"nota-justify\">La presidenta Claudia Sheinbaum Pardo asegur\u00f3 que la explotaci\u00f3n de fuentes \u201cno convencionales\u201d de gas natural ser\u00eda con el fracking de nuevas tecnolog\u00edas, con bajo impacto ambiental y uso de componentes biodegradables y no con fractura hidr\u00e1ulica tradicional.<\/p>\n<p class=\"nota-justify\">\u201c\u00c9se no, porque s\u00ed tiene impactos ambientales muy graves, pero hay nuevas t\u00e9cnicas, nuevas tecnolog\u00edas que nos abren la posibilidad de que el agua sea reciclada, de que no se usen estos qu\u00edmicos tan potentes que son dif\u00edciles de reciclar\u201d.<\/p>\n<p class=\"nota-justify\">Sostuvo que \u201chay que estar abiertos a estas nuevas tecnolog\u00edas para fortalecer la soberan\u00eda nacional. O sea, existe evidencia de que esta tecnolog\u00eda de fracking con bajo impacto ambiental se ha desarrollado en otros pa\u00edses y podr\u00eda traerse a M\u00e9xico\u201d. Incluso mencion\u00f3 que empresas mexicanas que tienen qu\u00edmicos biodegradables o sustancias biodegradables han demostrado que pueden ser utilizadas\u201d.<\/p>\n<p class=\"nota-justify\">\u201cSi seguimos as\u00ed, vamos a importar m\u00e1s\u201d de ese pa\u00eds, del cual ya importamos 75 por ciento de ese combustible.<\/p>\n<p class=\"nota-justify\">\u201cNecesitamos gas natural en la perspectiva y en el plan que hemos hecho; necesitamos para una parte de la base de la generaci\u00f3n el\u00e9ctrica, que son plantas muy eficientes que funcionan las 24 horas del d\u00eda.<\/p>\n<p class=\"nota-justify\">\u201c\u00bfQu\u00e9 hacemos con ese 75 por ciento de gas que estamos importando, \u201cfrente a una situaci\u00f3n como la que hemos vivido recientemente y la que han vivido otras regiones del mundo, donde por razones clim\u00e1ticas puede estar disponible el gas?\u201d, como son heladas donde sube mucho el precio.<\/p>\n<p class=\"nota-justify\">Indic\u00f3 que los estudios que se han hecho no son suficientes por lo que \u201ctodav\u00eda tendr\u00edamos que importar mucho\u201d.<\/p>\n<p class=\"nota-justify\">Resalt\u00f3 que ella se mantiene en contra del fracking tradicional, \u201ctoda mi vida hable en contra de \u00e9l\u2026 No queremos lo tradicional, \u00e9se s\u00ed tiene impactos graves, pero hay nuevas tecnolog\u00edas, incluso para evitar el cambio clim\u00e1tico que inyectan el metano y el CO2 que se produce para que pueda volver a romper las piedras\u201d.<\/p>\n<p class=\"nota-justify\">Indic\u00f3 que hay un desarrollo muy grande en esto, entre otras empresas de Estados Unidos y Canad\u00e1.<\/p>\n<p class=\"nota-justify\">Se\u00f1al\u00f3 que a\u00fan no tienen el mecanismo, pero manifest\u00f3 que la idea es considerar contratos mixtos y de Petr\u00f3leos Mexicanos (Pemex), pero no concesiones ni contratos privados, \u201cni de servicios m\u00faltiples\u201d, como se hizo en la \u00e9poca de Felipe Calder\u00f3n, \u201cque eran absolutamente leoninos o las rondas que hizo (Enrique) Pe\u00f1a Nieto\u201d.<\/p>\n<p class=\"nota-justify\">&#8211; \u00bfSer\u00e1 necesaria alguna adecuaci\u00f3n legal o constitucional para este tema?<br \/>\nNo, ninguna, ya est\u00e1 todo contemplado. Lo primero es la garant\u00eda de la soberan\u00eda sobre los recursos naturales\u2026 En todo caso, si hay alguna participaci\u00f3n privada en contratos, tendr\u00edan que determinarlo la Secretar\u00eda de Energ\u00eda y Pemex, a trav\u00e9s de mecanismos que beneficien a las y a los mexicanos.<\/p>\n<p class=\"nota-justify\">El objetivo es que \u201cprimero se pague el impuesto para el bienestar, que es la garant\u00eda para todas y todos los mexicanos, y que el mayor porcentaje de la explotaci\u00f3n vaya para Pemex y en todo caso que una parte pueda ser desarrollada por los privados, como ha sido en muchos casos, pero primero hay que determinar las tecnolog\u00edas\u201d.<\/p>\n<p class=\"nota-justify\">Por eso queremos que los expertos nos digan \u201cqu\u00e9 tipo de qu\u00edmicos se deber\u00edan de usar, que en su mayor\u00eda deben permitir el reciclamiento de agua y de qu\u00e9 tipo debe usarse, y los impactos que pudieran tener; d\u00f3nde se podr\u00eda hacer y donde no\u201d.<\/p>\n<p class=\"nota-justify\">-\u00bfNo existe el riesgo de que M\u00e9xico pase de una dependencia de la importaci\u00f3n a una dependencia tecnol\u00f3gica de empresas extranjeras?<\/p>\n<p class=\"nota-justify\">Bueno, hay mucha dependencia tecnol\u00f3gica de M\u00e9xico en muchas \u00e1reas; las turbinas de gas que usa la Comisi\u00f3n Federal de Electricidad no se producen en M\u00e9xico, se importan\u2026 Los paneles solares que se utilizan en todo el mundo, la mayor\u00eda se producen en China.<\/p>\n<p class=\"nota-justify\">\u201cObviamente queremos ampliar las capacidades de Pemex y ahora tan lo estamos haciendo, que se est\u00e1 utilizando a los propios trabajadores en muchas obras\u2026 Queremos fortalecer la soberan\u00eda de M\u00e9xico, tambi\u00e9n pero hay muchas tecnolog\u00edas que est\u00e1n disponibles en el mundo entero que hay que utilizarlas\u201d.<\/p>\n<p class=\"nota-justify\">Insisti\u00f3 que contin\u00faan en pl\u00e1ticas con \u201cun grupo de expertos mexicanos, -de la UNAM, del Polit\u00e9cnico y otras instancias acad\u00e9micas- de los mejores en agua, en geotermia, en geolog\u00eda, en geof\u00edsica, en residuos peligrosos, en reciclamiento de agua\u201d, para que nos ayuden a tomar la mejor decisi\u00f3n posible para el futuro de M\u00e9xico.<\/p>\n<p class=\"nota-justify\">La pr\u00f3xima semana \u201cvamos a presentar a los expertos que nos van a ayudar a tomar la mejor decisi\u00f3n, porque ser\u00eda muy irresponsable de nuestra parte decir: seguimos importando y no vemos ninguna otra alternativa\u201d.<\/p>\n<p class=\"nota-justify\">La mandataria rechaz\u00f3 las versiones de que se puso de acuerdo con Larry Fink, presidente de BlackRock, para anunciar el\u00a0<i>fracking<\/i>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum Pardo asegur\u00f3 que la explotaci\u00f3n de fuentes \u201cno convencionales\u201d de gas natural ser\u00eda con el fracking<\/p>\n","protected":false},"author":4,"featured_media":76680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-76679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/declaudiaygas0904.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:40:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76679"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76680"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}