{"id":76673,"date":"2026-04-10T00:06:01","date_gmt":"2026-04-10T06:06:01","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76673"},"modified":"2026-04-09T19:22:57","modified_gmt":"2026-04-10T01:22:57","slug":"reitera-stps-desacuerdo-con-conclusiones-de-panel-del-t-mec-sobre-injerencia-patronal-en-mina-de-zacatecas","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/10\/reitera-stps-desacuerdo-con-conclusiones-de-panel-del-t-mec-sobre-injerencia-patronal-en-mina-de-zacatecas\/","title":{"rendered":"Reitera STPS desacuerdo con conclusiones de panel del T-MEC sobre injerencia patronal en mina de Zacatecas"},"content":{"rendered":"<p class=\"nota-justify\">El secretario del Trabajo y Previsi\u00f3n Social del Gobierno de M\u00e9xico, Marath Baruch Bola\u00f1os L\u00f3pez, advirti\u00f3 que los paneles del Mecanismo de Respuesta R\u00e1pida del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC) s\u00f3lo deben abordar temas sobre la libertad sindical y la negociaci\u00f3n colectiva aut\u00e9ntica, por lo que reiter\u00f3 su desacuerdo con las conclusiones de un panel sobre violencia e injerencia patronal en una mina de Zacatecas propiedad de una compa\u00f1\u00eda canadiense.<\/p>\n<p class=\"nota-justify\">Hay un planteamiento que se realiz\u00f3 que no estamos de acuerdo porque solo estas dos materias son las que se deben abordar en el panel o en el tratado \u00aby aqu\u00ed est\u00e1n planteando temas que no son laborales propiamente\u00bb sostuvo.<\/p>\n<p class=\"nota-justify\">El funcionario federal se refiri\u00f3 a la resoluci\u00f3n preliminar del tercer panel que se realiza en el marco del T-MEC, donde se determin\u00f3 que la compa\u00f1\u00eda canadiense Orla Mining, propietaria de la mina de oro y plata Camino Rojo, ubicada en el muncipio de Mazapil, Zacatecas, \u201cmantuvo silencio y mostr\u00f3 tolerancia\u201d al uso del crimen organizado para amedrentar a trabajadores afiliados a la secci\u00f3n 335 del Sindicato Nacional Minero, adem\u00e1s de la inacci\u00f3n sobre las denuncias de violaciones a la libertad sindical.<\/p>\n<p class=\"nota-justify\">La intimidaci\u00f3n provino de un contratista y de personal de la empresa, se\u00f1al\u00f3 el panel de expertos, para violar derechos laborales y provocar la deserci\u00f3n por lo que consider\u00f3 la injerencia patronal en actividades sindicales.<\/p>\n<p class=\"nota-justify\">Una nota publicada este jueves 9 de abril se\u00f1ala que el panel corrobor\u00f3 \u201cque la mina contrat\u00f3 a un narcotraficante para interrumpir las reuniones sindicales con personas armadas, proferir amenazas de muerte y obligar a los trabajadores a aceptar el sindicato preferido de la empresa\u201d, seg\u00fan un comentario adjudicado al Departamento de Trabajo de Estados Unidos.<\/p>\n<p class=\"nota-justify\">Al finalizar la inauguraci\u00f3n del Centro de Atenci\u00f3n Integral para trabajadores agr\u00edcolas de San Quint\u00edn, al sur de Baja California, el secretario federal del Trabajo dijo no estar de acuerdo con el planteamiento del panel, \u00abpero vamos a seguir trabajando al respecto\u00bb<\/p>\n<p class=\"nota-justify\">Advirti\u00f3 que \u00abese mecanismo laboral es muy asim\u00e9trico, no tiene posibilidad de que M\u00e9xico denuncie violaciones laborales en Estados Unidos\u00bb.<\/p>\n<p class=\"nota-justify\">Cuestionado sobre la diversificaci\u00f3n del crimen organizado en esta zona del pa\u00eds, dijo que el Estado Mexicano y ha hecho una reducci\u00f3n importante a delitos de alto impacto.<\/p>\n<p>No estamos de acuerdo con las conclusiones del panel del MMR del T-MEC, sostuvo al tiempo de advertir que la Secretar\u00eda del Trabajo ha tenido la claridad de defender los derechos de los trabajadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario del Trabajo y Previsi\u00f3n Social del Gobierno de M\u00e9xico, Marath Baruch Bola\u00f1os L\u00f3pez, advirti\u00f3 que los paneles del<\/p>\n","protected":false},"author":4,"featured_media":76674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-76673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/stps-rechaza-incluir-temas-no-laborales-en-resoluciones-de-paneles-del-tmec_37effab9-0a5f-43eb-8bd9-808e63871d18_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:04:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76673"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76674"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}