{"id":76630,"date":"2026-04-09T00:15:18","date_gmt":"2026-04-09T06:15:18","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76630"},"modified":"2026-04-08T21:33:58","modified_gmt":"2026-04-09T03:33:58","slug":"disuelven-caravana-migrante-genesis-en-chiapas","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/09\/disuelven-caravana-migrante-genesis-en-chiapas\/","title":{"rendered":"Disuelven caravana migrante \u201cG\u00e9nesis\u201d en Chiapas"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">La Caravana Migrante \u201cG\u00e9nesis\u201d que avanzaba por la costa de Chiapas fue disuelta por el Instituto Nacional de Migraci\u00f3n a la altura del municipio de Tonal\u00e1, a donde hab\u00eda llegado el domingo tras 12 d\u00edas de caminata, informaron fuentes oficiales.<\/p>\n<p class=\"nota-justify\">Los extranjeros decidieron aceptar la propuesta del INM de ser llevados en veh\u00edculos a otras ciudades de la regi\u00f3n como Tuxtla Guti\u00e9rrez y Villahermosa, indicaron las fuentes consultadas.<\/p>\n<p class=\"nota-justify\">\u201cLos migrantes ya estaban muy cansados, presentaban cuadros severos de deshidrataci\u00f3n. La mayor\u00eda eran adultos, hab\u00eda muy pocos ni\u00f1os\u201d, dijo un funcionario que pidi\u00f3 el anonimato.<\/p>\n<p class=\"nota-justify\">El domingo cuando llegaron a Tonal\u00e1 recibieron asistencia m\u00e9dica por parte de brigadistas de la Secretar\u00eda de Salud y de Protecci\u00f3n Civil, mientras que el sistema DIF les brind\u00f3 alimentaci\u00f3n, cont\u00f3 el servidor municipal.<\/p>\n<p class=\"nota-justify\">A\u00f1adi\u00f3 que los casi 300 extranjeros de Cuba, Venezuela, Hait\u00ed y pa\u00edses de Centro y Sudam\u00e9rica, principalmente, fueron llevados en peque\u00f1os grupos sin oponer resistencia y sin uso de la fuerza.<\/p>\n<p class=\"nota-justify\">Luis Garc\u00eda Villagr\u00e1n, coordinador del Centro de Dignificaci\u00f3n Humana AC, acus\u00f3 que el INM s\u00f3lo enga\u00f1a a los migrantes al ofrecerles ayuda con su proceso regularizaci\u00f3n pero \u00fanicamente les da un permiso con validez de 30 d\u00edas, pero los mantiene en el sur de M\u00e9xico porque siguen sin poder avanzar a otros Estados.<\/p>\n<p class=\"nota-justify\">\u201cLucran con el dolor al permitir que caminen por varios d\u00edas. Los desgastan y ya cuando est\u00e1n muy cansados les dicen que los van ayudar pero se los llevan a Tuxtla o Villahermosa, y no los dejan salir como ocurre en Tapachula\u201d, expres\u00f3<\/p>\n<p class=\"nota-justify\">Garc\u00eda Villagr\u00e1n se\u00f1al\u00f3 que los migrantes s\u00f3lo est\u00e1n pidiendo algo que por derecho internacional les asiste, que es acceder a un proceso de regularizaci\u00f3n y buscar mejores oportunidades laborales, algo que en Tapachula- la principal ciudad de la frontera con Guatemala- no pueden obtener porque las oficinas de Comar e INM est\u00e1n saturadas y los empleos ofrecen salarios bajos con jornadas largas.<\/p>\n<p class=\"nota-justify\">A\u00f1adi\u00f3 que la frontera sur tambi\u00e9n experimenta una exacerbaci\u00f3n de la xenofobia alentada en redes sociales presuntamente desde oficinas gubernamentales que terminan generando un entorno peligroso para los extranjeros.<\/p>\n<p class=\"nota-justify\">\u201cLos migrantes s\u00f3lo quieren trabajar y tener mejores oportunidades, algo que no encuentran en Tapachula donde est\u00e1n detenidos en contra de su voluntad. Aqu\u00ed los vemos trabajar de meseros, conductores, jornaleros y por todos lados pero con salarios bajos o son explotados\u201d, explic\u00f3.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Caravana Migrante \u201cG\u00e9nesis\u201d que avanzaba por la costa de Chiapas fue disuelta por el Instituto Nacional de Migraci\u00f3n a<\/p>\n","protected":false},"author":4,"featured_media":76631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-76630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/disuelven-caravana-migrante-genesis-en-chiapas_83ae119e-53ba-4bd0-bc52-b9f5e1bc6961_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:35:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76630"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76631"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}