{"id":76594,"date":"2026-04-09T00:03:25","date_gmt":"2026-04-09T06:03:25","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76594"},"modified":"2026-04-08T21:06:06","modified_gmt":"2026-04-09T03:06:06","slug":"llaman-a-tramitar-licencias-sin-intermediarios","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/09\/llaman-a-tramitar-licencias-sin-intermediarios\/","title":{"rendered":"Llaman a tramitar licencias sin intermediarios"},"content":{"rendered":"<p>El Gobierno del Estado exhorta a la ciudadan\u00eda a no recurrir a intermediarios o gestores, conocidos como coyotes, para realizar tr\u00e1mites de licencias de conducir, ya que no cuentan con respaldo legal y sus servicios pueden derivar en fraudes, p\u00e9rdidas econ\u00f3micas y la obtenci\u00f3n de documentos sin validez oficial.<\/p>\n<p>La Secretar\u00eda de Seguridad P\u00fablica (SSP), informa que la expedici\u00f3n de licencias se realiza \u00fanicamente de manera personal y presencial en los m\u00f3dulos oficiales autorizados por la Direcci\u00f3n General de Transporte del Estado (DGTE), por lo que cualquier oferta externa representa un riesgo para las y los usuarios.<\/p>\n<p>Para verificar la autenticidad de una licencia, la SSP pone a disposici\u00f3n el \u00fanico sitio oficial\u00a0<a href=\"https:\/\/licencias.sspver.gob.mx.\/\">https:\/\/licencias.sspver.gob.mx.<\/a>\u00a0Asimismo, las personas pueden escanear el c\u00f3digo QR impreso en el documento para acceder directamente al portal de validaci\u00f3n.<\/p>\n<p>En caso de que la licencia no aparezca en el sistema, se considera ap\u00f3crifa. Ante esta situaci\u00f3n, se recomienda iniciar el tr\u00e1mite correspondiente en los m\u00f3dulos oficiales de la DGTE y presentar la denuncia correspondiente.<\/p>\n<p>La Secretar\u00eda advierte que se han detectado al menos tres sitios web falsos que simulan ofrecer este servicio: licencias-sspver.com.mx, veracruz.validsystem.top y siete.buscaconsulta.com.mx. Como medida de seguridad, se recuerda que el portal oficial cuenta con dominio gubernamental gob.mx.<\/p>\n<p>Finalmente, reitera que la atenci\u00f3n y orientaci\u00f3n del personal de la DGTE es gratuita, independientemente de los costos establecidos para los tr\u00e1mites conforme a la normatividad vigente.<\/p>\n<p>Para denunciar cobros indebidos por parte de servidores p\u00fablicos o reportar a personas que operan como gestores, se encuentran disponibles la l\u00ednea de denuncia an\u00f3nima 089 y el n\u00famero de emergencias 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del Estado exhorta a la ciudadan\u00eda a no recurrir a intermediarios o gestores, conocidos como coyotes, para realizar<\/p>\n","protected":false},"author":4,"featured_media":76595,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-76594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/ALC.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:40:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76594"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76595"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}