{"id":76387,"date":"2026-04-03T00:18:08","date_gmt":"2026-04-03T06:18:08","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76387"},"modified":"2026-04-02T23:20:00","modified_gmt":"2026-04-03T05:20:00","slug":"gobierno-de-noboa-decreta-nuevo-estado-de-excepcion-por-violencia-en-nueve-provincias-de-ecuador","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/03\/gobierno-de-noboa-decreta-nuevo-estado-de-excepcion-por-violencia-en-nueve-provincias-de-ecuador\/","title":{"rendered":"Gobierno de Noboa decreta nuevo estado de excepci\u00f3n por violencia en nueve provincias de Ecuador"},"content":{"rendered":"<p class=\"nota-justify\">El presidente de Ecuador, Daniel Noboa, decret\u00f3 este jueves un nuevo estado de excepci\u00f3n que se extender\u00e1 por 60 d\u00edas sobre nueve provincias y cuatro cantones del pa\u00eds por la grave conmoci\u00f3n interna, report\u00f3 el diario\u00a0<i>El Universo<\/i>.<\/p>\n<p class=\"nota-justify\">La medida afectar\u00e1 a Guayas, Manab\u00ed, Santa Elena, Los R\u00edos, El Oro, Pichincha, Esmeraldas, Santo Domingo de los Ts\u00e1chilas y Sucumb\u00edos, as\u00ed como en los cantones La Man\u00e1, de Cotopaxi, Las Naves y Echeand\u00eda, en Bol\u00edvar, y La Troncal, en Ca\u00f1ar, detall\u00f3 el medio.<\/p>\n<p class=\"nota-justify\">Dicho decreto suspender\u00e1 los derechos a la inviolabilidad de domicilio e inviolabilidad de correspondencia.<\/p>\n<p class=\"nota-justify\">La suspensi\u00f3n del derecho a la inviolabilidad de domicilio permitir\u00e1 a la polic\u00eda realizar allanamientos inmediatos cuando existan \u201cindicios\u201d de que en el interior de los inmuebles se oculten integrantes del crimen organizado o se encuentren armas o sustancias sujetas a fiscalizaci\u00f3n u otros objetos que constituyan un delito.<\/p>\n<p class=\"nota-justify\">La suspensi\u00f3n del derecho a la inviolabilidad de correspondencia implica \u201cla identificaci\u00f3n, an\u00e1lisis, recopilaci\u00f3n de informaci\u00f3n estrictamente pertinente, cuando resulte indispensable para prevenir o neutralizar amenazas\u201d<\/p>\n<p class=\"nota-justify\">Noboa detall\u00f3 que permitir\u00e1 el empleo de fuerzas armadas en coordinaci\u00f3n con la polic\u00eda con el fin de precautelar \u201cla protecci\u00f3n interna, el mantenimiento y control del orden p\u00fablico y la seguridad ciudadana\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Ecuador, Daniel Noboa, decret\u00f3 este jueves un nuevo estado de excepci\u00f3n que se extender\u00e1 por 60 d\u00edas<\/p>\n","protected":false},"author":4,"featured_media":76388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-76387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/daniel-noboa-decreta-estado-de-excepcion-por-violencia-en-nueve-provincias_444a0e2a-249d-43cc-8196-31afa6c0cd63_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:41:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76387"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76388"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}