{"id":76363,"date":"2026-04-03T00:10:53","date_gmt":"2026-04-03T06:10:53","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76363"},"modified":"2026-04-02T22:58:39","modified_gmt":"2026-04-03T04:58:39","slug":"petroleo-se-dispara-hasta-10-por-tension-entre-eu-e-iran","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/03\/petroleo-se-dispara-hasta-10-por-tension-entre-eu-e-iran\/","title":{"rendered":"Petr\u00f3leo se dispara hasta 10% por tensi\u00f3n entre EU e Ir\u00e1n"},"content":{"rendered":"<p class=\"nota-justify\">Los precios del petr\u00f3leo internacional escalaron en promedio un 10 por ciento durante la jornada de este jueves, en el marco de una nueva ola de incertidumbre geopol\u00edtica.<\/p>\n<p class=\"nota-justify\">El barril de crudo West Texas Intermediate (WTI), referencia estadunidense, lleg\u00f3 a incrementarse m\u00e1s de un 11 por ciento, alcanzando los 111.54 d\u00f3lares, su mayor alza desde 2020; mientras que el Brent del mar del Norte, principal referencia europea, subi\u00f3 un 7.78 por ciento, hasta los 109.03 d\u00f3lares para entrega en junio.<\/p>\n<p class=\"nota-justify\">El discurso a la naci\u00f3n de Donald Trump, presidente de Estados Unidos, la noche del mi\u00e9rcoles dej\u00f3 en desconcierto a los inversionistas, pues aleja el final del conflicto al amenazar a Ir\u00e1n con hacer retroceder al pa\u00eds \u00aba la Edad de Piedra\u00bb si no hay acuerdo. Mientras, Ir\u00e1n lanz\u00f3 una nueva oleada de misiles y advirti\u00f3 de ataques \u201cm\u00e1s destructivos\u201d hasta la rendici\u00f3n de Estados Unidos. Asimismo, atac\u00f3 la infraestructura de Amazon.<\/p>\n<p class=\"nota-justify\">El crudo estadunidense WTI super\u00f3 el precio del europeo; es decir, el petr\u00f3leo estadunidense ya no est\u00e1 tan aislado de la interrupci\u00f3n que afecta al Brent por el cierre del estrecho de Ormuz, por lo que se empieza a enfrentar a una mayor prima de riesgo.<\/p>\n<p class=\"nota-justify\">Pese a que Donald Trump anunci\u00f3 que su pa\u00eds continuar\u00e1 con los ataques contra Ir\u00e1n, avivando los temores de interrupciones prolongadas en el suministro petrolero, los mercados accionarios de Estados Unidos, por su parte, borraron las p\u00e9rdidas matutinas y cerraron en verde la jornada de este jueves.<\/p>\n<p class=\"nota-justify\">El Nasdaq cerr\u00f3 con una ganancia de 0.18 por ciento; mientras que el S&amp;P 500 subi\u00f3 0.11 por ciento. El Dow Jones retrocedi\u00f3 0.13 por ciento.<\/p>\n<p class=\"nota-justify\">El mercado reaccion\u00f3 primero con miedo y despu\u00e9s recul\u00f3. Tras un desplome inicial, Wall Street recort\u00f3 p\u00e9rdidas este jueves, al calor de una expectativa: que el tr\u00e1fico energ\u00e9tico por el estrecho de Ormuz vuelva a normalizarse.<\/p>\n<p class=\"nota-justify\"><strong>El d\u00f3lar al quite<\/strong><\/p>\n<p class=\"nota-justify\">Con el regreso del nerviosismo de un precio del petr\u00f3leo m\u00e1s elevado y quiz\u00e1s por m\u00e1s tiempo hace temer un aumento de la inflaci\u00f3n fuera de los l\u00edmites permitidos para garantizar la estabilidad de precios, aunado a lo anterior, el d\u00f3lar regres\u00f3 a su papel de refugio.<\/p>\n<p class=\"nota-justify\">El \u00edndice DXY, que mide el comportamiento de la moneda estadunidense frente a una canasta de seis divisas internacionales, subi\u00f3 0.40 por ciento, a 99.86 unidades.<\/p>\n<p class=\"nota-justify\">Los mercados financieros mexicano se mantuvieron cerrados este jueves y ma\u00f1ana viernes tampoco tendr\u00e1n operaci\u00f3n, pero en operaciones internacionales, al ser una de las monedas m\u00e1s l\u00edquidas a nivel mundial, oper\u00f3 sobre los 17.8625 unidades por d\u00f3lar.<\/p>\n<p class=\"nota-justify\">En el mercado de deuda, nueva escalada de las rentabilidades. El rendimiento del bono alem\u00e1n vuelve a superar el 3 por ciento, mientras en Estados Unidos, la rentabilidad del bono a 10 a\u00f1os opera en 4.309 por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los precios del petr\u00f3leo internacional escalaron en promedio un 10 por ciento durante la jornada de este jueves, en el<\/p>\n","protected":false},"author":4,"featured_media":76364,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-76363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/04\/petroleo-se-dispara-hasta-10-por-tension-entre-eu-e-iran_fc8027cc-966f-4c3d-84ac-435a735687e8_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:56:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76363"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76364"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}