{"id":76309,"date":"2026-04-01T00:14:13","date_gmt":"2026-04-01T06:14:13","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76309"},"modified":"2026-03-31T21:14:59","modified_gmt":"2026-04-01T03:14:59","slug":"entre-criticas-congreso-de-chihuahua-designa-a-ada-miriam-aguilera-al-frente-de-la-cedh","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/04\/01\/entre-criticas-congreso-de-chihuahua-designa-a-ada-miriam-aguilera-al-frente-de-la-cedh\/","title":{"rendered":"Entre cr\u00edticas, Congreso de Chihuahua designa a Ada Miriam Aguilera al frente de la CEDH"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">El Congreso de Chihuahua, con mayor\u00eda de diputados del Partido Acci\u00f3n Nacional (PAN), design\u00f3 por 22 votos a favor y 11 en contra a la actual Fiscal Especializada en Investigaci\u00f3n de Violaciones a Derechos Humanos y Desaparici\u00f3n Forzada, Ada Miriam Aguilera Mercado, como nueva titular de la Comisi\u00f3n Estatal de los Derechos Humanos (CEDH), nombramiento que fue cuestionado por legisladores de Morena y organizaciones feministas.<\/p>\n<p class=\"nota-justify\">Fue el diputado panista Sa\u00fal Mireles Corral, miembro de la Junta de Coordinaci\u00f3n Pol\u00edtica, quien present\u00f3 el dictamen que conten\u00eda la terna de las personas a elegir para la titularidad de la CEDH: Ada Miriam Aguilera Mercado (22 votos), Flor Alejandra Corral Requejo (cero votos) y Fryda Libertad Licano Ram\u00edrez (cero votos), mismas que obtuvieron las mejores calificaciones dentro del proceso de evaluaci\u00f3n.<\/p>\n<p class=\"nota-justify\">Antes, el coordinador parlamentario de Morena, Cuauht\u00e9moc Estrada Sotelo, pidi\u00f3 que la terna de candidatas regresar\u00e1 a la Junta de Coordinaci\u00f3n Pol\u00edtica, porque Ada Miriam Aguilera fungi\u00f3 como representante jur\u00eddica del Partido Acci\u00f3n Nacional en 2019, antecedente que ella omiti\u00f3 referir en su postulaci\u00f3n, adem\u00e1s de que tiene v\u00ednculos evidentes con dicho instituto pol\u00edtico.<\/p>\n<p class=\"nota-justify\">En este sentido, los panistas defendieron que las personas interesadas en el proceso de elecci\u00f3n de ombudsman estatal, se inscribieron con su documentaci\u00f3n correspondiente entre el 13 de diciembre del 2025 y 11 de enero del 2026, el listado de quienes cumplieron los requisitos fue publicado el 16 de enero, mientras que el desahogo de las entrevistas se realiz\u00f3 los d\u00edas 19 y 20 de enero.<\/p>\n<p class=\"nota-justify\">Ada Miriam Aguilera fue la persona mejor evaluada durante el proceso de selecci\u00f3n, su nombramiento cumple la paridad de g\u00e9nero y ser\u00e1 la primera mujer al frente de la CEDH, resultado de un consenso entre distintas bancadas que incluye al grupo parlamentario de Morena, asegur\u00f3 el l\u00edder de los diputados del PAN, Alfredo Ch\u00e1vez Madrid.<\/p>\n<p class=\"nota-justify\">Sin embargo, organizaciones como Escuela de Formaci\u00f3n Feminista, Colectiva de Estudios Feministas Maye, Revoluci\u00f3n Atena, M\u00e9dicas Verde Violeta, y Frente contra la Violencia Vicaria se\u00f1alaron \u201cdeficiencias preocupantes\u201d en las mujeres aspirantes de la terna que vot\u00f3 el Congreso, incluida Ada Miriam Aguilera Mercado.<\/p>\n<p class=\"nota-justify\">Cuestionaron que el proceso de selecci\u00f3n permiti\u00f3 aspirantes con falta de preparaci\u00f3n en \u00e1reas clave como violencia familiar, digital y sexual contra mujeres, ni\u00f1as y adolescentes, la convocatoria refiere a \u00a0\u201cterminolog\u00eda obsoleta\u201d y se omitieron acciones preventivas esenciales, como la capacitaci\u00f3n y promoci\u00f3n de derechos humanos dentro del servicio p\u00fablico.<\/p>\n<p class=\"nota-justify\">\u201cEs indispensable que quien represente a este organismo tenga calidad moral probada, sin afiliaciones partidistas y con un conocimiento profundo en la materia\u201d, se\u00f1alaron en un pronunciamiento.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso de Chihuahua, con mayor\u00eda de diputados del Partido Acci\u00f3n Nacional (PAN), design\u00f3 por 22 votos a favor y<\/p>\n","protected":false},"author":4,"featured_media":76310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-76309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/entre-criticas-congreso-de-chihuahua-designa-a-ada-miriam-aguilera-en-cedh_f1cb0b23-c8ee-4322-9002-8c10dc22af65_medialjnimgndimagefullsize.webp","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 05:08:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76309"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76310"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}