{"id":76216,"date":"2026-03-31T00:03:44","date_gmt":"2026-03-31T06:03:44","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=76216"},"modified":"2026-03-30T21:03:06","modified_gmt":"2026-03-31T03:03:06","slug":"conade-impulsa-infraestructura-deportiva-en-veracruz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/31\/conade-impulsa-infraestructura-deportiva-en-veracruz\/","title":{"rendered":"CONADE impulsa infraestructura deportiva en Veracruz"},"content":{"rendered":"<p>El Gobierno de Veracruz, en coordinaci\u00f3n con la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (CONADE), impulsa la modernizaci\u00f3n de la infraestructura deportiva con el objetivo de posicionar a la entidad como sede de eventos nacionales e internacionales.<\/p>\n<p>En este contexto, la gobernadora Roc\u00edo Nahle Garc\u00eda y el director de la CONADE, Rommel Pacheco Marrufo, realizaron un recorrido por instalaciones clave como el Estadio Heriberto Jara Corona, el Vel\u00f3dromo Internacional de Xalapa y la Arena Macuilt\u00e9petl.<\/p>\n<p>Durante la visita, se plante\u00f3 la posibilidad de atraer nuevas competencias, entre ellas los Juegos Nacionales Populares, como parte de la estrategia para fortalecer el deporte en la entidad.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Modernizaci\u00f3n del Estadio Heriberto Jara<\/strong><\/h3>\n<p>En el Estadio Heriberto Jara Corona se presentaron los avances de su rehabilitaci\u00f3n integral, proyecto que contempla la modernizaci\u00f3n de sus instalaciones en el marco de su centenario.<\/p>\n<p>El plan incluye consolidarlo como un Centro de Alto Rendimiento, recuperar su pista de atletismo \u2014considerada entre las mejores de Latinoam\u00e9rica\u2014 y gestionar certificaciones que permitan albergar competencias de alto nivel.<\/p>\n<p>Se estima que los trabajos concluyan en un periodo de cuatro meses, con una capacidad proyectada para 10 mil espectadores.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Vel\u00f3dromo con certificaci\u00f3n internacional<\/strong><\/h3>\n<p>En el Vel\u00f3dromo Internacional de Xalapa, las autoridades destacaron su certificaci\u00f3n internacional y su experiencia como sede de disciplinas en los Juegos CONADE, como ciclismo y luchas asociadas.<\/p>\n<p>Estas condiciones lo posicionan como un recinto con potencial para recibir competencias de mayor escala.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Arena Macuilt\u00e9petl, en proceso de fortalecimiento<\/strong><\/h3>\n<p>En la Arena Macuilt\u00e9petl, con capacidad para m\u00e1s de 5 mil asistentes, se revis\u00f3 su situaci\u00f3n legal con el objetivo de ampliar las oportunidades de preparaci\u00f3n y competencia para atletas veracruzanos.<\/p>\n<p>Con estas acciones, Veracruz avanza en su consolidaci\u00f3n como un referente deportivo a nivel nacional, apostando por infraestructura moderna y espacios adecuados para el desarrollo de atletas y la atracci\u00f3n de eventos de alto nivel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Veracruz, en coordinaci\u00f3n con la Comisi\u00f3n Nacional de Cultura F\u00edsica y Deporte (CONADE), impulsa la modernizaci\u00f3n de<\/p>\n","protected":false},"author":4,"featured_media":76217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-76216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/CUFE.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:02:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=76216"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/76216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/76217"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=76216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=76216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=76216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}