{"id":75994,"date":"2026-03-27T00:05:29","date_gmt":"2026-03-27T06:05:29","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=75994"},"modified":"2026-03-26T22:37:20","modified_gmt":"2026-03-27T04:37:20","slug":"ai-saluda-ley-de-feminicidio-en-el-senado-y-pide-robustecerla","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/27\/ai-saluda-ley-de-feminicidio-en-el-senado-y-pide-robustecerla\/","title":{"rendered":"AI saluda ley de feminicidio en el Senado y pide robustecerla"},"content":{"rendered":"<p class=\"nota-justify\" dir=\"ltr\">Amnist\u00eda Internacional M\u00e9xico salud\u00f3 la iniciativa en el Senado sobre Ley General para Prevenir, Investigar, Sancionar y Reparar el Da\u00f1o por el Delito de Feminicidio y la consider\u00f3 un paso relevante hacia la garant\u00eda de verdad, justicia y reparaci\u00f3n.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">Por ello, hizo un llamado a los legisladores a abrir el di\u00e1logo a la sociedad civil para fortalecer la propuesta y responda a los derechos humanos de las v\u00edctimas y sus familias.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">Al referirse sobre la iniciativa, afirm\u00f3 que el Estado tiene una deuda con este sector y \u201cha sido documentada en informes y acciones legales que evidencian la falta de debida diligencia, impunidad y barreras para el acceso a la justicia en casos de feminicidio\u201d.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">Mencion\u00f3 que este proyecto de ley es resultado de a\u00f1os de lucha de familias de v\u00edctimas, colectivas y organizaciones, que \u201chan visibilizado las fallas en las investigaciones ministeriales y en los procesos de reparaci\u00f3n del da\u00f1o\u201d.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">Record\u00f3 dos casos de feminicidio que la organizaci\u00f3n defensora de derechos humanos acompa\u00f1\u00f3 y en ambos solicit\u00f3 un amicus curiae para visibilizar el actuar de las autoridades.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">Uno de ellos fue el de Karla Pontigo, con el cual quisieron exponer las fallas en la investigaci\u00f3n de su feminicidio y la falta de debida diligencia con perspectiva de g\u00e9nero.<\/p>\n<p class=\"nota-justify\" dir=\"ltr\">El otro fue el de Alejandra Garc\u00eda Andrade, cuyo recurso presentaron ante la Corte Interamericana de Derechos Humanos para subrayar la violencia estructural, la impunidad y los riesgos que enfrentan las familias que buscan justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amnist\u00eda Internacional M\u00e9xico salud\u00f3 la iniciativa en el Senado sobre Ley General para Prevenir, Investigar, Sancionar y Reparar el Da\u00f1o<\/p>\n","protected":false},"author":4,"featured_media":75995,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-75994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/AMIN.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:33:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=75994"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/75995"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=75994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=75994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=75994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}