{"id":75814,"date":"2026-03-24T00:08:49","date_gmt":"2026-03-24T06:08:49","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=75814"},"modified":"2026-03-23T17:48:10","modified_gmt":"2026-03-23T23:48:10","slug":"sheinbaum-elogia-traduccion-de-los-derechos-de-la-mujer-a-lenguas-indigenas","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/24\/sheinbaum-elogia-traduccion-de-los-derechos-de-la-mujer-a-lenguas-indigenas\/","title":{"rendered":"Sheinbaum elogia traducci\u00f3n de los derechos de la mujer a lenguas ind\u00edgenas"},"content":{"rendered":"<p class=\"nota-justify\">Hasta la regi\u00f3n istme\u00f1a de esta entidad lleg\u00f3 la presidenta Claudia Sheinbaum para hacer un reconocimiento a las ind\u00edgenas, que en esta ocasi\u00f3n fue especialmente a quienes que tradujeron a 67 lenguas originarias la Cartilla de los Derechos de las Mujeres. Fue otra forma de resaltar el papel femenino en la preservaci\u00f3n de la lengua, la cultura y los valores de los pueblos nativos, que representan una herencia para el pa\u00eds.<\/p>\n<p class=\"nota-justify\">Ante decenas de mujeres del Istmo, la mandataria dedic\u00f3 su discurso a dos de sus prioridades: consolidar la revalorizaci\u00f3n de los pueblos originarios y resaltar el rol de ellas en la historia y en la vida p\u00fablica, porque pocas veces se les ha reconocido. Desde la llegada de la Cuarta Transformaci\u00f3n, dijo, y con ella el humanismo mexicano que promovi\u00f3 Andr\u00e9s Manuel L\u00f3pez Obrador, se ha reivindicado a los pueblos originarios.<\/p>\n<p class=\"nota-justify\">Y subray\u00f3: \u201cL\u00f3pez Obrador, otro gigante de la historia nacional&#8230; C\u00f3mo no les gusta que lo mencionemos a los conservadores, pero se van a quedar con las ganas, porque vamos a seguir hablando de \u00e9l\u201d.<\/p>\n<p class=\"nota-justify\">Destac\u00f3 que los dos primeros a\u00f1os de su gobierno se han destinado a reconocer a las mujeres, dedicando el primero a las hero\u00ednas ind\u00edgenas, y este 2026 a Margarita Maza. En este contexto, anunci\u00f3 que si la gente \u201cquiere que sigamos hasta 2030 \u2013en alusi\u00f3n a que, en su caso, se someter\u00e1 a la revocaci\u00f3n de mandato\u2013\u201d, el \u00faltimo a\u00f1o de su gobierno se dedicar\u00e1 a las hero\u00ednas an\u00f3nimas de M\u00e9xico.<\/p>\n<p class=\"nota-justify\">Eligi\u00f3 esta entidad para reconocer a las traductoras, porque Oaxaca es donde m\u00e1s lenguas originarias se hablan: 15 en total. \u201c\u00bfQu\u00e9 significa (esta traducci\u00f3n de la cartilla )? Es decir a todos que las mujeres tenemos derechos, que somos iguales \u2013cada quien con sus caracter\u00edsticas\u2013, porque durante a\u00f1os se consider\u00f3 que \u00e9ramos menos\u201d.<\/p>\n<p class=\"nota-justify\">Sheinbaum record\u00f3 que en el pasado reciente a\u00fan se les llamaba dialectos, porque no se conceb\u00eda que pudieran equipararse con el castellano. En realidad, dijo, \u201clos pueblos originarios son los que nos ense\u00f1aron a ser como somos los mexicanos\u201d, pues los valores que hay en el pa\u00eds provienen de nuestro pasado ind\u00edgena.<\/p>\n<p class=\"nota-justify\">Consider\u00f3 que el legado de nuestros ancestros tambi\u00e9n radica en asumir un sentido de comunidad que no existe en otras naciones, donde s\u00f3lo hay individualismo.<\/p>\n<p class=\"nota-justify\">Y en ese sentido, apunt\u00f3: Oaxaca es \u201cel gran maestro\u201d para adoptar esa idiosincrasia comunitaria, porque \u201caqu\u00ed el sentido de comunidad es profundo. \u00bfUstedes creen que en muchos lugares del mundo hay tierras comunales? Aqu\u00ed las hay desde antes de que llegaran los espa\u00f1oles\u201d.<\/p>\n<p class=\"nota-justify\">La traductora Odilia Aquino \u2013de la etnia ikoots\u2013 afirm\u00f3 que las mujeres ind\u00edgenas han sido protagonistas en el cuidado no s\u00f3lo de los hogares y la familia, sino tambi\u00e9n de las comunidades y los pueblos. Han sido fundamentales defendiendo la vida y la tierra, abri\u00e9ndose espacios en la vida p\u00fablica.<\/p>\n<p class=\"nota-justify\">Con la publicaci\u00f3n de esta cartilla, a\u00f1adi\u00f3, \u201ccaminamos juntas para hacer realidad las reformas al art\u00edculo segundo constitucional, en el que se reconoce plenamente a pueblos y comunidades ind\u00edgenas como sujetos de derecho p\u00fablico. Una disposici\u00f3n que incluye un apartado de las garant\u00edas de las mujeres ind\u00edgenas y afromexicanas que alienta la participaci\u00f3n femenina en la toma de decisiones sobre educaci\u00f3n, salud, la tierra y dem\u00e1s derechos humanos\u201d.<\/p>\n<p class=\"nota-justify\">La titular de la Secretar\u00eda de las Mujeres, Citlalli Hern\u00e1ndez, sostuvo que al concluir el periodo neoliberal, desde la administraci\u00f3n pasada se ha reconocido \u201ca los pueblos originarios como parte de la identidad nacional. Hoy en especial a las ind\u00edgenas, que son parte fundamental de la memoria colectiva, porque han permitido que las lenguas sobrevivan por medio de las asambleas, los tequios y las festividades.<\/p>\n<p class=\"nota-justify\">\u201cEllas son quienes cuidan de los bienes naturales, son las cuidadoras de la naturaleza, las guardianas de la medicina tradicional, del cuerpo y del esp\u00edritu. Son las principales promotoras de derechos, y aunque a\u00fan faltan muchos caminos por transitar, han conquistado espacios que les hab\u00edan sido negados hist\u00f3ricamente\u201d, subray\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta la regi\u00f3n istme\u00f1a de esta entidad lleg\u00f3 la presidenta Claudia Sheinbaum para hacer un reconocimiento a las ind\u00edgenas, que<\/p>\n","protected":false},"author":4,"featured_media":75815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-75814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/PNDJDS.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:09:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=75814"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/75815"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=75814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=75814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=75814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}