{"id":75526,"date":"2026-03-19T00:08:49","date_gmt":"2026-03-19T06:08:49","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=75526"},"modified":"2026-03-18T21:41:36","modified_gmt":"2026-03-19T03:41:36","slug":"manuel-velasco-ratifica-respaldo-del-pvem-al-plan-b-electoral","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/19\/manuel-velasco-ratifica-respaldo-del-pvem-al-plan-b-electoral\/","title":{"rendered":"Manuel Velasco ratifica respaldo del PVEM al plan B electoral"},"content":{"rendered":"<p class=\"nota-justify\">El coordinador del Partido Verde Ecologista de M\u00e9xico (PVEM) en el Senado, Manuel Velasco, ratific\u00f3 que apoyar\u00e1 el llamado plan B de la reforma electoral.<\/p>\n<p class=\"nota-justify\">\u201cTenemos pr\u00e1cticamente coincidencias en todos los puntos\u201d, pero consider\u00f3 que no es necesario que la presidenta Claudia Sheinbaum se someta al proceso de revocaci\u00f3n, pues tiene le respaldo de la mayor\u00eda de los mexicanos. En las encuestas est\u00e1 arriba del 70 por ciento y ha dado resultados, sobre todo en materia de seguridad, apunt\u00f3.<\/p>\n<p class=\"nota-justify\">Resalt\u00f3 que de septiembre de 2024 a la fecha se ha reducido en 44 por ciento los homicidios, la coordinaci\u00f3n con el gobierno de Estados Unidos ha sido eficaz, ha disminuido en m\u00e1s de 50 por ciento el tr\u00e1fico de fentanilo al pa\u00eds del norte y las muertes por esa droga\u00a0 en aquella naci\u00f3n han bajado m\u00e1s de 24 por ciento.<\/p>\n<p class=\"nota-justify\">Agreg\u00f3 que de 14 senadores del PVEM 13\u00a0 van por la reforma presidencial, al destacar que tratar\u00e1 de convencer a\u00a0 Luis Armando Melgar, quien ha declarado que votar\u00e1 en contra, pero \u00e9l habr\u00e1 de tomar su definici\u00f3n. \u201cYo no puedo tomar una definici\u00f3n por \u00e9l\u201d, enfatiz\u00f3.<\/p>\n<p class=\"nota-justify\">Por otra parte, dio a conocer el listado de sus correligionarios que participar\u00e1n en las encuestas de Morena para definir candidatos a gubernaturas. En este sentido, pidi\u00f3 que se respeten los resultados de dichos sondeos.<\/p>\n<p class=\"nota-justify\">Para Nayarit destap\u00f3 a la senadora Jasmine Bugar\u00edn, para Nuevos Le\u00f3n a Waldo Fernp\u00e1ndez, en Quer\u00e9taro va el diputado Ricardo Astudillo, en Guerero Karen Castrej\u00f3n, en Zacatecas \u00a0Carlos Puente, y en Sinaloa Ricardo Madrid.Para Baja California Sur Manuel Cota y Para Baja California Jorge Ramos, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coordinador del Partido Verde Ecologista de M\u00e9xico (PVEM) en el Senado, Manuel Velasco, ratific\u00f3 que apoyar\u00e1 el llamado plan<\/p>\n","protected":false},"author":4,"featured_media":75527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-75526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/ANO.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:06:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=75526"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/75527"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=75526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=75526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=75526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}