{"id":75479,"date":"2026-03-18T00:13:54","date_gmt":"2026-03-18T06:13:54","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=75479"},"modified":"2026-03-17T22:33:38","modified_gmt":"2026-03-18T04:33:38","slug":"zacatecas-con-bloqueos-campesinos-reclaman-cumplimiento-de-acuerdos-con-sader-conagua-y-cfe","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/18\/zacatecas-con-bloqueos-campesinos-reclaman-cumplimiento-de-acuerdos-con-sader-conagua-y-cfe\/","title":{"rendered":"Zacatecas: con bloqueos, campesinos reclaman cumplimiento de acuerdos con Sader, Conagua y CFE"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">Debido a que funcionarios federales de la Conagua, Sader y la CFE no han cumplido compromisos a los que se comprometieron, dar soluci\u00f3n, desde el pasado 4 de diciembre de 2025, este martes cientos de campesinos se manifestaron en las sedes de esas dependencias ubicadas en la zona conurbada de las ciudades de Guadalupe y Zacatecas, y realizaron bloqueos en el bulevares y avenidas, adem\u00e1s de tres casetas de peaje en carreteras federales que cruzan por las localidades de Osiris, Calera y Morf\u00edn Ch\u00e1vez.<\/p>\n<p class=\"nota-justify\">La movilizaci\u00f3n de los campesinos divididos en dos grandes grupos \u2013unos los productores que siembran bajo sistemas de riego, y los otros agricultores \u201cde temporal\u201d, es decir que dependen del ciclo de lluvias-, se movilizaron a bordo de sus camionetas y tractores, protestando \u201cineptitud burocr\u00e1tica\u201d, en las dependencias citadas. Entre otros dirigentes, la movilizaci\u00f3n de este martes tuvo como voceros a Severiano Zamarr\u00f3n L\u00f3pez, Josefa L\u00f3pez Moncada y David Caldera V\u00e1zquez.<\/p>\n<p class=\"nota-justify\">La respuesta a sus demandas no llegaba y luego los mismos funcionarios federales solicitaron en dos ocasiones una pr\u00f3rroga para dar respuesta: la primera para el 27 de febrero y la segunda para el 10 de marzo. En ambos casos, se les volvi\u00f3 a incumplir, y por eso ahora est\u00e1n nuevamente movilizados, en protesta por tiempo indefinido, frente a las oficinas de la Sader y la Conagua, as\u00ed como en la CFE.<\/p>\n<p class=\"nota-justify\">Uno de los principales asuntos es la actualizaci\u00f3n de los tr\u00e1mites de regularizaci\u00f3n y actualizaci\u00f3n de m\u00e1s de 500 pozos de riego \u2013cada pozo puede tener m\u00e1s de un agricultor beneficiario-, y deben estar realizados esos procedimientos a m\u00e1s tardar el 30 de abril.<\/p>\n<p class=\"nota-justify\">Si para esa fecha no est\u00e1n actualizados sus registros como usuarios de pozos de riego, perder\u00e1n la posibilidad de inscribirse para obtener los beneficios consistentes principalmente en subsidios federales, como la cuota energ\u00e9tica.<\/p>\n<p class=\"nota-justify\">Decenas de miles de automovilistas de la zona metropolitana de la ciudad de Guadalupe y la capital de Zacatecas, incluidos taxis y autos de renta mediante plataformas, as\u00ed como miembros del transporte p\u00fablico y sus miles de usuarios, quienes enfrentaron severos congestionamientos por los bloqueos de bulevares.<\/p>\n<p class=\"nota-justify\">Parad\u00f3jicamente el caos vial se agrav\u00f3 por el cierre de avenidas y cortes a la circulaci\u00f3n que realizaban en distintos puntos de la mancha urbana, integrantes de la Direcci\u00f3n Estatal de Polic\u00eda de Vialidad y Transporte, pues los cierres continuaban hasta las 19:00 horas de este martes.<\/p>\n<p class=\"nota-justify\">Este diario obtuvo una copia de la minuta que se elabor\u00f3 por personal de la Sader, en la reuni\u00f3n del pasado 4 de diciembre de 2025, en la que funcionarios de dependencias federales \u2013incluidos representantes de la Secretar\u00eda de Gobernaci\u00f3n-, recibieron y escucharon las peticiones de integrantes de la Uni\u00f3n de Productores Pozos Agr\u00edcolas en el Estado de Zacatecas.<\/p>\n<p class=\"nota-justify\">La reuni\u00f3n \u2013que tuvo lugar en un escenario de constantes manifestaciones y protestas de los campesinos, pr\u00e1cticamente durante todo el a\u00f1o 2025-, fue para \u201cla atenci\u00f3n de demandas y peticiones relacionadas con inquietudes respecto a las pr\u00f3rrogas de concesi\u00f3n en tr\u00e1mite, ingreso al decreto de facilidades administrativas y acceso al programa especial de energ\u00eda para el campo en materia de energ\u00eda el\u00e9ctrica de uso agr\u00edcola (PEUA), ejercicio 2026, y la revisi\u00f3n de adeudos hist\u00f3ricos con CFE 2023 y 2024\u201d.<\/p>\n<p class=\"nota-justify\">En aquella reuni\u00f3n Ver\u00f3nica Mart\u00ednez Garc\u00eda, funcionaria de la Conagua les comunic\u00f3 a los representantes de los productores de riego que le les dar\u00eda \u201cprioridad a 318 concesiones que son susceptibles de acceder a la cuota energ\u00e9tica del PEUA 2026, de acuerdo a la revisi\u00f3n con Agricultura, y se resolver\u00e1n con dictaminadores desde oficinas centrales\u201d.<\/p>\n<p class=\"nota-justify\">\u201cLa misma prioridad de resoluci\u00f3n aplicar\u00e1 para los tr\u00e1mites de concesiones de productores, que ya hicieron su tr\u00e1mite dentro del Decreto de Facilidades y que consideramos son del orden de 170\u201d, es decir, se admiti\u00f3 atender y resolver la problem\u00e1tica que presentan los concesionarios agr\u00edcolas de 518 pozos de agua.<\/p>\n<p class=\"nota-justify\">Incluso, Jes\u00fas Enrique V\u00e1zquez Liz\u00e1rraga, funcionario de la Secretar\u00eda de Agricultura, les comunic\u00f3 a los campesinos presentes que \u201cla presidenta de la Rep\u00fablica Claudia Sheinbaum Pardo ha determinado que se otorguen facilidades a los productores, para que ninguno -que cumpla los requisitos de la normatividad que lo rige-, se quede fuera del programa\u201d. Dichas facilidades consistir\u00edan en la \u201cAcreditaci\u00f3n Provisional de Concesi\u00f3n\u201d.<\/p>\n<p class=\"nota-justify\">Sin embargo, Severiano Zamarr\u00f3n L\u00f3pez inform\u00f3 en entrevista con La Jornada, en el plant\u00f3n afuera de la Conagua, que de los m\u00e1s de 500 tr\u00e1mites de regularizaci\u00f3n a los que hace m\u00e1s de tres meses se comprometieron a realizar los funcionarios federales, a la fecha lament\u00f3 \u201cno llevan un avance ni del 20 por ciento\u2026y pronto se vencer\u00e1 el plazo del \u00faltimo d\u00eda de abril\u201d.<\/p>\n<p class=\"nota-justify\">Por otra parte, los campesinos \u201cde temporal\u201d, quienes realizaron bloqueos en tres casetas de peaje y varios puntos de la zona metropolitana de las ciudades de Zacatecas y Guadalupe, insistieron en su demanda al gobierno estatal y federal, para que ampl\u00eden los cupos de acopio de frijol, debido a que s\u00f3lo se aceptaron 80 mil toneladas en los centros oficiales de compra de grano, con precio oficial de 27 pesos el kilo.<\/p>\n<p class=\"nota-justify\">Esto ha dejado \u201cfuera\u201d, del programa, a m\u00e1s de 250 mil toneladas de frijol, dejando a miles de productores al acecho de los intermediarios o coyotes, que les pagan su frijol a solamente 7 pesos el kilogramo. Como protesta, algunos campesinos tiraron algunos costales de frijol en la carretera, manifestando as\u00ed su descontento.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Debido a que funcionarios federales de la Conagua, Sader y la CFE no han cumplido compromisos a los que se<\/p>\n","protected":false},"author":4,"featured_media":75480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-75479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/LOSOM.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:45:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=75479"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/75480"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=75479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=75479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=75479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}