{"id":75443,"date":"2026-03-18T00:01:18","date_gmt":"2026-03-18T06:01:18","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=75443"},"modified":"2026-03-17T22:13:48","modified_gmt":"2026-03-18T04:13:48","slug":"daran-hasta-12-mil-pesos-a-pescadores","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2026\/03\/18\/daran-hasta-12-mil-pesos-a-pescadores\/","title":{"rendered":"Dar\u00e1n hasta 12 mil pesos a pescadores"},"content":{"rendered":"<p>La gobernadora de Veracruz, Roc\u00edo Nahle Garc\u00eda, inform\u00f3 que pescadores del estado recibir\u00e1n apoyos econ\u00f3micos tras la presencia de hidrocarburos que llegaron al litoral veracruzano, fen\u00f3meno que afect\u00f3 principalmente zonas del sur.<\/p>\n<p>La mandataria indic\u00f3 que, a trav\u00e9s del programa federal Bienpesca, alrededor de 25 mil pescadores en Veracruz, desde Tampico Alto hasta Agua Dulce, recibir\u00e1n un apoyo de 8 mil pesos.<\/p>\n<p>Adem\u00e1s, el Gobierno de Veracruz otorgar\u00e1 un apoyo estatal adicional de 4 mil pesos, con lo que cada trabajador del sector pesquero podr\u00e1 recibir hasta 12 mil pesos en total.<\/p>\n<p>\u201cSon 8 mil pesos por cada pescador\u201d, explic\u00f3 la gobernadora.<\/p>\n<p>Nahle Garc\u00eda se\u00f1al\u00f3 que uno de los municipios m\u00e1s afectados por la mancha de hidrocarburo fue Pajapan, donde pescadores participaron en las labores de limpieza junto con personal de Petr\u00f3leos Mexicanos (Pemex).<\/p>\n<p>Indic\u00f3 que Pemex otorg\u00f3 una aportaci\u00f3n econ\u00f3mica a los pescadores que colaboraron en las tareas para retirar el material de la costa.<\/p>\n<p>La gobernadora asegur\u00f3 que la mancha de hidrocarburo que se desplaz\u00f3 por el sur del estado y alcanz\u00f3 algunas playas de la zona conurbada Veracruz\u2013Boca del R\u00edo ya fue retirada, por lo que actualmente las costas se encuentran limpias.<\/p>\n<p>Explic\u00f3 que el material fue arrastrado por las corrientes marinas y no se trat\u00f3 de un derrame activo que continuara fluyendo hacia el litoral veracruzano.<\/p>\n<p>\u201cFue una mancha que se movi\u00f3 con las corrientes mar\u00edtimas y lleg\u00f3 a las costas de Veracruz\u201d, se\u00f1al\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gobernadora de Veracruz, Roc\u00edo Nahle Garc\u00eda, inform\u00f3 que pescadores del estado recibir\u00e1n apoyos econ\u00f3micos tras la presencia de hidrocarburos<\/p>\n","protected":false},"author":4,"featured_media":75444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-75443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2026\/03\/PESC.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:51:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=75443"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/75443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/75444"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=75443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=75443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=75443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}