{"id":7414,"date":"2022-08-26T07:40:56","date_gmt":"2022-08-26T12:40:56","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=7414"},"modified":"2022-08-26T07:42:27","modified_gmt":"2022-08-26T12:42:27","slug":"va-cfe-por-5-mil-antenas-para-ampliar-cobertura-de-internet-en-mexico-presidente","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2022\/08\/26\/va-cfe-por-5-mil-antenas-para-ampliar-cobertura-de-internet-en-mexico-presidente\/","title":{"rendered":"Va CFE por 5 mil antenas para ampliar cobertura de internet: Presidente"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\"><em><strong>CIUDAD DE M\u00c9XICO.<\/strong> <\/em>El presidente <strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong> dio a conocer que la<strong> Comisi\u00f3n Federal de Electricidad<\/strong> (CFE) montar 5 mil antenas, y no 2 mil 500, <strong>para alcanzar un 80 por ciento de cobertura de Internet y telefon\u00eda m\u00f3vil en el pa\u00eds.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Vamos a ampliar y vamos a invertir en la creaci\u00f3n con un montaje de 5 mil antenas en todo el pa\u00eds para ampliar la cobertura de Alt\u00e1n. Se va a llevar a cabo un acuerdo entre\u00a0CFE y Alt\u00e1n\u201d<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 18pt;\">Andr\u00e9s Manuel L\u00f3pez Obrador no dijo la cifra que se invertir\u00e1, solo del aumento en la meta en cuanto antenas. Sin embargo, se\u00f1al\u00f3 que\u00a0 hay cobertura solo de un 70%, pero con <span style=\"color: #ff0000;\">m\u00e1s antenas se conseguir\u00e1 llevar el servicio a otros 25 millones de mexicanos.<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 18pt; color: #ff0000;\"><strong>PROYECTO ALT\u00c1N<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Cuestionado por periodistas por el proyecto de internet gratuito, el presidente L\u00f3pez Obrador consider\u00f3 que Alt\u00e1n fue un mal proyecto, pensado para tener una red nacional de internet, pero no creci\u00f3 y fracas\u00f3. <\/span><span style=\"font-size: 14pt;\">Coment\u00f3 que la empresa quebr\u00f3, se qued\u00f3 con una deuda en\u00a0Nacional Financiera\u00a0y el gobierno tuvo que intervenir para resolver el problema.<\/span><\/p>\n<p class=\"p1\"><span style=\"color: #333333; font-size: 18pt;\"><strong>Precis\u00f3 que el Estado cuenta con el 61% de las acciones de esta empresa, que aclar\u00f3 no es estatal, y continuar\u00e1 siendo una empresa mixta con participaci\u00f3n mayoritaria del Estado mexicano.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9362 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/08\/P-INTERNET-2-1024x573.png\" alt=\"\" width=\"800\" height=\"448\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Coment\u00f3 que le cost\u00f3 mucho trabajo \u201cllegar a esto\u201d, pues Alt\u00e1n cay\u00f3 en quiebra, se debi\u00f3 esperar el tiempo de ley y respetar contratos.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador informo que se intervino en este caso porque se quiere que el pa\u00eds est\u00e9 comunicado con Internet y si no lo hace el Estado, no lo har\u00e1n las empresas particulares.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Record\u00f3 que fue el presidente L\u00f3pez Mateos quien tom\u00f3 la decisi\u00f3n de nacionalizar la industria el\u00e9ctrica y a partir de este hecho, se electrifica todo el pa\u00eds y<span style=\"color: #e42d33;\"> hoy M\u00e9xico tiene 99.6% de su poblaci\u00f3n con servicio de energ\u00eda el\u00e9ctrica.<\/span><\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Consider\u00f3 \u201cabsurdo\u201d y una justificaci\u00f3n al saqueo el manifestarse que el Estado debe diluirse, no participar en desarrollo y todo tiene que estar a cargo del mercado. Q<\/span><span style=\"font-size: 14pt;\">ue esto no se trata de ser estatista, sino de que el Estado cumpla con su responsabilidad social.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>Andr\u00e9s Manuel L\u00f3pez Obrador dijo que se fortalecer esta red, que \u201cno fue hecha para el consumidor\u201d, sino para dar servicio a intermediarios, a empresas que se dediquen a dar servicio a particulares\u201d. Es m\u00e1s dijo, <\/strong><strong>que la red de Alt\u00e1n, no llega a la llamada \u201c\u00faltima milla\u201d, y no llega a los pueblos m\u00e1s apartados.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Adelant\u00f3 que se va ampliar\u00e1 la red de Alt\u00e1n porque la CFE ya tiene una nueva filial que se llama Internet para Todos, \u201cestamos calculando que vamos a llegar al 80%\u201d. <\/span><span style=\"font-size: 14pt;\">Y tambi\u00e9n se dar\u00e1 servicio a las 3 mil sucursales del Banco del Bienestar y a las comunidades apartadas. Aunque el presidente dijo<\/span><span style=\"font-size: 14pt;\">\u00a0que el fin de semana realizar\u00e1 una gira para reunirse con los trabajadores electricistas e iniciar con este proyecto.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Sostuvo que sin fines de lucro se buscar\u00e1 sacar los costos de operaci\u00f3n, evitar que tenga n\u00fameros rojos, pero que brinde el servicio, \u201cporque va a ser una gran revoluci\u00f3n, va a ser excepcional\u201d, que en todos los pueblos de M\u00e9xico, en las escuelas, los j\u00f3venes puedan contar con conexi\u00f3n a internet, pues <\/span><span style=\"font-size: 14pt;\">lo que se hizo anteriormente fue un fraude, pues les daban equipos, pero no ten\u00edan conexi\u00f3n a la red.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CIUDAD DE M\u00c9XICO. El presidente Andr\u00e9s Manuel L\u00f3pez Obrador dio a conocer que la Comisi\u00f3n Federal de Electricidad (CFE) montar 5 mil antenas, y no 2 mil 500, para alcanzar un 80 por ciento de cobertura de Internet y telefon\u00eda m\u00f3vil en el pa\u00eds. &nbsp; Vamos a ampliar y vamos a invertir en la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[1296,65,940,1297,550],"class_list":["post-7414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-altan","tag-andres-manuel-lopez-obrador","tag-cfe","tag-cobertura","tag-internet"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 01:54:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2022\/08\/P-INTERNET-1.png","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/7414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=7414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/7414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/7415"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=7414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=7414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=7414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}