{"id":61645,"date":"2025-08-02T02:45:23","date_gmt":"2025-08-02T08:45:23","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=61645"},"modified":"2025-08-02T02:45:23","modified_gmt":"2025-08-02T08:45:23","slug":"rina-entre-alcaldes-morenistas-en-edomex-deja-dos-policias-lesionados","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/08\/02\/rina-entre-alcaldes-morenistas-en-edomex-deja-dos-policias-lesionados\/","title":{"rendered":"Ri\u00f1a entre alcaldes morenistas en Edomex deja dos polic\u00edas lesionados"},"content":{"rendered":"<div id=\"article-content-tts\" class=\"nota-contenido mb-5\">\n<div id=\"content_nitf\">\n<p class=\"nota-justify\">Dos polic\u00edas lesionados dej\u00f3 una ri\u00f1a entre dos alcaldes del estado de M\u00e9xico, Juana Carrillo Luna, de Cuautitl\u00e1n y Luis Zenteno Santaella, de Teoloyucan (ambos morenistas), quienes acompa\u00f1ados por polic\u00edas de sus alcald\u00edas, protagonizaron una disputa de l\u00edmites territoriales.<\/p>\n<p class=\"nota-justify\">Carrillo Luna se present\u00f3 en la carretera Las \u00c1nimas\u2013Coyotepec, donde coloc\u00f3 sellos de suspensi\u00f3n a la construcci\u00f3n de un Centro de Distribuci\u00f3n (Cedis), en un hecho donde hubo dos uniformados heridos por fracturas.<\/p>\n<p class=\"nota-justify\">\u201cEstamos haciendo actos de gobierno en nuestro municipio, porque ya basta de que est\u00e9n autorizando bodegas que yo vine a clausurar en Puente Grande\u201d, se\u00f1al\u00f3 la presidente municipal, quien responsabiliz\u00f3 al edil Luis Zenteno, de promover la violencia y autorizar el Cedis en territorio que es de Cuautitl\u00e1n.<\/p>\n<p class=\"nota-justify\">Insisti\u00f3 que en la avenida Las \u00c1nimas (vialidad paralela a la autopista M\u00e9xico-Quer\u00e9taro) existen graves problemas de movilidad y llam\u00f3 al alcalde Zenteno a respetar el territorio de Cuautitl\u00e1n. \u201cQue toda la gente est\u00e9 enterada que nosotros venimos a clausurar naves industriales, pero lo \u00fanico que ellos est\u00e1n buscando son beneficios econ\u00f3micos\u201d.<\/p>\n<p class=\"nota-justify\">Por su parte, el mun\u00edcipe de Teoloyucan en conferencia en redes sociales plante\u00f3 que existe un conflicto de l\u00edmites territoriales en la zona que perteneci\u00f3 a la ex Hacienda de San Jos\u00e9, pues asegur\u00f3 es parte de la zona. \u201cNo estoy de acuerdo que hagan actos de gobierno donde no les pertenece\u201d.<\/p>\n<p class=\"nota-justify\">No voy a permitir \u201cque nos vengan a faltar el respeto y nos hagan de menos\u201d, reclam\u00f3.<\/p>\n<p class=\"nota-justify\">La gobernadora Delfina G\u00f3mez y el secretario General de Gobierno, Horacio Duarte, pidieron a los ediles fueran \u201cprudentes\u201d.<\/p>\n<p class=\"nota-justify\">Acus\u00f3 que este viernes la alcaldesa pretendi\u00f3 hacer actos de gobierno en una empresa colocando sellos de suspensi\u00f3n, cuando ese establecimiento tributa en Teoloyucan, su escritura p\u00fablica tambi\u00e9n est\u00e1 dentro de la demarcaci\u00f3n y adem\u00e1s cumpli\u00f3 con los requisitos legales para establecerse en la zona.<\/p>\n<p class=\"nota-justify\">Carrillo Luna y Luis Zenteno arribaron al exterior del Cedis, donde por separado encararon a sus contrarios, incluso hubo empujones entre los efectivos de ambas demarcaciones y se escucharon detonaciones, las corporaciones se deslindaron de los disparos.<\/p>\n<p class=\"nota-justify\">En tanto, la alcald\u00eda de Cuautitl\u00e1n acus\u00f3 que resultaron lesionados al menos dos polic\u00edas con fracturas en pies y manos.<\/p>\n<p class=\"nota-justify\">\u201cDurante los hechos, empleados de Teoloyucan invitados por el mun\u00edcipe agredieron f\u00edsica y verbalmente a personal del gobierno de Cuautitl\u00e1n, disparando armas de fuego, poniendo en riesgo a funcionarios entre ellos a la propia alcaldesa\u201d, dio a conocer la alcald\u00eda de Cuautitl\u00e1n en un comunicado.<\/p>\n<\/div>\n<\/div>\n<div class=\"notas-relacionadas\"><\/div>\n<div class=\"nota-tags\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dos polic\u00edas lesionados dej\u00f3 una ri\u00f1a entre dos alcaldes del estado de M\u00e9xico, Juana Carrillo Luna, de Cuautitl\u00e1n y Luis<\/p>\n","protected":false},"author":4,"featured_media":61646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[145],"tags":[],"class_list":["post-61645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/08\/moren.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:49:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=61645"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/61646"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=61645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=61645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=61645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}