{"id":61557,"date":"2025-08-01T00:20:02","date_gmt":"2025-08-01T06:20:02","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=61557"},"modified":"2025-08-01T00:20:02","modified_gmt":"2025-08-01T06:20:02","slug":"necesario-reglamentar-criterios-sobre-elegibilidad-de-candidatos-en-eleccion-judicial-humphrey","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/08\/01\/necesario-reglamentar-criterios-sobre-elegibilidad-de-candidatos-en-eleccion-judicial-humphrey\/","title":{"rendered":"Necesario, reglamentar criterios sobre elegibilidad de candidatos en elecci\u00f3n judicial: Humphrey"},"content":{"rendered":"<p class=\"nota-justify\">Ante una eventual reforma legal es necesario reglamentar los criterios a partir de los cuales los comit\u00e9s de evaluaci\u00f3n de la elecci\u00f3n judicial declaran una candidatura elegible, advirti\u00f3 Carla Humphrey, consejera del Instituto Nacional Electoral (INE).<\/p>\n<p class=\"nota-justify\">Un d\u00eda despu\u00e9s de que la Sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF) revoc\u00f3 la metodolog\u00eda del INE, creada por este \u00f3rgano para revisar expedientes de los candidatos ganadores de la elecci\u00f3n judicial, la consejera dej\u00f3 en claro que la actuaci\u00f3n del Instituto se bas\u00f3 en una jurisprudencia de la Sala Superior.<\/p>\n<p class=\"nota-justify\">Ese lineamiento se\u00f1ala que hay dos momentos para la revisi\u00f3n de requisitos: cuando se registran los candidatos y antes de otorgar las constancias de mayor\u00eda.<\/p>\n<p class=\"nota-justify\">\u201cY eso fue lo que hicimos\u201d, indic\u00f3 Humphrey, una de las consejeras m\u00e1s activas en cuanto al an\u00e1lisis de documentos, quien hall\u00f3 cerca de 100 casos de candidatos que no cumpl\u00edan con los requisitos de promedio acad\u00e9mico estipulados en la Constituci\u00f3n.<\/p>\n<p class=\"nota-justify\">Aparte del tema de calificaciones (en licenciatura deb\u00edan acreditar 8.0 como m\u00ednimo, y al menos 9.0 en las materias de la especialidad para la cual se postularon los candidatos a jueces de distrito y magistrados de circuito), el INE emprendi\u00f3 una investigaci\u00f3n para determinar que los ganadores no tuvieran antecedentes (sentencia firme) en hechos violentos, en morosidad en el pago de pensiones alimentarias o se hallar\u00e1n pr\u00f3fugos de la justicia.<\/p>\n<p class=\"nota-justify\">Gracias a este buz\u00f3n abierto a la ciudadan\u00eda, m\u00e1s las indagatorias propias, se pusieron al descubierto circunstancias que los Comit\u00e9s de Evaluaci\u00f3n no reportaron; al final, con criterios propios, el INE determin\u00f3 que 46 personas no cumpl\u00edan con los requisitos de elegibilidad: 45 por el tema de los promedios acad\u00e9micos y una que se hallaba en prisi\u00f3n preventiva, acusado de abuso sexual a un menor de edad.<\/p>\n<p class=\"nota-justify\">No obstante, la Sala Superior revoc\u00f3 los acuerdos y orden\u00f3 se d\u00e9 constancia de mayor\u00eda a 15 de ellos que seg\u00fan el diagn\u00f3stico del INE no cumpl\u00edan el nivel m\u00ednimo de promedio acad\u00e9mico.<\/p>\n<p class=\"nota-justify\">En entrevista, la consejera Humphrey dijo que no est\u00e1 de acuerdo en la resoluci\u00f3n de la Sala Superior.<\/p>\n<p class=\"nota-justify\">\u201cHicimos una metodolog\u00eda, se aplic\u00f3 de manera uniforme a todas las candidaturas y resolvimos en consecuencia. La sentencia de la Sala Superior la tenemos que cumplir (aunque) por supuesto, no la comparto. Revisamos expediente por expediente. Esta es una \u00e1rea de oportunidad si hay una reforma para elegir a personas juzgadoras de poderes judiciales federal y locales\u201d, se\u00f1al\u00f3.<\/p>\n<p class=\"nota-justify\">Subray\u00f3 que el trabajo del INE fue importante porque los comit\u00e9s no dieron a conocer la metodolog\u00eda a partir de la cual otorgaron registro a aspirantes, de ah\u00ed que el INE adopt\u00f3 un sistema para no afectar los derechos de ninguna persona.<\/p>\n<p class=\"nota-justify\">Dijo que en los miles de documentos revisados el INE encontr\u00f3 un certificado con una calificaci\u00f3n sobrepuesta, entre otras circunstancias.<\/p>\n<p class=\"nota-justify\">En ese contexto, consider\u00f3, el INE deber\u00eda tener participaci\u00f3n en esa revisi\u00f3n,desde el primer momento, sobre todo porque pasan varios meses desde la primera evaluaci\u00f3n hasta la etapa posterior a la elecci\u00f3n, previo a la expedici\u00f3n de las constancias de mayor\u00eda, y la situaci\u00f3n de los candidatos ganadores puede cambiar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante una eventual reforma legal es necesario reglamentar los criterios a partir de los cuales los comit\u00e9s de evaluaci\u00f3n de<\/p>\n","protected":false},"author":4,"featured_media":61558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-61557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/08\/PER.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:28:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=61557"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/61558"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=61557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=61557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=61557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}