{"id":61291,"date":"2025-07-28T00:46:14","date_gmt":"2025-07-28T06:46:14","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=61291"},"modified":"2025-07-28T00:46:14","modified_gmt":"2025-07-28T06:46:14","slug":"iglesia-polaca-solicita-al-vaticano-expulsion-de-sacerdote-acusado-de-homicidio","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/07\/28\/iglesia-polaca-solicita-al-vaticano-expulsion-de-sacerdote-acusado-de-homicidio\/","title":{"rendered":"Iglesia polaca solicita al Vaticano expulsi\u00f3n de sacerdote acusado de homicidio"},"content":{"rendered":"<p class=\"nota-justify\">El arzobispo de Varsovia, en Polonia, solicit\u00f3 al Vaticano que expulse del sacerdocio a un sacerdote acusado de asesinar a un hombre sin hogar de 68 a\u00f1os, quien fue golpeado con un hacha y quemado.<\/p>\n<p class=\"nota-justify\">El sacerdote supuestamente golpe\u00f3 a la v\u00edctima en la cabeza con un hacha, lo roci\u00f3 con l\u00edquido inflamable y le prendi\u00f3 fuego, inform\u00f3 Aneta G\u00f3\u017ad\u017a, portavoz de la Fiscal\u00eda del Distrito de Radom. Luego, el sacerdote se alej\u00f3 en su coche al ver una luz de bicicleta acerc\u00e1ndose.<\/p>\n<p class=\"nota-justify\">El pasado s\u00e1bado, los fiscales acusaron al sacerdote, identificado s\u00f3lo como Miros\u0142aw M. de acuerdo con las normas de privacidad polacas, de asesinato con particular crueldad. Est\u00e1 detenido a la espera de un juicio y enfrenta una condena de 15 a\u00f1os a cadena perpetua tras las rejas.<\/p>\n<p class=\"nota-justify\">Los investigadores dicen que el sacerdote y la v\u00edctima, Anatol Cz., estaban juntos en un coche tarde el jueves cuando estall\u00f3 una discusi\u00f3n, seg\u00fan G\u00f3\u017ad\u017a.<\/p>\n<p class=\"nota-justify\">La pelea surgi\u00f3 de un acuerdo de donaci\u00f3n en el que el sacerdote hab\u00eda acordado proporcionar asistencia y cuidado de por vida al hombre, explic\u00f3 G\u00f3\u017ad\u017a en un comunicado, la discusi\u00f3n se intensific\u00f3 por la futura vivienda del hombre sin hogar.<\/p>\n<p class=\"nota-justify\">El ciclista encontr\u00f3 a la v\u00edctima envuelta en llamas y llam\u00f3 a los servicios de emergencia, dijo G\u00f3\u017ad\u017a \u00abUna autopsia mostr\u00f3 que la v\u00edctima sufri\u00f3 quemaduras que cubr\u00edan el 80 por ciento de su cuerpo y lesiones en la cabeza causadas por un objeto pesado con filo\u00bb, asegur\u00f3 G\u00f3\u017ad\u017a.<\/p>\n<p class=\"nota-justify\">El arzobispo de Varsovia, Adrian Galbas, solicit\u00f3 el s\u00e1bado a la Santa Sede que destituya al sacerdote del sacerdocio, la pena m\u00e1s alta en el derecho can\u00f3nico para un cl\u00e9rigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El arzobispo de Varsovia, en Polonia, solicit\u00f3 al Vaticano que expulse del sacerdocio a un sacerdote acusado de asesinar a<\/p>\n","protected":false},"author":4,"featured_media":61292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[355],"tags":[],"class_list":["post-61291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/VATI.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:28:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=61291"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/61291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/61292"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=61291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=61291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=61291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}