{"id":60487,"date":"2025-07-14T20:49:30","date_gmt":"2025-07-15T02:49:30","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=60487"},"modified":"2025-07-14T20:49:30","modified_gmt":"2025-07-15T02:49:30","slug":"clase-magistral-de-poder-y-dignidad-rocio-nahle-frente-a-aristegui","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/07\/14\/clase-magistral-de-poder-y-dignidad-rocio-nahle-frente-a-aristegui\/","title":{"rendered":"\u201cClase magistral de poder y dignidad: Roc\u00edo Nahle frente a Aristegui\u201d"},"content":{"rendered":"<p style=\"font-weight: 400;\"><em>\u201cLa conducta es un espejo en que cada uno muestra su imagen\u201d. \u2013 . Johann Wolfgang von Goethe.<\/em><\/p>\n<p style=\"font-weight: 400;\"><strong>En pol\u00edtica, como en la vida, hay momentos en que la inteligencia y la elegancia derrotan al esc\u00e1ndalo y al amarillismo. As\u00ed ocurri\u00f3 recientemente cuando la gobernadora de Veracruz, Roc\u00edo Nahle Garc\u00eda, dio una verdadera c\u00e1tedra de altura pol\u00edtica, temple y dignidad al ejercer su derecho de r\u00e9plica en el noticiero de Carmen Aristegui, luego de que la reconocida periodista diera voz al general Eduardo Le\u00f3n Trauwitz, pr\u00f3fugo de la justicia y se\u00f1alado por el robo sistem\u00e1tico de combustibles en Pemex.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Con firmeza, sin estridencias y con datos precisos, la mandataria veracruzana desarm\u00f3 las acusaciones lanzadas por quien est\u00e1 hoy en la mira de la Interpol y es investigado por la Fiscal\u00eda General de la Rep\u00fablica junto a una red de colaboradores que ya fueron condenados por sustracci\u00f3n il\u00edcita de hidrocarburos y delincuencia organizada.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Lejos de caer en la provocaci\u00f3n, Nahle record\u00f3 el breve encuentro que sostuvo con Le\u00f3n Trauwitz durante la etapa de transici\u00f3n, cuando \u00e9l mismo \u2014a sabiendas de su situaci\u00f3n\u2014 pretendi\u00f3 ofrecer servicios de \u201cinteligencia\u201d sin aportar absolutamente nada relevante. \u201cY usted, \u00bfpor qu\u00e9 se va?\u201d, le cuestion\u00f3 con natural contundencia en aquella reuni\u00f3n. \u201cPorque ya me voy a Panam\u00e1\u201d, respondi\u00f3 el entonces funcionario, en lo que ahora suena a confesi\u00f3n anticipada de fuga.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>La gobernadora aprovech\u00f3 el espacio para poner sobre la mesa un tema mayor: el desfalco energ\u00e9tico impulsado desde la Reforma Energ\u00e9tica de Pe\u00f1a Nieto, que permiti\u00f3 la entrega indiscriminada de m\u00e1s de mil permisos de importaci\u00f3n de combustibles sin sustento t\u00e9cnico ni fiscalizaci\u00f3n real.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u201cEra inundar el mercado sin control\u201d, sentenci\u00f3, al tiempo que explic\u00f3 c\u00f3mo desde la Secretar\u00eda de Energ\u00eda se logr\u00f3 depurar el sistema, cancelando permisos ilegales y desmontando un huachicol fiscal que operaba con total impunidad.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>La intervenci\u00f3n de Roc\u00edo Nahle no fue solo una defensa personal. Fue una lecci\u00f3n clara de c\u00f3mo se ejerce el poder con responsabilidad, inteligencia y transparencia. Y tambi\u00e9n fue un mensaje para quienes creen que las mujeres en la 4T est\u00e1n de paso. Al contrario, est\u00e1n m\u00e1s firmes que nunca, marcando diferencia con hechos y no con gritos.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Aristegui, acostumbrada a llevar la voz cr\u00edtica, esta vez fue sorprendida por una interlocutora que no s\u00f3lo desminti\u00f3, sino que desmont\u00f3 con hechos y sin aspavientos toda una narrativa. Una clase pol\u00edtica con todas sus letras. Y s\u00ed, una muestra m\u00e1s de que las mujeres de la 4T no solo llegaron: llegaron para quedarse.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Al tiempo.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-60403 size-full\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3.jpg\" alt=\"\" width=\"1024\" height=\"125\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3.jpg 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3-300x37.jpg 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3-768x94.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa conducta es un espejo en que cada uno muestra su imagen\u201d. \u2013 . Johann Wolfgang von Goethe. En pol\u00edtica,<\/p>\n","protected":false},"author":4,"featured_media":30989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-60487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/05\/LUIS-RAMIREZ-BAQUEIRO-800x445-1.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:31:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=60487"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/30989"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=60487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=60487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=60487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}