{"id":60427,"date":"2025-07-15T00:01:56","date_gmt":"2025-07-15T06:01:56","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=60427"},"modified":"2025-07-14T19:50:30","modified_gmt":"2025-07-15T01:50:30","slug":"impulsan-reforma-para-pedir-revocacion-de-ediles","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/07\/15\/impulsan-reforma-para-pedir-revocacion-de-ediles\/","title":{"rendered":"Impulsan reforma para pedir revocaci\u00f3n de ediles"},"content":{"rendered":"<p>Con el prop\u00f3sito de establecer el derecho de la ciudadan\u00eda de los municipios a solicitar la revocaci\u00f3n de mandato del o la presidenta municipal, el diputado Ricardo S\u00f3stenes Mej\u00eda Berdeja (PT) propone agregar un tercer y cuarto p\u00e1rrafos a la fracci\u00f3n I del art\u00edculo 115 de la Constituci\u00f3n Pol\u00edtica.<\/p>\n<p>Mediante una iniciativa, girada a la Comisi\u00f3n de Puntos Constitucionales, se\u00f1ala que las constituciones de los estados establecer\u00e1n las normas relativas a los procesos de revocaci\u00f3n de mandato del o la presidenta municipal.<\/p>\n<p>En el articulado transitorio precisa que, para efectos de la revocaci\u00f3n a que hace referencia la Constituci\u00f3n Pol\u00edtica, tanto a nivel federal como local, deber\u00e1 entenderse como el instrumento de participaci\u00f3n solicitado por la ciudadan\u00eda para determinar la conclusi\u00f3n anticipada en el desempe\u00f1o del cargo a partir de la p\u00e9rdida de la confianza.<\/p>\n<p>Adem\u00e1s, que las constituciones de las entidades federativas, dentro de los seis meses siguientes a la entrada en vigor del presente decreto, deber\u00e1n garantizar el derecho a la ciudadan\u00eda a solicitar la revocaci\u00f3n de mandato de la persona presidenta municipal.<\/p>\n<p>Explica que la solicitud deber\u00e1 plantearse durante los tres meses posteriores al a\u00f1o y medio del inicio del per\u00edodo constitucional, por un n\u00famero equivalente al 3 por ciento de la ciudadan\u00eda inscrita en la lista nominal del municipio, y podr\u00e1 llevarse a cabo en una sola ocasi\u00f3n durante el per\u00edodo constitucional, mediante votaci\u00f3n libre, directa y secreta; ser\u00e1 vinculante cuando la participaci\u00f3n corresponda como m\u00ednimo a 40 por ciento de la lista y cuando la votaci\u00f3n sea por mayor\u00eda absoluta.<\/p>\n<p>Tambi\u00e9n, que la jornada se efectuar\u00e1 en fecha posterior y no coincidir\u00e1 con procesos electorales o de participaci\u00f3n ciudadana locales o federales; quien asuma el mandato de la presidencia revocada concluir\u00e1 el per\u00edodo constitucional.<\/p>\n<p>En su exposici\u00f3n de motivos, el legislador refiere que actualmente la Carta Magna se\u00f1ala en el art\u00edculo 115 que las legislaturas locales, por acuerdo de las dos terceras partes de sus integrantes, podr\u00e1n suspender ayuntamientos, declarar que \u00e9stos han desaparecido y suspender o revocar el mandato a alguno de sus miembros, por alguna de las causas graves que la ley local prevenga.<\/p>\n<p>Destaca que debe ser un ejercicio democr\u00e1tico, mediante el cual la poblaci\u00f3n del municipio decida si contin\u00faa con el mandato el titular del Ejecutivo local.<\/p>\n<p>Considere que la figura de la revocaci\u00f3n es un pilar fundamental en la democracia participativa, ya que permite a la ciudadan\u00eda ejercer un control real sobre sus gobernantes y exigir cuentas; adem\u00e1s, asegura que el poder emana del pueblo y que las personas servidoras p\u00fablicas se mantienen a la altura de las expectativas ciudadanas. Por ello se debe garantizar el derecho de la ciudadan\u00eda a iniciar procesos de revocaci\u00f3n, fomentar la participaci\u00f3n y en lugar de esperar los per\u00edodos electorales regulares, contar con una herramienta para evaluar y tomar medidas cuando est\u00e9 descontento con el desempe\u00f1o de sus autoridades locales, se\u00f1ala.<\/p>\n<p>Adem\u00e1s, se promueve la democracia participativa, donde el poder es un instrumento que atiende las necesidades de la sociedad, quien debe solicitar ese proceso, pues es la que resiente lo que la administraci\u00f3n hace o no para la comunidad. De esta forma se tendr\u00edan estad\u00edsticas m\u00e1s claras sobre el nivel de aprobaci\u00f3n social de este orden de gobierno en seguridad p\u00fablica, servicios, tr\u00e1mites, adecuaci\u00f3n e innovaci\u00f3n del espacio p\u00fablico, entre otros.<\/p>\n<p>Este mecanismo debe implementarse sin candidatos jur\u00eddicos o trabajos institucionales, y dar paso al respeto pleno de la demanda del electorado y el pueblo que no est\u00e1 satisfecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el prop\u00f3sito de establecer el derecho de la ciudadan\u00eda de los municipios a solicitar la revocaci\u00f3n de mandato del<\/p>\n","protected":false},"author":4,"featured_media":60428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[356],"tags":[],"class_list":["post-60427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/edi.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:28:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=60427"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/60428"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=60427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=60427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=60427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}