{"id":60417,"date":"2025-07-14T00:22:55","date_gmt":"2025-07-14T06:22:55","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=60417"},"modified":"2025-07-14T00:22:55","modified_gmt":"2025-07-14T06:22:55","slug":"el-lodazal-esta-en-tabasco-no-en-veracruz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/07\/14\/el-lodazal-esta-en-tabasco-no-en-veracruz\/","title":{"rendered":"\u201cEl lodazal est\u00e1 en Tabasco, no en Veracruz\u201d"},"content":{"rendered":"<p><em>\u201cSon de m\u00e1s valor la honradez y el talento, que la riqueza\u201d. \u2013 . John Dryden.<\/em><\/p>\n<p><strong>En pol\u00edtica, como en el ajedrez, cada jugada tiene un prop\u00f3sito. Nada es casual. La reciente \u201cdescubierta\u201d de una minirefiner\u00eda clandestina en Veracruz m\u00e1s que un hallazgo, parece un acto de prestidigitaci\u00f3n medi\u00e1tica para desviar la atenci\u00f3n de lo que realmente sacude a la opini\u00f3n p\u00fablica: el esc\u00e1ndalo may\u00fasculo que estremece al vecino estado de Tabasco.<\/strong><\/p>\n<p><strong>Ah\u00ed, la orden de aprehensi\u00f3n hecha p\u00fablica contra el exsecretario de Seguridad P\u00fablica, Hern\u00e1n Berm\u00fadez Requena, y de altos mandos como Ulises Pinto y Prada, presuntamente ligados al grupo delictivo conocido como \u201cLa Barredora\u201d, desenmascara una red criminal con tent\u00e1culos en las m\u00e1s altas esferas del poder.<\/strong><\/p>\n<p><strong>Fue el propio General de Brigada de Estado Mayor, Miguel \u00c1ngel L\u00f3pez Mart\u00ednez, quien se\u00f1al\u00f3 las conexiones de estos funcionarios con el crimen organizado, y los nexos apuntan directamente al exgobernador y hoy senador Ad\u00e1n Augusto L\u00f3pez Hern\u00e1ndez.<\/strong><\/p>\n<p><strong>La gravedad del asunto no es menor. Queda en evidencia una relaci\u00f3n de complicidad institucional con el crimen, que convierte a la seguridad p\u00fablica de Tabasco en una fachada para el encubrimiento. Pero mientras el esc\u00e1ndalo crece como espuma en el sur, en Veracruz se intenta fabricar una narrativa que distraiga, y a la vez da\u00f1e pol\u00edticamente a la mandataria Roc\u00edo Nahle Garc\u00eda.<\/strong><\/p>\n<p><strong>La operaci\u00f3n viene acompa\u00f1ada de otra burda maniobra: revivir una denuncia hecha por el general Eduardo Le\u00f3n Trauwitz \u2014hoy en proceso de extradici\u00f3n desde Canad\u00e1\u2014 quien intenta implicar a la hoy gobernadora y al equipo de transici\u00f3n de Andr\u00e9s Manuel L\u00f3pez Obrador en el incremento del robo de combustible en 2018.<\/strong><\/p>\n<p><strong>El argumento resulta no solo infundado, sino desesperado: el mismo militar fue acusado precisamente por encubrir y facilitar el huachicol desde las entra\u00f1as de Pemex.<\/strong><\/p>\n<p><strong>No sorprende que esta narrativa haya sido promovida por el viejo clan yunista en alianza con Manuel Huerta Ladr\u00f3n de Guevara, senador por Veracruz y eterno aspirante frustrado al poder estatal. Ambos, con la torpeza de quienes intentan vender chiles a Herdez, han querido enlodar la imagen de Nahle Garc\u00eda, sin lograrlo.<\/strong><\/p>\n<p><strong>La realidad se impone: mientras unos inventan distractores, otros enfrentan procesos judiciales reales y con pruebas contundentes.<\/strong><\/p>\n<p><strong>Porque en pol\u00edtica, como entre los perros, hay razas. Algunas leales, otras rabiosas. Y los que hoy ladran contra Roc\u00edo Nahle, solo delatan su desesperaci\u00f3n ante una figura que, guste o no, avanza firme y sin m\u00e1cula.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Al tiempo.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-60403 size-full\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3.jpg\" alt=\"\" width=\"1024\" height=\"125\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3.jpg 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3-300x37.jpg 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-3-768x94.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSon de m\u00e1s valor la honradez y el talento, que la riqueza\u201d. \u2013 . John Dryden. En pol\u00edtica, como en<\/p>\n","protected":false},"author":4,"featured_media":30989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-60417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/05\/LUIS-RAMIREZ-BAQUEIRO-800x445-1.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:31:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=60417"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/60417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/30989"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=60417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=60417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=60417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}