{"id":59785,"date":"2025-07-03T22:25:52","date_gmt":"2025-07-04T04:25:52","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=59785"},"modified":"2025-07-03T22:25:52","modified_gmt":"2025-07-04T04:25:52","slug":"la-nueva-ley-de-censura-2","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/07\/03\/la-nueva-ley-de-censura-2\/","title":{"rendered":"La Nueva Ley de Censura"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><strong>\u00bfUna Amenaza a la Libertad de Expresi\u00f3n?<\/strong><\/li>\n<li style=\"font-weight: 400;\"><strong>Cualquier cuenta podr\u00eda ser considerada \u00abpeligrosa\u201d<\/strong><\/li>\n<li style=\"font-weight: 400;\"><strong>El futuro de nuestra voz depende de nuestra capacidad para actuar en el presente<\/strong><\/li>\n<\/ul>\n<p style=\"font-weight: 400;\"><strong>Por Miguel \u00c1ngel Cristiani G.<\/strong><\/p>\n<p style=\"font-weight: 400;\">La aprobaci\u00f3n de la reforma por parte de los partidos Morena, PT y PVEM en la C\u00e1mara de Diputados ha encendido una alarma entre aquellos que valoran la libertad de expresi\u00f3n en M\u00e9xico. La creaci\u00f3n de la nueva Agencia de Transformaci\u00f3n Digital y Telecomunicaciones trae consigo facultades alarmantes, que permiten la intervenci\u00f3n en plataformas digitales sin necesidad de una orden judicial. \u00bfSuena ambiguo? Es porque lo es.<\/p>\n<p style=\"font-weight: 400;\">Esta reforma no solo afecta a los grandes medios de comunicaci\u00f3n; cualquier cuenta podr\u00eda ser considerada \u00abpeligrosa\u00bb si expresa opiniones inc\u00f3modas. La vaguedad de los t\u00e9rminos utilizados en esta ley abre la puerta a la censura. No hay criterios claros sobre qu\u00e9 constituye una amenaza a la \u201cseguridad nacional\u201d o al \u201cbienestar social\u201d. En este nuevo marco legal, el poder se concentra sin contrapesos reales, lo que genera un caldo de cultivo para el abuso.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00bfQui\u00e9nes Pueden Estar en la Mira?<\/strong><\/p>\n<p style=\"font-weight: 400;\">La lista de quienes podr\u00edan ser afectados es extensa y preocupante:<\/p>\n<ul>\n<li style=\"font-weight: 400;\"><strong>Periodismo independiente<\/strong>: Aquellos que buscan informar sin agenda pol\u00edtica.<\/li>\n<li style=\"font-weight: 400;\"><strong>Cuentas pol\u00edticas inc\u00f3modas<\/strong>: Usuarios que critican al sistema.<\/li>\n<li style=\"font-weight: 400;\"><strong>Defensores de ideolog\u00edas alternativas<\/strong>: Grupos que abogan por visiones no hegem\u00f3nicas sobre g\u00e9nero y identidad.<\/li>\n<li style=\"font-weight: 400;\"><strong>Canales alternativos<\/strong>: Desde los conservadores hasta los libertarios, cualquier voz que se atreva a cuestionar la narrativa oficial.<\/li>\n<li style=\"font-weight: 400;\"><strong>Comedia pol\u00edtica y s\u00e1tira<\/strong>: Espacios que, a trav\u00e9s del humor, critican a la autoridad.<\/li>\n<li style=\"font-weight: 400;\"><strong>Gente com\u00fan<\/strong>: Aquellos que simplemente expresan verdades que podr\u00edan incomodar a los poderosos.<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">Para muchos, la mentalidad \u00absi no haces nada malo, no te pasa nada\u00bb puede parecer un refugio seguro. Pero, \u00bfrealmente entendemos las implicaciones de esta postura? La historia est\u00e1 llena de ejemplos en los que el poder ha silenciado voces disidentes. Alguna vez, todos hemos estado a favor de un partido o hemos criticado al gobierno. La diferencia radica en el momento en que decidimos alzar la voz. En ese instante, podr\u00edamos descubrir que ya no tenemos la libertad de hacerlo.<\/p>\n<p style=\"font-weight: 400;\">La verdadera peligrosidad de esta ley no radica solo en la censura expl\u00edcita, sino en la autocensura que puede surgir de ella. El miedo a incomodar a quien tiene el poder puede llevar a muchos a callar, a reprimir sus opiniones y a conformarse con la narrativa dominante. As\u00ed, la libertad de expresi\u00f3n se transforma en una ilusi\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">Este no es un llamado a la paranoia, sino a la reflexi\u00f3n. La aprobaci\u00f3n de esta reforma es un hecho y estamos ante un nuevo terreno legal. Es fundamental que la ciudadan\u00eda est\u00e9 consciente de las implicaciones que esto conlleva. La falta de claridad en los criterios de intervenci\u00f3n y la ausencia de contrapesos son motivos suficientes para estar en alerta.<\/p>\n<p style=\"font-weight: 400;\">La libertad de expresi\u00f3n no debe ser un privilegio reservado para unos pocos. Debe ser un derecho garantizado para todos, independientemente de su opini\u00f3n pol\u00edtica o ideol\u00f3gica. La lucha por este derecho es, en esencia, una lucha por la democracia misma.<\/p>\n<p style=\"font-weight: 400;\">La nueva Agencia de Transformaci\u00f3n Digital y Telecomunicaciones representa un cambio significativo en el panorama pol\u00edtico y social de M\u00e9xico. Es crucial que los ciudadanos se mantengan informados y participen activamente en la defensa de sus derechos.<\/p>\n<p style=\"font-weight: 400;\">La libertad de expresi\u00f3n es un pilar fundamental en cualquier sociedad democr\u00e1tica. No permitamos que se erosione bajo la sombra del miedo y la censura. El futuro de nuestra voz depende de nuestra capacidad para actuar en el presente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-59702 size-full\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD.jpg\" alt=\"\" width=\"1024\" height=\"125\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD.jpg 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-300x37.jpg 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/07\/FIRMA-EDITORIAL-PD-768x94.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfUna Amenaza a la Libertad de Expresi\u00f3n? Cualquier cuenta podr\u00eda ser considerada \u00abpeligrosa\u201d El futuro de nuestra voz depende de<\/p>\n","protected":false},"author":4,"featured_media":29037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-59785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/04\/BANNER-cristiani-NV.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:28:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/59785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=59785"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/59785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/29037"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=59785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=59785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=59785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}