{"id":55935,"date":"2025-05-05T00:09:06","date_gmt":"2025-05-05T06:09:06","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=55935"},"modified":"2025-05-05T00:09:06","modified_gmt":"2025-05-05T06:09:06","slug":"conclave-la-realidad-que-parece-ficcion","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/05\/05\/conclave-la-realidad-que-parece-ficcion\/","title":{"rendered":"C\u00f3nclave, la realidad que parece ficci\u00f3n"},"content":{"rendered":"<p>Sin importar cu\u00e1l sea nuestra creencia religiosa es innegable que la figura del Papa, principal dirigente de la iglesia cat\u00f3lica, tiene un gran impacto en el mundo, sus declaraciones y posturas tambi\u00e9n afectan el actuar de sus m\u00e1s de 1390 millones de fieles. De ah\u00ed que tambi\u00e9n figuras emblem\u00e1ticas y l\u00edderes de estado constantemente buscaran los encuentros con el Papa.<\/p>\n<p>Con la llegada de Jorge Mario Bergoglio al papado hubo una gran serie de reformas en la iglesia, tanto al interior como al exterior del Vaticano. No es casualidad que el papa haya sido latinoamericano ni que perteneciera a la que es considerada una de las \u00f3rdenes rebeldes de la iglesia cat\u00f3lica: Los jesuitas. Ahora con su muerte, el pr\u00f3ximo 7 de mayo tendr\u00e1 lugar un nuevo c\u00f3nclave, el espacio donde a puertas cerradas se da la votaci\u00f3n para elegir al pr\u00f3ximo Papa.<\/p>\n<p>Es importante prestar atenci\u00f3n a este suceso pues m\u00e1s all\u00e1 de la iglesia cat\u00f3lica, se trata tambi\u00e9n de un l\u00edder mundial que puede influir en las posturas que se tengan respecto a un actuar humano o por el contrario encubrir todo tipo de delitos como ocurri\u00f3 con antiguos l\u00edderes de la iglesia. Durante el tiempo de gesti\u00f3n del Papa Francisco se presentaron declaraciones disruptivas que m\u00e1s all\u00e1 de pensar en fieles de la iglesia, se enfocaba en seres humanos, se dejaron de lado los lujos con los que anta\u00f1o se manejaron otros Papas y constantemente se invitaba a las personas a actuar desde el amor.<\/p>\n<p>La orden a la que pertenec\u00eda el Papa Francisco es as\u00ed. Los Jesuitas han sido reconocidos en la historia por su proceso de preparaci\u00f3n y defensa de vidas humanas, no buscan lujos, hacen votos de pobreza y toman como ejemplo de vida a Jesucristo, considerando sus vivencias y entrega hacia los dem\u00e1s, de ah\u00ed que parte de sus lemas sea \u201c<em>ser para los dem\u00e1s\u201d<\/em>, aunque tambi\u00e9n han sido expulsados y perseguidos, ha sido la orden que m\u00e1s impuls\u00f3 la educaci\u00f3n y la liberaci\u00f3n de personas ind\u00edgenas, en Latinoam\u00e9rica fueron precursores de movimientos como la independencia y actualmente defienden m\u00faltiples proyectos de protecci\u00f3n y desarrollo de migrantes.<\/p>\n<p>Bajo estos puntos donde se tuvo un Papa disruptivo, ahora toca elegir al sucesor, previo a esta noticia en cines se hab\u00eda estrenado un filme que llevaba por t\u00edtulo <em>\u201cC\u00f3nclave\u201d<\/em> esta pel\u00edcula hablaba de manera sutil sobre esc\u00e1ndalos del vaticano, las reuniones previas para la sucesi\u00f3n y el papel que tiene la iglesia en un mundo en constante cambio, donde las declaraciones emitidas por su l\u00edder pueden seguir dividiendo a la humanidad o marcar la diferencia donde sin importar la religi\u00f3n se invite al respeto y la colaboraci\u00f3n comunitaria.<\/p>\n<p>En la pel\u00edcula tambi\u00e9n se ve\u00eda c\u00f3mo algunos cardenales deb\u00edan renunciar al puesto por las acusaciones de abusos, robos y gastos excesivos entre otros. Ahora a unos d\u00edas de comenzar el c\u00f3nclave real pareciera que estamos inmersos de nueva cuenta en una producci\u00f3n cinematogr\u00e1fica, no hay sucesores claramente definidos, hay cardenales que han tenido que renunciar a la posibilidad de ser elegidos y el resultado final sin duda es de gran inter\u00e9s para todo el mundo.<\/p>\n<p>El pr\u00f3ximo mi\u00e9rcoles 7 de mayo, entrar\u00e1n en la Capilla Sixtina 133 cardenales provenientes de 71 pa\u00edses, la elecci\u00f3n es dif\u00edcil pues muchos de ellos son desconocidos entre s\u00ed, no hay un nombre que resuene con fuerza contrario a los dos c\u00f3nclaves anteriores donde era sencillo estar a favor o en contra de propuestas m\u00e1s claras, en este caso se dividen los progresistas y conservadores pero el panorama se percibe confuso.<\/p>\n<p>Actualmente suenan como posibles papables 8 nombres, a la cabeza quiz\u00e1s est\u00e1 Pietro Parolin, actual Secretario de Estado de la Santa Sede, sin embargo, como se requiere una mayor\u00eda, es posible que, si para el 8 de mayo el humo de la Capilla Sixtina a\u00fan es negro, entonces comiencen las sorpresas. De momento como sociedad seguiremos atentos, pues el futuro de la iglesia cat\u00f3lica tambi\u00e9n influye en el orden mundial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-55927 size-full\" src=\"http:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/05\/FIRMA-EDITORIAL-PD-2.jpg\" alt=\"\" width=\"1024\" height=\"125\" srcset=\"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/05\/FIRMA-EDITORIAL-PD-2.jpg 1024w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/05\/FIRMA-EDITORIAL-PD-2-300x37.jpg 300w, https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/05\/FIRMA-EDITORIAL-PD-2-768x94.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin importar cu\u00e1l sea nuestra creencia religiosa es innegable que la figura del Papa, principal dirigente de la iglesia cat\u00f3lica, tiene un gran impacto en el mundo, sus declaraciones y posturas tambi\u00e9n afectan el actuar de sus m\u00e1s de 1390 millones de fieles. De ah\u00ed que tambi\u00e9n figuras emblem\u00e1ticas y l\u00edderes de estado constantemente buscaran [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":42443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-55935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-08 19:42:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/10\/NV-ZAIRA-ROSAS.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/55935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=55935"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/55935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/42443"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=55935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=55935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=55935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}