{"id":52477,"date":"2025-03-17T00:17:05","date_gmt":"2025-03-17T06:17:05","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=52477"},"modified":"2025-03-16T21:17:54","modified_gmt":"2025-03-17T03:17:54","slug":"acusa-venezuela-a-eu-de-criminalizar-a-migrantes-con-antigua-ley","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/03\/17\/acusa-venezuela-a-eu-de-criminalizar-a-migrantes-con-antigua-ley\/","title":{"rendered":"Acusa Venezuela a EU de criminalizar a migrantes con antigua ley"},"content":{"rendered":"<p class=\"nota-justify\">El gobierno de Venezuela consider\u00f3 este domingo que el gobierno de Donald Trump \u00abcriminaliza\u00bb a migrantes venezolanos al invocar una antigua ley para deportar a presuntos miembros de la banda\u00a0<i>Tren de Aragua<\/i>.<\/p>\n<p class=\"nota-justify\">Trump invoc\u00f3 la Ley de Enemigos Extranjeros, que data de 1798, que permite arrestar y deportar a ciudadanos de una naci\u00f3n enemiga. Hab\u00eda sido utilizada por \u00faltima vez durante la Segunda Guerra Mundial para detener a unos 120 mil japoneses y estadunidenses de origen japon\u00e9s.<\/p>\n<p class=\"nota-justify\">\u00abVenezuela rechaza de manera categ\u00f3rica y contundente la proclama del gobierno de Estados Unidos que criminaliza de forma infame e injusta a la migraci\u00f3n venezolana\u00bb, reza un comunicado oficial.<\/p>\n<p class=\"nota-justify\">El texto calific\u00f3 de \u00abanacr\u00f3nica\u00bb la vieja ley invocada por Trump.<\/p>\n<p class=\"nota-justify\">\u00abNo solo violenta leyes fundamentales y vigentes de los Estados Unidos, sino que vulnera el ordenamiento jur\u00eddico internacional en materia de derechos humanos\u00bb, denuncia. \u00abEn su inmensa mayor\u00eda, los migrantes son mujeres y hombres trabajadores, dignos y honestos, no son terroristas, no son criminales, ni &#8216;enemigos extranjeros&#8217;. Son v\u00edctimas\u00bb, continu\u00f3.<\/p>\n<p class=\"nota-justify\">M\u00e1s de 7.5 millones de venezolanos han dejado su pa\u00eds desde 2014 ante una asfixiante crisis econ\u00f3mica, seg\u00fan la Organizaci\u00f3n de Naciones Unidas.<\/p>\n<p class=\"nota-justify\">El gobierno de Maduro, que niega que la cifra de migrantes sea tan alta, culpa por el \u00e9xodo a las sanciones que Washington ha impuesto a Venezuela en su presi\u00f3n contra el presidente izquierdista Nicol\u00e1s Maduro, cuya reelecci\u00f3n es denunciada como un fraude por la oposici\u00f3n y varios gobiernos latinoamericanos.<\/p>\n<p class=\"nota-justify\">La orden de Trump para deportaciones amparadas en esta ley fue bloqueada el s\u00e1bado por una decisi\u00f3n judicial: el juez James Boasberg orden\u00f3 una suspensi\u00f3n de 14 d\u00edas de cualquier expulsi\u00f3n bajo esa proclama.<\/p>\n<p class=\"nota-justify\">La Casa Blanca tiene hasta este lunes para presentar una moci\u00f3n si quiere anular la pausa. La pr\u00f3xima audiencia ser\u00e1 el 21 de marzo, seg\u00fan la resoluci\u00f3n judicial.<\/p>\n<p class=\"nota-justify\">Pero ya El Salvador recibi\u00f3 este domingo a 238 presuntos miembros del Tren de Aragua enviados por Estados Unidos para ser recluidos en una prisi\u00f3n de m\u00e1xima seguridad, anunci\u00f3 el presidente salvadore\u00f1o, Nayib Bukele, en la red social X.<\/p>\n<p class=\"nota-justify\">La banda criminal, que naci\u00f3 en Venezuela y extendi\u00f3 sus tent\u00e1culos por Estados Unidos y varios pa\u00edses de Am\u00e9rica Latina, fue designada como organizaci\u00f3n terrorista por Washington.<\/p>\n<p class=\"nota-justify\">Venezuela y Estados Unidos acordaron reanudar los vuelos de deportados, suspendidos cuando Washington revoc\u00f3 la licencia que permit\u00eda a Chevron operar en el pa\u00eds caribe\u00f1o pese a las sanciones petroleras. Los dos pa\u00edses, que rompieron relaciones en 2019, hab\u00edan concretado la repatriaci\u00f3n de m\u00e1s de 600 venezolanos tras una reuni\u00f3n en Caracas entre Maduro y un enviado de Trump.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Venezuela consider\u00f3 este domingo que el gobierno de Donald Trump \u00abcriminaliza\u00bb a migrantes venezolanos al invocar una<\/p>\n","protected":false},"author":4,"featured_media":52478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-52477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/03\/VEN.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 10:14:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/52477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=52477"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/52477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/52478"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=52477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=52477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=52477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}