{"id":52474,"date":"2025-03-17T00:16:17","date_gmt":"2025-03-17T06:16:17","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=52474"},"modified":"2025-03-16T21:15:26","modified_gmt":"2025-03-17T03:15:26","slug":"marchan-miles-contra-tarifas-de-luz-en-sonora","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/03\/17\/marchan-miles-contra-tarifas-de-luz-en-sonora\/","title":{"rendered":"Marchan miles contra tarifas de luz en Sonora"},"content":{"rendered":"<p>Indignados por los altos costos de los servicios b\u00e1sicos, unas cinco mil personas se manifestaron frente a las oficinas de la Comisi\u00f3n Federal de Electricidad (CFE) en Hermosillo, convocados por la Uni\u00f3n de Usuarios de Hermosillo (UUH), para exigir tarifas justas en electricidad y agua, as\u00ed como soluciones en el transporte p\u00fablico y acceso a vivienda.<\/p>\n<p>La protesta, encabezada por Ignacio Peinado Luna, l\u00edder de la UUH, tuvo lugar en la calle Matamoros, donde denunciaron su inconformidad ante los cobros excesivos en sus recibos y la incertidumbre del subsidio el\u00e9ctrico para el verano de 2025.<\/p>\n<p>Miles de familias coincidieron en que enfrentan facturas impagables, debido a que en invierno padecen bajas temperaturas y en verano, calor extremo.<\/p>\n<p>Ante ello, los hermosillenses demandan que se eleven a rango constitucional la energ\u00eda el\u00e9ctrica como derecho humano, pues es una demanda que no se ha cumplido desde hace a\u00f1os.<\/p>\n<p>Actualmente, la tarifa invernal solo permite un consumo de 400 kilowatts-hora bimestrales antes de aplicar un cobro elevado de 3.76 pesos por kilowatt adicional, por ello para evitar estos cobros desproporcionados, la UUH propone aumentar el subsidio invernal a mil 200 kilowatts bimestrales, medida que ser\u00e1 gestionada ante el Congreso de la Uni\u00f3n.<\/p>\n<p>\u201cNo queremos que el pr\u00f3ximo verano nos tomen desprevenidos sin un convenio firmado para el subsidio el\u00e9ctrico. Si no hay soluciones, regresaremos a las calles como lo hicimos el a\u00f1o pasado\u201d, advirti\u00f3 Peinado Luna.<\/p>\n<p>La vecina Virginia Ramos se\u00f1al\u00f3 que es tiempo de que senadores y legisladores federales piensen en los ciudadanos y aprueben modificar el sistema tarifario para que todos tengan ese beneficio.<\/p>\n<p>La organizaci\u00f3n tambi\u00e9n exigi\u00f3 que la dependencia municipal Agua de Hermosillo\u00a0ajuste sus tarifas a usuarios sin medidor y que la instalaci\u00f3n de equipos no sea un costo adicional para las familias.<\/p>\n<p>Explic\u00f3 que a diario acuden al menos 50 usuarios con peticiones de modificaci\u00f3n por cobros excesivos en su consumo de agua, pero hay que tomar en cuenta que no es un servicio regular y que Hermosillo ocupa el tercer lugar nacional en fugas de agua potable.<\/p>\n<p>Adem\u00e1s, denunciaron un aumento del cien por ciento en el primer bimestre de este 2025, luego de que en el Congreso Local les negara el incremento del l\u00edquido en el pasado presupuesto de ingresos presentado por el Ayuntamiento capitalino.<\/p>\n<p>Los afectados acusaron que la escasez del recurso afecta a distintas colonias de Hermosillo, y obliga a los residentes a modificar sus h\u00e1bitos diarios y da\u00f1a su calidad de vida. La incertidumbre por no saber a qu\u00e9 hora contar\u00e1n con el servicio ha llevado a los vecinos a organizarse y protestar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Indignados por los altos costos de los servicios b\u00e1sicos, unas cinco mil personas se manifestaron frente a las oficinas de<\/p>\n","protected":false},"author":4,"featured_media":52475,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[],"class_list":["post-52474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/03\/GmIy_a6a0AADz56.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:44:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/52474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=52474"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/52474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/52475"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=52474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=52474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=52474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}