{"id":47079,"date":"2025-01-03T00:31:38","date_gmt":"2025-01-03T06:31:38","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=47079"},"modified":"2025-01-03T00:31:38","modified_gmt":"2025-01-03T06:31:38","slug":"flujo-de-remesas-no-ha-sido-afectado-por-victoria-de-trump-bbva","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/01\/03\/flujo-de-remesas-no-ha-sido-afectado-por-victoria-de-trump-bbva\/","title":{"rendered":"Flujo de remesas no ha sido afectado por victoria de Trump: BBVA"},"content":{"rendered":"<p>El flujo de remesas que los connacionales que radican en Estados Unidos env\u00edan a sus familias\u00a0\u00a0en M\u00e9xico no se ha visto afectado luego de que Donald Trump resultara electo presidente del pa\u00eds vecino, afirm\u00f3 BBVA M\u00e9xico.<\/p>\n<p>Las subidas y bajadas que han tenido las remesas a lo largo de 2024, plante\u00f3 el banco, son resultado de diversos factores, como la depreciaci\u00f3n o apreciaci\u00f3n del peso con respecto al d\u00f3lar o la incertidumbre que se vive por una posible desaceleraci\u00f3n de la actividad tanto en M\u00e9xico como en Estados Unidos este a\u00f1o.<\/p>\n<p>Esta ma\u00f1ana, el Banco de M\u00e9xico (BdeM) dio a conocer que en noviembre de 2024, los ingresos por remesas provenientes del exterior fueron por\u00a0cinco mil 435 millones de d\u00f3lares, lo que represent\u00f3 una expansi\u00f3n anual de 10.6 por ciento.<\/p>\n<p>En este sentido, BBVA precis\u00f3 que de enero a noviembre, las remesas a M\u00e9xico han mostrado un comportamiento muy vol\u00e1til, con importantes aumentos en su flujo en los meses de abril, junio, agosto y noviembre, y con ca\u00eddas en marzo, mayo, julio, septiembre y octubre.<\/p>\n<p>\u201cEstas fluctuaciones se explican, en parte, por factores coyunturales como las fuertes variaciones en el tipo de cambio del peso mexicano frente al d\u00f3lar estadounidense, y por factores estructurales como los ajustes en el mercado laboral estadounidense en 2024 relacionados con los signos de una posible desaceleraci\u00f3n de su econom\u00eda en 2025.<\/p>\n<p>\u201cLo anterior podr\u00eda conllevar a una menor absorci\u00f3n de la mano de obra migrante en la uni\u00f3n americana\u201d, precis\u00f3 BBVA.<\/p>\n<p>Sin embargo, detall\u00f3 que a diferencia de lo ocurrido hace 8 a\u00f1os, cuando Donald Trump result\u00f3 electo presidente de Estados Unidos y el flujo de remesas se increment\u00f3 considerablemente por el temor a las deportaciones masivas, ahora eso no ha ocurrido.<\/p>\n<p>\u201cHace 8 a\u00f1os, en noviembre de 2016, cuando el presidente Trump gan\u00f3 las elecciones presidenciales en su primer t\u00e9rmino de gobierno, las remesas tuvieron un s\u00fabito incremento de 25.8 por ciento debido a las amenazas del endurecimiento en la frontera, de deportaciones masivas y por un posible impuesto a las remesas\u201d, detall\u00f3 BBVA.<\/p>\n<p>En noviembre de 2016, record\u00f3, el peso mexicano se depreci\u00f3 5.2 por ciento frente al d\u00f3lar estadounidense, debido, en parte, por los posibles riesgos de la negociaci\u00f3n del entonces Tratado de Libre Comercio de Am\u00e9rica del Norte (TLCAN).<\/p>\n<p>Ahora, en noviembre de 2024, con la victoria electoral del presidente Trump para un segundo t\u00e9rmino de gobierno, el peso mexicano tuvo una depreciaci\u00f3n mensual de 3.3 por ciento frente al d\u00f3lar estadounidense, la cual podr\u00eda considerarse como una fluctuaci\u00f3n dentro de los rangos del mercado.<\/p>\n<p>\u201cAs\u00ed, a diferencia de lo ocurrido hace 8 a\u00f1os, no se tiene evidencia clara de que el efecto Trump tenga efectos en las remesas a M\u00e9xico\u201d, agreg\u00f3 BBVA.<\/p>\n<p>La \u00faltima estimaci\u00f3n presentada por ese banco a este medio es que, al concluir 2024, el flujo de remesas que lleguen a M\u00e9xico sea por 66 mil millones de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El flujo de remesas que los connacionales que radican en Estados Unidos env\u00edan a sus familias\u00a0\u00a0en M\u00e9xico no se ha visto afectado luego de que Donald Trump resultara electo presidente del pa\u00eds vecino, afirm\u00f3 BBVA M\u00e9xico. Las subidas y bajadas que han tenido las remesas a lo largo de 2024, plante\u00f3 el banco, son resultado [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-47079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:49:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/01\/AA1wSetF.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=47079"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/47080"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=47079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=47079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=47079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}