{"id":47033,"date":"2025-01-02T00:47:27","date_gmt":"2025-01-02T06:47:27","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=47033"},"modified":"2025-01-02T00:47:27","modified_gmt":"2025-01-02T06:47:27","slug":"conmociona-a-ecuador-muerte-de-cuatro-menores-tras-detencion-por-soldados","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/01\/02\/conmociona-a-ecuador-muerte-de-cuatro-menores-tras-detencion-por-soldados\/","title":{"rendered":"Conmociona a Ecuador muerte de cuatro menores tras detenci\u00f3n por soldados"},"content":{"rendered":"<p>Un examen antropol\u00f3gico y de ADN identific\u00f3, el \u00faltimo d\u00eda del a\u00f1o 2024, los cuerpos calcinados de los cuatro chicos detenidos por una patrulla militar el pasado 8 de diciembre, luego de lo cual fueron torturados, asesinados, los habr\u00edan rociado de gasolina y prendido fuego para despu\u00e9s lanzarlos al r\u00edo Taura, a 16 kil\u00f3metros del lugar de su aprehensi\u00f3n, en la ciudad de Guayaquil.<\/p>\n<p>La noticia conmocion\u00f3 a todo el pa\u00eds porque ese d\u00eda precisamente un juez orden\u00f3 la prisi\u00f3n preventiva de los 16 militares de esa patrulla bajo la acusaci\u00f3n de desaparici\u00f3n forzosa. Ahora el delito por el que se los procesar\u00e1 penalmente ser\u00eda el de ejecuci\u00f3n extrajudicial.<\/p>\n<p>As\u00ed, en vez de los consabidos deseos de un buen a\u00f1o 2025 un sinn\u00famero de personalidades, dirigentes sociales, pol\u00edticos y de defensa de los Derechos Humanos se sumaron a la corriente de dolor e indignaci\u00f3n que cop\u00f3 las redes sociales y algunos medios de comunicaci\u00f3n, inculpando directamente al gobierno de Daniel Noboa, pues d\u00edas atr\u00e1s el mandatario ecuatoriano ya los hab\u00eda declarado \u201ch\u00e9roes nacionales\u201d, \u201cporque ya sab\u00eda que estaban muertos tras la tortura, dijo Antonio, t\u00edo de Josu\u00e9 e Ismael Arroyo.<\/p>\n<p>Tras una intensa expectativa, Dennis Ugalde \u00c1lvarez, juez de la Ni\u00f1ez y la Familia, dict\u00f3 prisi\u00f3n preventiva la ma\u00f1ana del 31 de diciembre de 2024 para los 16 militares procesados, en principio, por el delito de desaparici\u00f3n forzada en el caso conocido como Malvinas.<\/p>\n<p>Ahora vendr\u00e1n algunas diligencias como, por ejemplo, la reconstrucci\u00f3n de los hechos. Adem\u00e1s, los 16 uniformados ya fueron trasladados a recintos penitenciarios diferenciados. Ese mismo d\u00eda se dictaron medidas de protecci\u00f3n para los familiares de los ni\u00f1os, incluyendo botones de auxilio, entrevistas psicol\u00f3gicas y otras acciones reparativas.<\/p>\n<p>En la audiencia, el fiscal del caso se\u00f1al\u00f3 que los menores no estaban involucrados en ning\u00fan acto delictivo, refutando la versi\u00f3n del ministro de Defensa Giancarlo Lofredo y los mandos militares de las Fuerzas Armadas del Ecuador. Incluso, el ministerio de Defensa deber\u00e1 pedir diculpas p\u00fablicas por lo acontecido, en nombre del Estado ecuatoriano.<\/p>\n<p>El delito con el que se llam\u00f3 a la audiencia de formulaci\u00f3n de cargos fue de desaparici\u00f3n forzada que tiene una pena que oscila entre 22 y 26 a\u00f1os de prisi\u00f3n. Sin embargo, tras la identificaci\u00f3n de los restos incinerados la figura del delito cambiar\u00e1 a ejecuci\u00f3n extrajudicial que conlleva una pena de hasta 34 a\u00f1os de privaci\u00f3n de la libertad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un examen antropol\u00f3gico y de ADN identific\u00f3, el \u00faltimo d\u00eda del a\u00f1o 2024, los cuerpos calcinados de los cuatro chicos detenidos por una patrulla militar el pasado 8 de diciembre, luego de lo cual fueron torturados, asesinados, los habr\u00edan rociado de gasolina y prendido fuego para despu\u00e9s lanzarlos al r\u00edo Taura, a 16 kil\u00f3metros del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-47033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-08 20:03:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/01\/f2e9b710-c8ba-11ef-87df-d575b9a434a4.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=47033"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/47034"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=47033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=47033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=47033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}