{"id":47024,"date":"2025-01-02T00:42:19","date_gmt":"2025-01-02T06:42:19","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=47024"},"modified":"2025-01-02T00:42:19","modified_gmt":"2025-01-02T06:42:19","slug":"bolivia-va-a-elecciones-sin-opciones-claras-en-el-oficialismo","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2025\/01\/02\/bolivia-va-a-elecciones-sin-opciones-claras-en-el-oficialismo\/","title":{"rendered":"Bolivia va a elecciones sin opciones claras en el oficialismo"},"content":{"rendered":"<p>\u201cNi Lucho (Arce), ni Evo (Morales), los dos son lo mismo\u201d, se le\u00eda en una pancarta que el viento arranc\u00f3 a una manifestante de la mano durante una masiva protesta contra el desabasto de alimentos y combustibles en las ca\u00f3ticas calles de La Paz.<\/p>\n<p>Los bolivianos se encaminan a los comicios presidenciales \u2014que tendr\u00e1n lugar en nueve meses\u2014 en medio de un clima de incertidumbre marcado por la peor crisis econ\u00f3mica en 40 a\u00f1os, con el partido de gobierno fracturado tras 18 a\u00f1os en el poder y una oposici\u00f3n de centro y derecha dividida, sin una figura que emerja como alternativa.<\/p>\n<p>El Movimiento al Socialismo (MAS) est\u00e1 en \u201cfase terminal\u201d, seg\u00fan analistas, lo que podr\u00eda llevar a un ciclo pol\u00edtico turbulento. La fuerza gobernante est\u00e1 dividida entre el ex presidente Morales (2006-2019) y el actual mandatario Arce.<\/p>\n<p>Morales anticip\u00f3 que buscar\u00e1 un nuevo mandato pese a que est\u00e1 impedido de postularse por un fallo del Tribunal Constitucional y su imagen ha quedado golpeada por una acusaci\u00f3n fiscal por el presunto abuso de una menor cuando era presidente. La fiscal\u00eda ha pedido su detenci\u00f3n preventiva tras negarse a concurrir a una citaci\u00f3n para declarar. Quien fuera el primer mandatario ind\u00edgena de Bolivia se ha recluido en su feudo cocalero del Chapare, en el centro del pa\u00eds, desde donde organiza protestas contra el gobierno de Arce, su otrora aliado y ahora mayor enemigo pol\u00edtico.<\/p>\n<p>\u201cMorales no tiene el apoyo de antes, su figura polariza al pa\u00eds, pero ser\u00e1 influyente en las pr\u00f3ximas elecciones con el MAS o con otra sigla\u00bb, dijo a The Associated Press Carlos Cordero, analista y profesor de ciencia pol\u00edtica en la principal universidad estatal de La Paz. \u00abSi es invalidada su postulaci\u00f3n, podr\u00eda desarrollar una actitud de bloqueo a las elecciones o buscar entorpecerlas\u201d.<\/p>\n<p>El ex mandatario, de 65 a\u00f1os, ha culpado a Arce de urdir un plan judicial para sacarlo de la carrera electoral y sus bases, sobre todo de cocaleros \u2014sector desde el que Morales salt\u00f3 a la pol\u00edtica\u2014 est\u00e1n decididas a defenderlo. En tanto, el \u00f3rgano electoral que aprueba la lista de candidatos anticip\u00f3 que har\u00e1 respetar el fallo constitucional que le impide volver a postularse por haber ejercido dos mandatos consecutivos.<\/p>\n<p>Arce, en tanto, no ha confirmado aun si ser\u00e1 candidato pero sus posibilidades dependen de su capacidad para sacar al pa\u00eds andino de la crisis econ\u00f3mica, que no parece tener una soluci\u00f3n inmediata.<\/p>\n<p>Bolivia se ha quedado casi sin reservas en d\u00f3lares para importar combustibles, la subvenci\u00f3n a la gasolina y el di\u00e9sel est\u00e1 desangrando a la econom\u00eda y la moneda nacional se deval\u00faa r\u00e1pidamente.<\/p>\n<p>La inflaci\u00f3n acumulada entre enero y noviembre cerr\u00f3 en 8.82% %, la m\u00e1s alta en 16 a\u00f1os, seg\u00fan el estatal Instituto Nacional de Estad\u00edstica y la escasez de carburantes retrasa la cosecha de granos, lo que podr\u00eda afectar la seguridad alimentaria en los pr\u00f3ximos meses, advirtieron los agroindustriales.<\/p>\n<p>Es la peor crisis econ\u00f3mica en 40 a\u00f1os, dijo Gonzalo Ch\u00e1vez, profesor de econom\u00eda de la Universidad Cat\u00f3lica Boliviana. \u201cLa econom\u00eda est\u00e1 en coma y requiere una transfusi\u00f3n de sangre financiera, se requieren ajustes, pero el gobierno sigue apostando al gasto y al endeudamiento para pasar el d\u00eda a d\u00eda. Adem\u00e1s, el pa\u00eds necesita estabilidad pol\u00edtica\u201d, se\u00f1al\u00f3 el experto.<\/p>\n<p>\u201cTodo est\u00e1 m\u00e1s caro, hay crisis y los que m\u00e1s sufrimos somos los pobres\u00bb, dijo a la Ap Mar\u00eda Quispe, una vendedora callejera de La Paz de 26 a\u00f1os y madre de dos peque\u00f1os. \u201cYo vendo papa pero a los productores tampoco les ha ido bien\u201d.<\/p>\n<p>Asegur\u00f3 que antes ganaba 100 pesos bolivianos (14 d\u00f3lares al cambio oficial, 9 d\u00f3lares en el mercado negro) por d\u00eda, y ahora entre 20 y 30 (3.5 d\u00f3lares oficial, 2.2 en el mercado negro).<\/p>\n<p>Una reciente encuesta encargada por un reconocido empresario revel\u00f3 que todos los que se perfilan como eventuales candidatos tienen un mayor \u00edndice negativo que positivo, incluido Morales que encabeza el sondeo con 18% de intenci\u00f3n de voto. El mismo porcentaje tiene el alcalde de derecha de Cochabamba, la tercera ciudad del pa\u00eds, Manfred Reyes Villa, mientras el empresario de centroderecha Samuel Doria Medina aparece con 16%. Los tres ya se han declarado en carrera, pero hay otros que han anticipado su participaci\u00f3n y que no fueron medidos en el estudio.<\/p>\n<p>El presidente Arce, de 61 a\u00f1os, apenas alcanza un 4% de intenci\u00f3n de voto.<\/p>\n<p>Morales alcanz\u00f3 su techo mientras que Reyes Villa y Doria Medina tienen chances de subir, agreg\u00f3 el sondeo encargado por el empresario Marcelo Claure a la firma Panterra Research, que particip\u00f3 en las mediciones preelectorales en Venezuela. La empresa consult\u00f3 a 2 mil personas a principios de noviembre y el estudio posee un margen de error de dos puntos porcentuales. Por ahora no se conocen otras encuestas independientes.<\/p>\n<p>Doria Medina y los ex presidentes Jorge Quiroga (2001-2002) y Carlos Mesa (2003-2005) han firmado un pacto de unidad con el compromiso de presentar un solo candidato capaz de derrotar al MAS en las urnas.<\/p>\n<p>Si ning\u00fan postulante obtiene una mayor\u00eda clara en las urnas el pr\u00f3ximo gobierno no tendr\u00e1 la musculatura para encarar las reformas de fondo que necesita la econom\u00eda, indic\u00f3 la exdiputada Jimena Costa.<\/p>\n<p>\u201cVamos camino de Venezuela, necesitamos un (Javier) Milei (presidente de Argentina)\u00bb, dijo Eusebio Poma, un malhumorado transportista que esper\u00f3 m\u00e1s de ocho horas para cargar di\u00e9sel a su cami\u00f3n, en el que carga materiales de construcci\u00f3n.<\/p>\n<p>El surgimiento de una figura nueva que no provenga de la pol\u00edtica podr\u00eda cambiar el tablero ante el hast\u00edo de la gente, seg\u00fan expertos. Pero por ahora no ha aparecido nadie con ese perfil.<\/p>\n<p>Arce culpa a Morales por la crisis por haber descuidado las inversiones energ\u00e9ticas luego de la nacionalizaci\u00f3n del sector en 2006, cuando el precio del gas \u2014el otrora principal producto de exportaci\u00f3n de Bolivia\u2014 estaba en auge. Ahora Bolivia gasta aproximadamente 56 millones de d\u00f3lares a la semana para importar gasolina y di\u00e9sel de Argentina, Paraguay y Rusia.<\/p>\n<p>Morales, por su parte, dice que el actual mandatario es el responsable de \u201chundir la econom\u00eda\u201d y los opositores se\u00f1alan a ambos de \u201cllevar al pa\u00eds a la quiebra con un modelo (estatista) fracasado\u201d, dijo el expresidente Quiroga.<\/p>\n<p>Mar\u00eda Aduviri, quien vende pl\u00e1tanos en la puerta de su casa para sobrevivir, tiene la esperanza de que \u201cEvo har\u00e1 bajar los precios\u201d si es elegido.<\/p>\n<p>En un pa\u00eds de 12 millones de habitantes que alguna vez tuvo una clase media con visi\u00f3n de futuro, muchos bolivianos ahora viven al l\u00edmite. En los \u00faltimos meses la falta de alimentos b\u00e1sicos como el arroz o el aceite y la escasez de combustible han impulsado recurrentes protestas.<\/p>\n<p>En una estaci\u00f3n de venta de di\u00e9sel, el transportista Francisco Yucra, de 54 a\u00f1os, se mostr\u00f3 irritado.<\/p>\n<p>\u201cHacer cola te quita tiempo y ganancia\u00bb, se quej\u00f3. \u00abSabemos qui\u00e9nes son culpables, Arce y Evo nos han llevado a esto y no creo que se solucione pronto\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNi Lucho (Arce), ni Evo (Morales), los dos son lo mismo\u201d, se le\u00eda en una pancarta que el viento arranc\u00f3 a una manifestante de la mano durante una masiva protesta contra el desabasto de alimentos y combustibles en las ca\u00f3ticas calles de La Paz. Los bolivianos se encaminan a los comicios presidenciales \u2014que tendr\u00e1n lugar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[355],"tags":[],"class_list":["post-47024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-08 20:04:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2025\/01\/descarga.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=47024"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/47024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/47025"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=47024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=47024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=47024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}