{"id":46081,"date":"2024-12-16T00:41:38","date_gmt":"2024-12-16T06:41:38","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=46081"},"modified":"2024-12-16T00:41:38","modified_gmt":"2024-12-16T06:41:38","slug":"por-abajo-del-promedio-en-al-los-ingresos-tributarios-de-mexico-en-2025","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/12\/16\/por-abajo-del-promedio-en-al-los-ingresos-tributarios-de-mexico-en-2025\/","title":{"rendered":"Por abajo del promedio en AL los ingresos tributarios de M\u00e9xico en 2025"},"content":{"rendered":"<div class=\"col col1\">\n<p class=\"s-s\">Los ingresos tributarios que el gobierno busca obtener en 2025 ser\u00e1n equivalentes a 14.6 por ciento del producto interno bruto (PIB), lo que representa la mayor participaci\u00f3n de este tipo de recursos en los \u00faltimos a\u00f1os. Sin embargo, esa proporci\u00f3n ser\u00eda 1.4 veces menor al promedio de la regi\u00f3n de Am\u00e9rica Latina y el Caribe, que es de 21.5 por ciento, seg\u00fan datos del Centro de Investigaci\u00f3n Econ\u00f3mica y Presupuestaria (CIEP).<\/p>\n<p>Los ingresos tributarios sumar\u00edan 5.29 billones de pesos, es decir, un crecimiento anual del 2.8 por ciento. Se trata de las contribuciones obligatorias que los ciudadanos y las empresas deben pagar al gobierno para financiar el gasto p\u00fablico, en \u00e1reas como educaci\u00f3n, salud, infraestructura, seguridad y programas sociales.<\/p>\n<p>Estos tributos se recaudan a trav\u00e9s de diversos instrumentos, como el impuesto sobre la renta (ISR), el impuesto al valor agregado (IVA) y el impuesto especial sobre producci\u00f3n y servicios (IEPS), entre otros. Dichos grav\u00e1menes se aplican sobre diferentes bases, como los ingresos, el consumo o la producci\u00f3n de bienes y servicios espec\u00edficos.<\/p>\n<p>De acuerdo con el Centro de Estudios de las Finanzas P\u00fablicas (CEFP) de la C\u00e1mara de Diputados, en el primer semestre de 2024, los ingresos tributarios alcanzaron 2 billones 527 mil 739.8 millones de pesos, cifra que representa 93.3 por ciento de los ingresos no petroleros.\u00a0<q>Esta alta proporci\u00f3n refleja la importancia de los ingresos tributarios dentro de la estructura de los ingresos p\u00fablicos no petroleros<\/q>, se\u00f1al\u00f3 el CEFP.<\/p>\n<\/div>\n<div class=\"col col2\">\n<p>Al comparar lo observado respecto a lo programado, se observa que lo captado fue superior en 3 mil 249.1 millones de pesos, mientras en comparaci\u00f3n con lo obtenido en el mismo periodo de 2023, se registr\u00f3 un incremento de 253 mil 122.9 millones de pesos, lo que representa un crecimiento real del 6.2 por ciento.<\/p>\n<p>Los ingresos por impuesto al IVA tuvieron un aumento de 41 mil 327.5 millones de pesos, lo que compens\u00f3 la principal ca\u00edda, registrada en el IEPS, que se redujo en 27 mil 912.5 millones de pesos.<\/p>\n<p>El ISR concentr\u00f3 la mayor parte de lo recaudado. Al segundo trimestre de 2024, gener\u00f3 un bill\u00f3n 435 mil 378.7 millones de pesos, monto que fue 18 mil 99.5 millones de pesos menor a lo programado.<\/p>\n<p>El pasado 4 de diciembre, el Senado aprob\u00f3 la Ley de Ingresos de la Federaci\u00f3n para el ejercicio fiscal 2025, donde se proyecta un ingreso total de 9.3 billones de pesos, con ingresos presupuestarios de 8 billones 55 mil 649.3 millones de pesos, lo que representa un incremento de 5.4 por ciento en t\u00e9rminos reales respecto a 2024.<\/p>\n<p><q>Los ingresos presupuestarios totales se han mantenido estables a lo largo de la \u00faltima d\u00e9cada, por lo que se evidencia la necesidad de implementar cambios que permitan incrementar la recaudaci\u00f3n<\/q>, menciona un an\u00e1lisis del CIEP.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los ingresos tributarios que el gobierno busca obtener en 2025 ser\u00e1n equivalentes a 14.6 por ciento del producto interno bruto (PIB), lo que representa la mayor participaci\u00f3n de este tipo de recursos en los \u00faltimos a\u00f1os. Sin embargo, esa proporci\u00f3n ser\u00eda 1.4 veces menor al promedio de la regi\u00f3n de Am\u00e9rica Latina y el Caribe, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-46081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:16:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/12\/380787289.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/46081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=46081"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/46081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/46082"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=46081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=46081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=46081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}