{"id":45643,"date":"2024-12-10T00:58:08","date_gmt":"2024-12-10T06:58:08","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=45643"},"modified":"2024-12-10T00:58:08","modified_gmt":"2024-12-10T06:58:08","slug":"sat-reafirma-su-compromiso-para-combatir-la-corrupcio","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/12\/10\/sat-reafirma-su-compromiso-para-combatir-la-corrupcio\/","title":{"rendered":"SAT reafirma su compromiso para combatir la corrupci\u00f3"},"content":{"rendered":"<p class=\"western\">El Servicio de Administraci\u00f3n Tributaria (SAT) reafirm\u00f3 su compromiso de combatir de manera frontal cualquier acto de corrupci\u00f3n mediante acciones preventivas y correctivas, seg\u00fan un comunicado emitido por la entidad.<\/p>\n<p class=\"western\">En el marco del D\u00eda Internacional contra la Corrupci\u00f3n que se celebra este 9 de diciembre, el SAT dijo que se\u00a0 han desarrollado mecanismos espec\u00edficos en cada una de sus \u00e1reas sustantivas para erradicar pr\u00e1cticas mediante las cuales se cometan delitos y faltas administrativas.<\/p>\n<p class=\"western\">Detall\u00f3 que en el \u00e1mbito preventivo, de enero a octubre de 2024 se han realizado 69 supervisiones para constatar que las operaciones realizadas por las unidades administrativas cumplen con las disposiciones que las regulan.<\/p>\n<p class=\"western\">A su vez, se han efectuado 5 mil 99 procesos de evaluaci\u00f3n a empleados, candidatos y terceros relacionados, para asegurar que estos sean confiables y no susceptibles a cometer actos il\u00edcitos.<\/p>\n<p class=\"western\">En el \u00e1mbito correctivo se han promovido denuncias ante el \u00d3rgano Interno de Control y ante la Fiscal\u00eda General de la Rep\u00fablica en contra de personas servidoras p\u00fablicas del SAT por presuntos actos il\u00edcitos.<\/p>\n<p class=\"western\">El SAT agreg\u00f3 que cada trimestre se realiza un estudio de opini\u00f3n para conocer la percepci\u00f3n de los contribuyentes sobre la honestidad del personal del SAT e identificar \u00e1reas de oportunidad que ayuden a mejorar los procesos y servicios, en el cual, al tercer trimestre de 2024 se obtuvo 9.19 de calificaci\u00f3n en el indicador de honestidad en una escala del 0 al 10.<\/p>\n<p class=\"western\">\u201cEn el SAT, el combate a la corrupci\u00f3n forma parte de las estrategias de recaudaci\u00f3n y ha permitido erradicar pr\u00e1cticas mediante las cuales se cometen delitos para evadir o eludir impuestos\u201d, concluy\u00f3 el organismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio de Administraci\u00f3n Tributaria (SAT) reafirm\u00f3 su compromiso de combatir de manera frontal cualquier acto de corrupci\u00f3n mediante acciones preventivas y correctivas, seg\u00fan un comunicado emitido por la entidad. En el marco del D\u00eda Internacional contra la Corrupci\u00f3n que se celebra este 9 de diciembre, el SAT dijo que se\u00a0 han desarrollado mecanismos espec\u00edficos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-45643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 06:25:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/12\/RFXQH_2_B7_OZP_7_NK_42_EQSJYMY_5_PM_1828ee56d5.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/45643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=45643"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/45643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/45644"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=45643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=45643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=45643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}