{"id":45410,"date":"2024-12-06T07:03:31","date_gmt":"2024-12-06T13:03:31","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=45410"},"modified":"2024-12-06T07:03:31","modified_gmt":"2024-12-06T13:03:31","slug":"desbandada-en-el-pri","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/12\/06\/desbandada-en-el-pri\/","title":{"rendered":"Desbandada en el PRI"},"content":{"rendered":"<p><strong><span style=\"font-size: 14pt;\">Por \u00c1ngel \u00c1lvaro Pe\u00f1a<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">El PRI se convirti\u00f3 en negocio de su c\u00fapula, donde no pertenecer a ese grupo se est\u00e1 excluido de todos los derechos y excesos que implica militar en ese organismo, que naci\u00f3, creci\u00f3 y muere en medio de la corrupci\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El PRI nace el 4 de marzo de 1929, todav\u00eda estaban calientes los cuerpos del mill\u00f3n de campesinos muertos en la revoluci\u00f3n y \u00e9sta ya se hab\u00eda institucionalizado, creando un partido para que nada cambiara. Las primeras siglas fueron PNR, Partido Nacional Revolucionario, donde se apropia no s\u00f3lo de la vida pol\u00edtica de M\u00e9xico sino de la Revoluci\u00f3n. Y afilia precisamente a los caciques y hacendados que provocaron la revuelta armada.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La exclusi\u00f3n de quienes ten\u00edan sus parcelas de poder los obliga a cambiar de partido, as\u00ed el exsecretario de Turismo durante el gobierno de Enrique Pe\u00f1a Nieto, Enrique de la Madrid, deja el PRI, pero no por diferencias con la direcci\u00f3n del partido ni por rechazo a falta de democracia interna, eso nunca le ha importado, sino porque se qued\u00f3 sin espacio para accionar.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Luego de obtener derechos especiales por ser hijo de un ex presidente, la militancia en el PRI por m\u00e1s de 43 a\u00f1os, obliga a Enrique de la Madrid Cordero a abandonar las filas a las que entr\u00f3 para seguir la carrera pol\u00edtica igual que su padre, uno de los m\u00e1s grises presidentes de M\u00e9xico.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">De la Madrid detall\u00f3 que est\u00e1 convencido de que un \u00abM\u00e9xico mejor es posible\u00bb, por lo que, para contribuir a esa visi\u00f3n, se\u00f1al\u00f3 que \u00abtengo que buscar otros espacios que me permitan sumarme a la construcci\u00f3n de di\u00e1logos positivos entre mexicanos\u00bb.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Sobre su decisi\u00f3n, De la Madrid Cordero se\u00f1al\u00f3 que no s\u00f3lo el PRI enfrenta una crisis, sino que en M\u00e9xico se vive una crisis de partidos pol\u00edticos en general, por lo que hizo un llamado a los partidos para que construyan \u00abuna sociedad m\u00e1s participativa\u00bb.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Es decir, De la Madrid no se va de la pol\u00edtica huye del PRI, lo dejaron sin derechos especiales, lo trataron como un militante m\u00e1s y eso no puede soportar la arrogancia que caracteriz\u00f3 a una clase pol\u00edtica en extinci\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Seguramente fue llamado al partido que organiza Guadalupe Acosta Naranjo, Frente C\u00edvico Nacional, grupo conservador de ultraderecha, patrocinado por Claudio X. Gonz\u00e1lez y que es el \u00fanico de los partidos pol\u00edticos que podr\u00edan lograr el registro condicionado el pr\u00f3ximo a\u00f1o, luego de sortear una serie de requisitos que no parecen f\u00e1ciles para una organizaci\u00f3n como \u00e9sta donde apenas comienzan a contarse cientos, pero no miles, en sus asambleas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En ese partido est\u00e1n personajes de oscura trayectoria como Beatriz Pag\u00e9s, Cecilia Soto, Gustavo Madero, Emilio \u00c1lvarez Icaza, Jos\u00e9 Antonio Crespo, Edmundo Jacobo, llaman a personajes como X\u00f3chitl G\u00e1lvez y desertores de otros partidos, sobre todo perredistas que se quedaron sin registro.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Deben reunir 200 asambleas, cada una con por lo menos 3 mil asistentes, y mantener presencia en 20 entidades, con por lo menos 3 mil asistentes en cada una de ellas, entre otros muchos retos que personajes como Felipe Calder\u00f3n y Margarita Zavala no pudieron cumplir, a pesar de contar con todo el dinero de Estados Unidos y una buena parte del financiamiento ten\u00eda origen oscuro.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Enrique de la Madrid, apost\u00f3 por X\u00f3chitl en las elecciones pasadas, se uni\u00f3 a ella luego de competir en su contra, por la candidatura, y perdi\u00f3 y ahora se une a un grupo de desertores del tricolor que parece no tener fin, desde Miguel \u00c1ngel Osorio Chong, Claudia Ruiz Massieu, pasando por Ana Lilia Herrera Anzaldo y Alejandro Castro Hern\u00e1ndez, y la m\u00e1s reciente, la senadora Cynthia L\u00f3pez Castro, quien renunci\u00f3 al PRI para unirse a Morena.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Imposible el ingreso de De la Madrid a Morena, ni quiere estar en ese partido que rechaza todo lo que el junior representa ni \u00e9l puede militar donde estar\u00eda bajo la lupa, luego de tener un lugar privilegiado en el tricolor.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Luego de la incorporaci\u00f3n a Morena de los panistas Javier Corral, ex gobernador de Chihuahua y del veracruzano, Miguel \u00c1ngel Yunes M\u00e1rquez, Morena debe cuidar la trayectoria de quienes entran a su partido, provenientes de otros. El jueves 5 de diciembre, se liaron a golpes en el Senado, a causa de la defensa de Yunes M\u00e1rquez, por la imprudencia del panista Mario V\u00e1zquez Robles, quien despu\u00e9s de agredirlo verbalmente intent\u00f3 convertirse en v\u00edctima cuando, en realidad provoc\u00f3 el zafarrancho y la golpiza.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Otro de los provocadores fue el senador con fama de agresivo, se\u00f1alado de pegarle hasta a su t\u00eda, Enrique Vargas del Villar, que tres d\u00edas antes mand\u00f3 golpear a quien hab\u00eda sido su contrincante a la alcald\u00eda de Huixquilucan, que gobierna su esposa. Municipio que es un feudo familiar porque llevan \u00e9l y su esposa tres administraciones municipales seguidas en sus manos, con importantes quejas de los ciudadanos por represi\u00f3n y violencia.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Morena al adoptar como hijos propios, a personajes de otros partidos, si bien puede ayudarle a la hora de las votaciones, pero el resto del tiempo, los adoptados se convierten en un dolor de cabeza para el partido en el poder, de tal forma que Morena nunca pensar\u00eda en la posibilidad de abrirle las puertas del movimiento a un personaje tan conflictivo y caprichoso como Enrique de la Madrid.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En San Luis Potos\u00ed hubo al mismo tiempo, otro brote de deserci\u00f3n masiva al PRI, donde se quejan del autoritarismo que priva en ese partido, al estilo de Alito, quien modific\u00f3 los estatutos para seguir al frente contra la voluntad de la mayor\u00eda de los militantes.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Alejandro Moreno est\u00e1 qued\u00e1ndose solo en el tricolor, s\u00f3lo algunos que conforman la c\u00fapula consideran que tienen fuerza, enga\u00f1\u00e1ndose solos porque en las \u00faltimas elecciones no gan\u00f3 ni un distrito electoral. La decadencia es evidente y la agon\u00eda inevitable.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">PEGA Y CORRE.- Los legisladores de oposici\u00f3n siempre vieron el presupuesto de egresos como un aumento de salario, el pr\u00f3ximo deb\u00eda superar al anterior, eran tiempos de inflaci\u00f3n y devaluaciones, no siempre debe ser creciente la cantidad, sobre todo cuando hay nuevas instancias que cubren necesidades de salud que no est\u00e1n precisamente dentro de ese rubro y lo mismo sucede con otras, pero la oposici\u00f3n cree que su tarea es oponerse a todo, cuando en realidad, debe cogobernar y olvidarse de ser contrapeso obligado, donde no tiene fuerza\u2026Esta columna se publica los lunes, mi\u00e9rcoles y viernes<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por \u00c1ngel \u00c1lvaro Pe\u00f1a El PRI se convirti\u00f3 en negocio de su c\u00fapula, donde no pertenecer a ese grupo se<\/p>\n","protected":false},"author":4,"featured_media":31729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6],"tags":[],"class_list":["post-45410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-columnistas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/05\/LOPEZ-DORIGA-LOGO-3.jpeg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:17:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/45410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=45410"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/45410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/31729"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=45410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=45410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=45410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}