{"id":44319,"date":"2024-11-19T00:14:45","date_gmt":"2024-11-19T06:14:45","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=44319"},"modified":"2024-11-18T18:50:20","modified_gmt":"2024-11-19T00:50:20","slug":"claudia-sheinbaum-se-reune-con-lideres-de-eu-china-y-canada-durante-el-g20","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/11\/19\/claudia-sheinbaum-se-reune-con-lideres-de-eu-china-y-canada-durante-el-g20\/","title":{"rendered":"Claudia Sheinbaum se re\u00fane con l\u00edderes de EU, China y Canad\u00e1 durante el G20"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">La presidenta\u00a0Claudia Sheinbaum\u00a0se re\u00fane con lideres mundiales\u00a0durante la\u00a0Cumbre\u00a0de las grandes potencias que integran el\u00a0G20, que se realiza en Sao Paulo, Brasil. Entre esos\u00a0Joe Biden, presidente de los Estados Unidos;\u00a0Xi Jinping, de China,\u00a0Justin Trudeau, ministro de Canad\u00e1, con integrantes del MIKTA, as\u00ed como el presidente de Chile,\u00a0Gabriel Boric.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En sus redes sociales la mandataria mexicana inform\u00f3 que \u201ccon el presidente\u00a0Joseph Biden\u00a0hablamos de la\u00a0buena relaci\u00f3n\u00a0que existe y debe existir\u00a0entre M\u00e9xico y Estados Unidos, adem\u00e1s de la importancia de\u00a0trabajar\u00a0juntos en materia de\u00a0migraci\u00f3n, seguridad y econom\u00eda. Desde el G20 Brasil 2024, refrendamos la amistad entre ambos pa\u00edses\u201d.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Asimismo, la presidenta inform\u00f3 que\u00a0convers\u00f3 con el presidente de China\u00a0Xi Jinping, a quien\u00a0agradeci\u00f3\u00a0todo el\u00a0apoyo\u00a0para la\u00a0recuperaci\u00f3n de Acapulco\u00a0mediante la producci\u00f3n y entrega de enseres dom\u00e9sticos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta\u00a0Claudia Sheinbaum\u00a0se re\u00fane con lideres mundiales\u00a0durante la\u00a0Cumbre\u00a0de las grandes potencias que integran el\u00a0G20, que se realiza en Sao Paulo,<\/p>\n","protected":false},"author":4,"featured_media":44320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[],"class_list":["post-44319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/11\/Biden-y-Sheinbaum-G20.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:50:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/44319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=44319"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/44319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/44320"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=44319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=44319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=44319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}