{"id":43865,"date":"2024-11-12T00:12:56","date_gmt":"2024-11-12T06:12:56","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=43865"},"modified":"2024-11-11T20:46:27","modified_gmt":"2024-11-12T02:46:27","slug":"america-latina-paga-un-costo-de-3-44-del-pib-por-el-crimen-y-la-inseguridad-fmi-y-bid","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/11\/12\/america-latina-paga-un-costo-de-3-44-del-pib-por-el-crimen-y-la-inseguridad-fmi-y-bid\/","title":{"rendered":"Am\u00e9rica Latina paga un costo de 3.44% del PIB por el crimen y la inseguridad: FMI y BID"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">El\u00a0costo econ\u00f3mico directo del crimen y la inseguridad\u00a0en Am\u00e9rica Latina asciende a 3.44% del PIB desde el a\u00f1o 2022 y no ha mejorado desde entonces, estimaron expertos del\u00a0Fondo Monetario Internacional\u00a0(FMI) y el\u00a0Banco Interamericano de Desarrollo\u00a0(BID).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Este costo incluye el impacto de la p\u00e9rdida de vidas, la\u00a0reducci\u00f3n de la calidad de vida, el mayor gasto p\u00fablico en servicios de prevenci\u00f3n y control, as\u00ed como los gastos en seguridad por parte del sector privado en 22 de los 33 pa\u00edses de la regi\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Esto representa casi el 80% del presupuesto p\u00fablico asignado en educaci\u00f3n y significa que son recursos que en lugar de invertirse a la innovaci\u00f3n o mejora en infraestructura, son absorbidos por las consecuencias del crimen y la violencia, advirti\u00f3 el Presidente del BID,\u00a0Ilan Goldfajn.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al inaugurar el seminario Crimen en Latinoam\u00e9rica y el impacto para las pol\u00edticas p\u00fablicas, explic\u00f3 que tambi\u00e9n hay costos indirectos de este flagelo, como es la disminuci\u00f3n de la inversi\u00f3n, la menor productividad empresarial, el aumento de la migraci\u00f3n as\u00ed como el impacto que se genera en el turismo, un sector clave para las econom\u00edas de la regi\u00f3n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0costo econ\u00f3mico directo del crimen y la inseguridad\u00a0en Am\u00e9rica Latina asciende a 3.44% del PIB desde el a\u00f1o 2022 y no ha mejorado desde entonces, estimaron expertos del\u00a0Fondo Monetario Internacional\u00a0(FMI) y el\u00a0Banco Interamericano de Desarrollo\u00a0(BID). Este costo incluye el impacto de la p\u00e9rdida de vidas, la\u00a0reducci\u00f3n de la calidad de vida, el mayor gasto p\u00fablico [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1947],"tags":[],"class_list":["post-43865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 00:10:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/11\/6732b5216df9c.jpeg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/43865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=43865"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/43865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/43866"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=43865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=43865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=43865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}