{"id":4304,"date":"2022-05-13T18:18:25","date_gmt":"2022-05-13T23:18:25","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=4304"},"modified":"2022-05-13T18:31:32","modified_gmt":"2022-05-13T23:31:32","slug":"presidente-se-compromete-con-padres-de-debanhi-no-habra-impunidad","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2022\/05\/13\/presidente-se-compromete-con-padres-de-debanhi-no-habra-impunidad\/","title":{"rendered":"Presidente se compromete con padres de Debanhi, \u201cno habr\u00e1 impunidad\u201d"},"content":{"rendered":"<p class=\"p1\"><span style=\"font-size: 14pt;\"><em><strong>Monterrey.<\/strong><\/em> El presidente <strong>L\u00f3pez Obrador se reuni\u00f3 en Nuevo Le\u00f3n con Mario Escobar y Dolores Bazald\u00faa<\/strong>, padres de la joven<strong> Debanhi Escobar<\/strong>, a quienes reiter\u00f3 el compromiso del gobierno federal para hacer justicia a su hija y conocer la verdad sobre su muerte a trav\u00e9s de las investigaciones que ya se realizan bajo la pol\u00edtica Cero Impunidad.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\"><strong>\u201cHice el compromiso de ayudar a esclarecer lo sucedido y que no haya impunidad; en eso coincidimos con el gobernador (Samuel Garc\u00eda) y las autoridades de Nuevo Le\u00f3n. Vamos a estar pendientes y nos van a seguir ayudando ustedes tambi\u00e9n (periodistas), porque ayuda mucho la transparencia, la denuncia y la cr\u00edtica\u201d, expres\u00f3.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Sobre los avances para contener la incidencia delictiva en el estado, el secretario de la Defensa Nacional, Luis Cresencio Sandoval Gonz\u00e1lez, resalt\u00f3 que, a marzo de 2022, registraron una tendencia a la baja los delitos de robo en transporte y secuestro.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5273 size-large\" src=\"https:\/\/politicosaldesnudo.com.mx\/wp-content\/uploads\/2022\/05\/13-05-2022-Conferencia-de-prensa-matutina-Nuevo-Leo\u0301n-Foto-03-1024x576.jpeg\" alt=\"\" width=\"800\" height=\"450\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong><span style=\"font-size: 14pt;\">La estrategia de seguridad se refuerza para revertir el alza que reporta el Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica en los delitos de extorsi\u00f3n, homicidio doloso, robo a casa habitaci\u00f3n y de veh\u00edculos. A nivel nacional, Nuevo Le\u00f3n ocupa el lugar 17 en delitos de impacto.<\/span><\/strong><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">En la entidad est\u00e1n <strong>desplegados 15 mil 836 elementos del Ej\u00e9rcito y Fuerza A\u00e9rea Mexicana<\/strong>; de la Secretar\u00eda de Marina, de la Guardia Nacional y de las polic\u00edas estatal y municipal.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Los efectivos tienen presencia en <strong>ocho coordinaciones territoriales de la Guardia Nacional en San Pedro Garza Garc\u00eda, Pesquer\u00eda, Guadalupe Victoria, Galeana, An\u00e1huac, Apodaca, Montemorelos y Linares.<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">La corporaci\u00f3n cuenta con seis instalaciones a las que se suman tres cedidas por el Ej\u00e9rcito. Se proyecta la edificaci\u00f3n de seis compa\u00f1\u00edas entre 2022 y 2023 con las que se tendr\u00e1 un total de 15 cuarteles en la entidad.<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">El titular de Sedena refiri\u00f3 que se mantiene vigilancia en instalaciones estrat\u00e9gicas en la entidad; tres corresponden a Petr\u00f3leos Mexicanos (Pemex) y dos al Centro Nacional de Control del Gas Natural (Cenagas).<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">De acuerdo con informaci\u00f3n de la Secretar\u00eda de la Defensa Nacional, las Fuerzas Armadas inhabilitaron 630 tomas clandestinas y recuperaron 7.5 millones de litros de combustible en los municipios de Cadereyta, Mina, Santa Catarina, General Bravo y Pesquer\u00eda. Adem\u00e1s, aseguraron 289 veh\u00edculos, 28 predios y detuvieron a 256 presuntos responsables.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey. El presidente L\u00f3pez Obrador se reuni\u00f3 en Nuevo Le\u00f3n con Mario Escobar y Dolores Bazald\u00faa, padres de la joven Debanhi Escobar, a quienes reiter\u00f3 el compromiso del gobierno federal para hacer justicia a su hija y conocer la verdad sobre su muerte a trav\u00e9s de las investigaciones que ya se realizan bajo la pol\u00edtica [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145],"tags":[698,697,218,15],"class_list":["post-4304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados","tag-denbahni-escobar","tag-ejercito","tag-nuevo-leon","tag-seguridad"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 00:10:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2022\/05\/P-DEBANH2.png","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/4304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=4304"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/4304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/4305"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=4304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=4304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=4304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}