{"id":39329,"date":"2024-09-05T03:50:27","date_gmt":"2024-09-05T08:50:27","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=39329"},"modified":"2024-09-04T23:51:23","modified_gmt":"2024-09-05T04:51:23","slug":"extremar-precaucion-por-situacion-compleja-y-de-riesgo-aumentan-lluvias-pc","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/09\/05\/extremar-precaucion-por-situacion-compleja-y-de-riesgo-aumentan-lluvias-pc\/","title":{"rendered":"Extremar precauci\u00f3n por \u201csituaci\u00f3n compleja y de riesgo\u201d: aumentan lluvias: PC"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">#AlertaGris\u00a0del #SIAT_VER en fase de #Vigilancia, emiti\u00f3\u00a0el \u00e1rea de Meteorolog\u00eda de la Secretar\u00eda de Protecci\u00f3n Civil a la poblaci\u00f3n de Veracruz para extremar\u00a0precauci\u00f3n por Situaci\u00f3n compleja y de riesgo sigue pronostic\u00e1ndose para los siguientes d\u00edas en el Golfo de M\u00e9xico por una onda tropical, vaguadas y centros de baja presi\u00f3n que aumenta el potencial de lluvias y tormentas a partir de hoy mi\u00e9rcoles 4 de agosto.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Prepar\u00e9monos\u00a0 ante la probabilidad alta de lluvias y tormentas fuertes a intensas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">SISTEMAS METEOROL\u00d3GICOS Y SU PREVISI\u00d3N:\u00a0 Situaci\u00f3n compleja y de riesgo sigue pronostic\u00e1ndose para los siguientes d\u00edas en el Golfo de M\u00e9xico y estados de la vertiente, con la presencia de vaguadas, centros de baja presi\u00f3n, el posible desarrollo de un frente fr\u00edo que podr\u00eda llegar el viernes al norte de Veracruz e interactuar el fin de semana con la llegada de la onda tropical con eje ubicado actualmente al sur de Jamaica. Toda esta situaci\u00f3n meteorol\u00f3gica se apoyar\u00e1 con el comportamiento del viento en altura (cizalladura-divergencia) muy favorable para aumentar el potencial de lluvias y tormentas (descargas el\u00e9ctricas, viento en rachas, posibles granizadas) en el estado de Veracruz, con acumulados muy significativos hacia el fin de semana e inicios de la siguiente, eventos localmente intensos, as\u00ed como con viento del Norte prolongado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">PRON\u00d3STICO PARA EL ESTADO DE VERACRUZ:\u00a0el potencial de lluvias y tormentas (actividad el\u00e9ctrica y r\u00e1fagas de viento) aumentar\u00e1 a partir de hoy,\u00a0persistiendo la tendencia de ser m\u00e1s significativo el fin de semana e inicios de la siguiente (consulte tabla para ver acumulados estimados, sin descartar mayores). Viento con pron\u00f3stico de dominar del NORTE y ser prolongado a partir del viernes con rachas fuertes. Oleaje de 0.5 a 1.5 m\u00a0 aumentando.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">IMPORTANTE: aumenta la probabilidad de deslaves, derrumbes, deslizamiento, crecida de r\u00edos y arroyos e inundaciones, debido a la intensidad y continuidad de la lluvia. Se recomienda realizar las labores preventivas y tomar las precauciones.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#AlertaGris\u00a0del #SIAT_VER en fase de #Vigilancia, emiti\u00f3\u00a0el \u00e1rea de Meteorolog\u00eda de la Secretar\u00eda de Protecci\u00f3n Civil a la poblaci\u00f3n de<\/p>\n","protected":false},"author":4,"featured_media":33982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[356],"tags":[],"class_list":["post-39329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/06\/LLUVIAS.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:03:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/39329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=39329"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/39329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/33982"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=39329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=39329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=39329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}