{"id":36177,"date":"2024-07-20T02:01:01","date_gmt":"2024-07-20T07:01:01","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=36177"},"modified":"2024-07-20T02:01:01","modified_gmt":"2024-07-20T07:01:01","slug":"condenan-a-corresponsal-estadunidense-en-rusia-a-16-anos-de-carcel","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/07\/20\/condenan-a-corresponsal-estadunidense-en-rusia-a-16-anos-de-carcel\/","title":{"rendered":"Condenan a corresponsal estadunidense en Rusia a 16 a\u00f1os de c\u00e1rcel"},"content":{"rendered":"<p class=\"western\"><span style=\"font-size: 14pt;\">En un juicio a puerta cerrada que sorprendi\u00f3 por su celeridad, apenas tres sesiones, la corte regional de Sverdlovsk en la ciudad de Yekaterimburgo, peculiar capital de los Urales que separa las partes europea y asi\u00e1tica de Rusia, conden\u00f3 este viernes al periodista estadunidense Evan Gershkovich, corresponsal en Mosc\u00fa del diario Wall Street Journal, a 16 a\u00f1os de c\u00e1rcel en un r\u00e9gimen penitenciario de m\u00e1xima seguridad al considerarlo culpable de \u201cespionaje\u201d.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">El Servicio Federal de Seguridad (FSB, por sus siglas en ruso, sucesor del KGB sovi\u00e9tico) detuvo a Gershkovich, de 32 a\u00f1os, el 29 de marzo de 2023 en el restaurante Bukovski Grill, de Yekaterimburgo. El periodista hab\u00eda viajado a la regi\u00f3n de Sverdlovsk para recabar informaci\u00f3n y hacer entrevistas.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Seg\u00fan uno de los entrevistados por Gershkovich, el diputado municipal Viacheslav Vegner \u2013en declaraciones al portal de noticias 66.ru, muy popular en los Urales\u2013, el enviado del Wall Street Journal le pregunt\u00f3 acerca de la actitud de los habitantes de la tercera ciudad rusa en importancia respecto de la \u201coperaci\u00f3n militar especial\u201d que lanz\u00f3 el presidente Vladimir Putin en Ucrania, lo que piensa la gente de a pie sobre el grupo de mercenarios Wagner (de Yevgueni Prigozhin, magnate ca\u00eddo en desgracia cuando orden\u00f3 una fallida rebeli\u00f3n, se distanci\u00f3 de su protector, el presidente Putin, y muri\u00f3 en agosto de 2023 al desplomarse su avi\u00f3n privado) y la reconversi\u00f3n de la industria local en tiempos que no son de paz.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Al anunciar su arresto, el FSB emiti\u00f3 un breve comunicado en el que acus\u00f3 a Gershkovich de \u201ctratar de conseguir, en inter\u00e9s del gobierno de Estados Unidos (despu\u00e9s se filtr\u00f3 que se refer\u00eda a la CIA, la Agencia Central de Inteligencia), informaci\u00f3n clasificada como secreto de Estado sobre una de las empresas del complejo industrial-militar de la regi\u00f3n\u201d, que la prensa local relacion\u00f3 de inmediato con el consorcio Uralvagonzavod, famoso por fabricar y reparar tanques.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Los voceros del Kremlin, Dimitri Peskov, y de la canciller\u00eda, Mar\u00eda Zajarova, se\u00f1alaron en su momento que el FSB detuvo a Gershkovich \u201cin fraganti\u201d y que \u201cno era el primer caso en que se usaba el estatus de periodista extranjero, acreditado ante el ministerio de Relaciones Exteriores de Rusia, para realizar actividades que nada tienen que ver con el periodismo\u201d.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">De acuerdo con sus abogados, el periodista neg\u00f3 los cargos y se declar\u00f3 inocente en la primera sesi\u00f3n del juicio en su contra, el 26 de junio anterior, mientras la fiscal\u00eda insisti\u00f3 en su culpabilidad y solicit\u00f3 este viernes, en la tercera y \u00faltima sesi\u00f3n, una pena de 18 a\u00f1os de privaci\u00f3n de la libertad, del m\u00e1ximo de 20 a\u00f1os que estipula el C\u00f3digo Penal ruso por \u201cespionaje\u201d.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\"><strong>Probable intercambio<\/strong><\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">El hecho de que la Corte satisfizo la petici\u00f3n de la fiscal\u00eda y adelant\u00f3 para el jueves de esta semana la segunda sesi\u00f3n que estaba prevista para el 13 de agosto y que un d\u00eda m\u00e1s tarde, este viernes, el juez emiti\u00f3 en apenas cuatro minutos su veredicto, parece indicar que ya hay avances en la negociaci\u00f3n soterrada para intercambiar al periodista con alg\u00fan ciudadano ruso detenido y condenado en Estados Unidos o pa\u00eds aliado suyo.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">La pr\u00e1ctica habitual muestra que Rusia acepta dichos canjes \u2013como el m\u00e1s reciente que fue el de la basquetbolista estadunidense Brittney Griner y el traficante de armas Viktor Bout en diciembre de 2022\u2013 cuando los presuntos imputados de un delito grave en este pa\u00eds ya son condenados por la justicia.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">En el caso de Gershkovich el intercambio depender\u00e1 de si su defensa presenta o no recurso de apelaci\u00f3n, lo que s\u00f3lo puede posponer la fecha de su liberaci\u00f3n. Desde el momento mismo de su detenci\u00f3n el gobierno de Estados Unidos comenz\u00f3 a gestionar un posible canje, sin que los negociadores de ambos bandos hayan podido ponerse de acuerdo sobre a qui\u00e9nes incluir en el intercambio de presos. \u201cCreo que se puede llegar a un entendimiento\u201d, respondi\u00f3 el presidente Vladimir Putin en la entrevista que concedi\u00f3, el 8 de febrero pasado, al controvertido\u00a0periodista estadunidense Tucker Carlson, quien le pregunt\u00f3 si estaba considerando un canje.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Putin reconoci\u00f3 que hab\u00eda contactos al respecto, pero dijo que este tipo de negociaciones son efectivos cuando no salen a la luz p\u00fablica. Dio a entender que Rusia estaba interesada en intercambiar a Gershkovich, despu\u00e9s de ser juzgado, por \u201cun patriota que estim\u00f3 necesario hacer justicia a un sangriento criminal\u201d.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">El mandatario ruso, al parecer, se refer\u00eda a un agente del FSB, Vadim Krasikov, condenado a cadena perpetua en Alemania por asesinar, en agosto de 2019, en un parque de Berl\u00edn al ex comandante separatista checheno de origen georgiano, Zelimjan Jangoshvili, pero hay muchos otros casos de estadunidenses y rusos que podr\u00edan ser parte de un intercambio.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\"><strong>Se crea precedente<\/strong><\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">El caso de Gershkovich, en opini\u00f3n del abogado Yevgueni Smirnov, crea un precedente porque es la primera vez que Rusia condena a un periodista extranjero por \u201cespionaje\u201d. Desde que se disolvi\u00f3 la Uni\u00f3n Sovi\u00e9tica en 1991, nunca hab\u00eda pasado, si bien se prefer\u00eda expulsar a los periodistas que \u201crealizaban actividades incompatibles con su estatus\u201d. De un tiempo para ac\u00e1, el ministerio de Relaciones Exteriores, alegando reciprocidad, suele anular la acreditaci\u00f3n y la visa de un periodista, dando un plazo breve para abandonar el pa\u00eds.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Antes de ser condenado este viernes en Yekaterimburgo, Gershkovich estuvo en prisi\u00f3n preventiva 478 d\u00edas en la misma c\u00e1rcel de Lef\u00f3rtovo, en Mosc\u00fa, que el corresponsal del semanario US News &amp;amp; World Report, Nicholas Daniloff, el anterior periodista extranjero detenido por \u201cespionaje\u201d, el 2 de septiembre de 1986, pero cuando todav\u00eda exist\u00eda la Uni\u00f3n Sovi\u00e9tica.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 14pt;\">Daniloff no lleg\u00f3 a ser juzgado. Tras intensas negociaciones, el 23 de septiembre de ese mismo a\u00f1o, se le permiti\u00f3 salir de la Uni\u00f3n Sovi\u00e9tica sin cargos. La misma fecha, regres\u00f3 a Mosc\u00fa Gennadi Zajarov, empleado de la Misi\u00f3n sovi\u00e9tica ante Naciones Unidas, arrestado en Nueva York, tres d\u00edas antes que Daniloff. Como parte del acuerdo tambi\u00e9n viaj\u00f3 a Occidente el disidente Yuri Orlov.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un juicio a puerta cerrada que sorprendi\u00f3 por su celeridad, apenas tres sesiones, la corte regional de Sverdlovsk en<\/p>\n","protected":false},"author":4,"featured_media":36178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[355],"tags":[],"class_list":["post-36177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/07\/Rusia.jpg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:13:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/36177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=36177"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/36177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/36178"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=36177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=36177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=36177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}