{"id":35248,"date":"2024-07-06T14:08:04","date_gmt":"2024-07-06T19:08:04","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=35248"},"modified":"2024-07-06T14:08:04","modified_gmt":"2024-07-06T19:08:04","slug":"realizan-cirugias-gratuitas-de-hernias-en-la-cruz-roja-de-veracruz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/07\/06\/realizan-cirugias-gratuitas-de-hernias-en-la-cruz-roja-de-veracruz\/","title":{"rendered":"Realizan cirug\u00edas gratuitas de hernias en la Cruz Roja de Veracruz"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">En la Cruz Roja Delegaci\u00f3n Veracruz se realiza la jornada de cirug\u00eda de hernias de manera gratuita.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El doctor de la Cruz Roja, \u00a0V\u00edctor\u00a0Vela Rangel, se\u00f1al\u00f3 que este\u00a0programa tiene 16 a\u00f1os, solo se par\u00f3 durante la pandemia.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La jornada se mantiene durante 6\u00a0s\u00e1bados, concluye a\u00a0\u00a0finales del mes de julio, en cada s\u00e1bado se operan a alrededor de 13 pacientes, precis\u00f3 Lucila Ale de Ficachi, coordinadora de Damas Voluntarias de la Cruz Roja Mexicana Veracruz-Boca del R\u00edo.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Destacaron en rueda de prensa que con esta operaci\u00f3n se\u00a0cambia la calidad de vida de las personas,\u00a0se les realiza \u00a0a personas de escasos recursos.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Al momento ya se cerr\u00f3 la convocatoria, las personas inscritas son de diversos municipios de la entidad.\u00a0<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Este s\u00e1bado se entregaron diplomas a m\u00e9dicos voluntarios que participan en la 13 Jornada de Cirug\u00eda de Hernias.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Cruz Roja Delegaci\u00f3n Veracruz se realiza la jornada de cirug\u00eda de hernias de manera gratuita. El doctor de<\/p>\n","protected":false},"author":4,"featured_media":35249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[356],"tags":[],"class_list":["post-35248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/07\/cruz-roja-realizara-operaciones-de-hernia-gratis-522273.jpeg","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:28:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/35248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=35248"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/35248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/35249"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=35248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=35248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=35248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}