{"id":33885,"date":"2024-06-15T01:25:20","date_gmt":"2024-06-15T06:25:20","guid":{"rendered":"https:\/\/noticiasveracruz.com\/?p=33885"},"modified":"2024-06-15T01:25:20","modified_gmt":"2024-06-15T06:25:20","slug":"rescatan-a-8-migrantes-tras-operativo-en-tierra-blanca-veracruz","status":"publish","type":"post","link":"https:\/\/noticiasveracruz.com\/index.php\/2024\/06\/15\/rescatan-a-8-migrantes-tras-operativo-en-tierra-blanca-veracruz\/","title":{"rendered":"Rescatan a 8 migrantes tras operativo en Tierra Blanca, Veracruz"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Elementos de la Fiscal\u00eda General del Estado de Veracruz y de otras corporaciones de seguridad se enfrentaron con delincuentes en el marco de un operativo para liberar a personas migrantes secuestradas.<\/span><\/p>\n<div class=\"teads-inread\">\n<div>\n<div id=\"teads0\" class=\"teads-player\"><span style=\"font-size: 14pt;\">Fue en el municipio de Tierra Blanca cuando elementos de la Unidad Antisecuestros arribaron a una casa de seguridad y fueron agredidos con armas de fuego de grueso calibre por parte de presuntos integrantes de un grupo de la delincuencia organizada.<\/span><\/div>\n<\/div>\n<\/div>\n<p><span style=\"font-size: 14pt;\">En el operativo se logr\u00f3 el rescate de 8 personas migrantes, entre ellas una menor de edad, as\u00ed como la detenci\u00f3n de 5 personas que fueron puestas a disposici\u00f3n de las autoridades correspondientes para determinar su situaci\u00f3n legal.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cEl operativo se desarroll\u00f3 en el municipio de Tierra Blanca y cont\u00f3 con la coordinaci\u00f3n de la Secretar\u00eda de la Defensa Nacional, la Guardia Nacional, la Secretar\u00eda de Marina y fuerzas estatales\u201d, inform\u00f3 la FGE a trav\u00e9s de un comunicado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Ante la agresi\u00f3n a los elementos de la FGE, la Secretar\u00eda de Seguridad P\u00fablica activ\u00f3 el \u201cC\u00f3digo Rojo\u201d por lo que diversos elementos de Polic\u00eda Estatal se movilizaron para reforzar la seguridad en la zona.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Hasta altas horas de la noche cuerpos de seguridad estatales y federales mantuvieron recorridos en la regi\u00f3n.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201cLa Secretar\u00eda de Seguridad P\u00fablica precisa que derivado de la implementaci\u00f3n de un C\u00f3digo Rojo, fueron detenidos los presuntos delincuentes por autoridades estatales en coordinaci\u00f3n con fuerzas federales\u201d, indicaron.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elementos de la Fiscal\u00eda General del Estado de Veracruz y de otras corporaciones de seguridad se enfrentaron con delincuentes en el marco de un operativo para liberar a personas migrantes secuestradas. Fue en el municipio de Tierra Blanca cuando elementos de la Unidad Antisecuestros arribaron a una casa de seguridad y fueron agredidos con armas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":33886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[145,356],"tags":[],"class_list":["post-33885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados","category-veracruz"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:16:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"jetpack_featured_media_url":"https:\/\/noticiasveracruz.com\/wp-content\/uploads\/2024\/06\/Enfrentamiento-armado-en-Tierra-Blanca.jpg","_links":{"self":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/33885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/comments?post=33885"}],"version-history":[{"count":0,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/posts\/33885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media\/33886"}],"wp:attachment":[{"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/media?parent=33885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/categories?post=33885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasveracruz.com\/index.php\/wp-json\/wp\/v2\/tags?post=33885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}